{"id":1743,"count":20,"description":"Convocatorias de oposiciones al cuerpo de Profesores de Educaci\u00f3n Secundaria, de todas las especialidades, en todas las Comunidades Aut\u00f3nomas para el a\u00f1o 2026","link":"https:\/\/www.campuseducacion.com\/blog\/secundaria\/oposiciones-secundaria-2026\/","name":"Oposiciones Secundaria 2026","slug":"oposiciones-secundaria-2026","taxonomy":"category","parent":22,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oposiciones Secundaria 2026 - Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"Convocatorias de oposiciones al cuerpo de Profesores de Educaci\u00f3n Secundaria, de todas las especialidades, en todas las Comunidades Aut\u00f3nomas para el a\u00f1o 2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/secundaria\/oposiciones-secundaria-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oposiciones Secundaria 2026 - Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"Convocatorias de oposiciones al cuerpo de Profesores de Educaci\u00f3n Secundaria, de todas las especialidades, en todas las Comunidades Aut\u00f3nomas para el a\u00f1o 2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/secundaria\/oposiciones-secundaria-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/secundaria\\\/oposiciones-secundaria-2026\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/secundaria\\\/oposiciones-secundaria-2026\\\/\",\"name\":\"Oposiciones Secundaria 2026 - Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"description\":\"Convocatorias de oposiciones al cuerpo de Profesores de Educaci\u00f3n Secundaria, de todas las especialidades, en todas las Comunidades Aut\u00f3nomas para el a\u00f1o 2026\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/secundaria\\\/oposiciones-secundaria-2026\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/secundaria\\\/oposiciones-secundaria-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oposiciones Secundaria\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/secundaria\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oposiciones Secundaria 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oposiciones Secundaria 2026 - Campuseducacion.com","description":"Convocatorias de oposiciones al cuerpo de Profesores de Educaci\u00f3n Secundaria, de todas las especialidades, en todas las Comunidades Aut\u00f3nomas para el a\u00f1o 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/secundaria\/oposiciones-secundaria-2026\/","og_locale":"es_ES","og_type":"article","og_title":"Oposiciones Secundaria 2026 - Campuseducacion.com","og_description":"Convocatorias de oposiciones al cuerpo de Profesores de Educaci\u00f3n Secundaria, de todas las especialidades, en todas las Comunidades Aut\u00f3nomas para el a\u00f1o 2026","og_url":"https:\/\/www.campuseducacion.com\/blog\/secundaria\/oposiciones-secundaria-2026\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","twitter_card":"summary_large_image","twitter_site":"@Campuseducacion","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.campuseducacion.com\/blog\/secundaria\/oposiciones-secundaria-2026\/","url":"https:\/\/www.campuseducacion.com\/blog\/secundaria\/oposiciones-secundaria-2026\/","name":"Oposiciones Secundaria 2026 - Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"description":"Convocatorias de oposiciones al cuerpo de Profesores de Educaci\u00f3n Secundaria, de todas las especialidades, en todas las Comunidades Aut\u00f3nomas para el a\u00f1o 2026","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/secundaria\/oposiciones-secundaria-2026\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/secundaria\/oposiciones-secundaria-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Oposiciones Secundaria","item":"https:\/\/www.campuseducacion.com\/blog\/secundaria\/"},{"@type":"ListItem","position":3,"name":"Oposiciones Secundaria 2026"}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories\/1743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories\/22"}],"wp:post_type":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts?categories=1743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}