{"id":798,"count":436,"description":"<strong>Recursos destinados a docentes<\/strong>: Noticias educativas, materiales did\u00e1cticos, consejos, infograf\u00edas descargables, art\u00edculos de reflexi\u00f3n\u2026 y materiales de todo tipo, elaborados por Campuseducacion.com, para maestros y profesores de cualquier etapa educativa.\r\n\r\nAprende las <strong><a href=\"https:\/\/www.campuseducacion.com\/blog\/destacados\/diferencias-entre-master-oficial-universitario-y-master-titulo-propio\/\">diferencias entre un M\u00e1ster Oficial y un T\u00edtulo propio<\/a><\/strong>, c\u00f3mo elaborar la programaci\u00f3n did\u00e1ctica, consejos para exponerla y un largo etc.\r\n<p style=\"text-align: center;\">\u00a1Explora esta secci\u00f3n, est\u00e1 hecha para los docentes!<\/p>","link":"https:\/\/www.campuseducacion.com\/blog\/recursos\/","name":"Recursos Educativos y Publicaciones Did\u00e1cticas","slug":"recursos","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recursos Educativos y Publicaciones Did\u00e1cticas<\/title>\n<meta name=\"description\" content=\"Recursos destinados a docentes: Noticias educativas, materiales did\u00e1cticos, consejos, infograf\u00edas descargables, art\u00edculos y materiales de todo tipo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/recursos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recursos Educativos y Publicaciones Did\u00e1cticas\" \/>\n<meta property=\"og:description\" content=\"Recursos destinados a docentes: Noticias educativas, materiales did\u00e1cticos, consejos, infograf\u00edas descargables, art\u00edculos y materiales de todo tipo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/recursos\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/recursos\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/recursos\\\/\",\"name\":\"Recursos Educativos y Publicaciones Did\u00e1cticas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"description\":\"Recursos destinados a docentes: Noticias educativas, materiales did\u00e1cticos, consejos, infograf\u00edas descargables, art\u00edculos y materiales de todo tipo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/recursos\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/recursos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recursos Educativos y Publicaciones Did\u00e1cticas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recursos Educativos y Publicaciones Did\u00e1cticas","description":"Recursos destinados a docentes: Noticias educativas, materiales did\u00e1cticos, consejos, infograf\u00edas descargables, art\u00edculos y materiales de todo tipo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/recursos\/","og_locale":"es_ES","og_type":"article","og_title":"Recursos Educativos y Publicaciones Did\u00e1cticas","og_description":"Recursos destinados a docentes: Noticias educativas, materiales did\u00e1cticos, consejos, infograf\u00edas descargables, art\u00edculos y materiales de todo tipo.","og_url":"https:\/\/www.campuseducacion.com\/blog\/recursos\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","twitter_card":"summary_large_image","twitter_site":"@Campuseducacion","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.campuseducacion.com\/blog\/recursos\/","url":"https:\/\/www.campuseducacion.com\/blog\/recursos\/","name":"Recursos Educativos y Publicaciones Did\u00e1cticas","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"description":"Recursos destinados a docentes: Noticias educativas, materiales did\u00e1cticos, consejos, infograf\u00edas descargables, art\u00edculos y materiales de todo tipo.","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/recursos\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/recursos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Recursos Educativos y Publicaciones Did\u00e1cticas"}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories\/798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts?categories=798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}