{"id":10213,"date":"2017-06-16T10:01:06","date_gmt":"2017-06-16T08:01:06","guid":{"rendered":"https:\/\/www.campuseducacion.com\/blog\/?p=10213"},"modified":"2019-06-26T11:48:44","modified_gmt":"2019-06-26T09:48:44","slug":"mediacion-intercultural","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/","title":{"rendered":"Mediaci\u00f3n intercultural"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Mediaci\u00f3n intercultural<\/strong> y <strong>tratamiento de conflictos<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Ante la diversidad inherente a las aulas, la labor de los docentes es la de crear un entorno de intercambio de conocimientos positivo que posibilite el encuentro, el trabajo conjunto y la armon\u00eda. Para ello, el educador tiene a su disposici\u00f3n una red multidisciplinar de profesionales, as\u00ed como diferentes herramientas que poner en pr\u00e1ctica con su grupo de alumnos, por lo que debe conocer los posibles conflictos que pueden surgir en el aula y en el centro, y procurar evitarlos.<\/p>\n<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\"><strong>MEDIACI\u00d3N INTERCULTURAL<\/strong><\/span><\/p>\n<h2 style=\"text-align: justify;\">Sociedad y diversidad<\/h2>\n<p style=\"text-align: justify;\">La <span style=\"text-decoration: underline;\"><strong>sociedad<\/strong><\/span> puede ser entendida como un t\u00e9rmino que designa al <em>conjunto de la colectividad, la cual se manifiesta como un ser vivo que evoluciona, diverge, cambia, se relaciona y avanza en el tiempo<\/em> (Spencer, 2004), por lo que requiere de personas que intercedan y medien dentro de s\u00ed, como la figura del mediador.<\/p>\n<p style=\"text-align: justify;\">Toda esta sociedad y su diversidad se refleja en las aulas, y son precisamente desde \u00e9stas desde donde se debe comenzar a cambiar los valores negativos que pueden suscitar el choque entre diferentes individuos, provocando un conflicto de convivencia (Cach\u00f3n, 2003).<\/p>\n<p style=\"text-align: justify;\"><span class='bctt-click-to-tweet'><span class='bctt-ctt-text'><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.campuseducacion.com%2Fblog%2Frevista-digital-docente%2Fmediacion-intercultural%2F&#038;text=%23Mediaci%C3%B3nIntercultural%20y%20Tratamiento%20de%20conflictos%20%23CEdRevistaDigitalDocente&#038;via=Campuseducacion&#038;related=Campuseducacion' target='_blank'rel=\"noopener noreferrer\">#Mediaci\u00f3nIntercultural y Tratamiento de conflictos #CEdRevistaDigitalDocente <\/a><\/span><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.campuseducacion.com%2Fblog%2Frevista-digital-docente%2Fmediacion-intercultural%2F&#038;text=%23Mediaci%C3%B3nIntercultural%20y%20Tratamiento%20de%20conflictos%20%23CEdRevistaDigitalDocente&#038;via=Campuseducacion&#038;related=Campuseducacion' target='_blank' class='bctt-ctt-btn'rel=\"noopener noreferrer\">Compartir en X<\/a><\/span><\/p>\n<h2>Conflictos culturales<\/h2>\n<p style=\"text-align: justify;\">Existen numerosos tipos de <strong>conflictos<\/strong>: sentimentales, sociales, de comunicaci\u00f3n, de intereses, de valores&#8230; pero se puede decir que unos de los <strong>m\u00e1s comunes dentro de \u00e1mbito educativo son aquellos que se producen por las diferencias culturales<\/strong> entre alguno de los miembros de la comunidad escolar, generalmente alumnos, y es que los centros docentes se han convertido, sobre todo en los \u00faltimos tiempos, en los m\u00e1s variados escaparates culturales.<\/p>\n<p style=\"text-align: justify;\">Se denomina <strong>cultura<\/strong> a <em>todo lo que rodea a un individuo y que marca sus pensamientos y actuaciones ante la vida<\/em>; es el conocimiento adquirido que las personas utilizan para interpretar su experiencia y generar comportamientos (Spradley y McCurdy, 1975).<\/p>\n<p style=\"text-align: justify;\"><strong>Nosotros solemos entender la cultura como todo lo que una persona necesita saber para actuar adecuadamente dentro de un grupo social determinado<\/strong> (Collingwood, 2004).<\/p>\n<div class=\"td-paragraph-padding-2\">\n<blockquote class=\"td_pull_quote td_pull_center\">\n<p style=\"text-align: justify;\">Todas y cada una de las culturas comparten ciertos rasgos que se denominan universales, pero tambi\u00e9n poseen al mismo tiempo rasgos \u00fanicos e irrepetibles. Cada cultura tiene unos sistemas simb\u00f3licos (c\u00f3digos ling\u00fc\u00edsticos y no verbales), sistemas de relaciones (parentesco y de rol), sistemas de creencias y valores, religi\u00f3n, etc. Y es solamente cuando nos adentramos en otra cultura cuando nos percatamos de todas estas diferencias con la propia.<\/p>\n<\/blockquote>\n<\/div>\n<p style=\"text-align: justify;\">La cultura, seg\u00fan Ruhly (1976)<em>,<\/em> puede ser percibida como un iceberg, en el aspecto de que s\u00f3lo podemos percibir una peque\u00f1a parte mientras que la m\u00e1s importante queda oculta a la vista<em>.<\/em><\/p>\n<p style=\"text-align: justify;\">La<strong> cultura<\/strong>, entendida <strong>desde el terreno educativo<\/strong>, se define como un <em>sistema conceptual y de valores que incluye las creencias y expectativas, los patrones, rutinas, conductas y costumbres creadas y mantenidas por un grupo, y que son utilizadas y modificadas por dicho grupo<\/em> (Figueroa, 1993).<\/p>\n<p style=\"text-align: justify;\">Como afirma Aguado (2002), la cultura en la escuela tiene que ver con significados que se comparten, con visiones del mundo que se perciben, con interpretaciones de los acontecimientos sociales y naturales que acontecen a diario y que nos llevan a modular nuestra conducta y nuestras producciones.<\/p>\n<h2>Interculturalidad y Multiculturalidad<\/h2>\n<p style=\"text-align: justify;\">Para adentrarnos m\u00e1s en el tema que nos ocupa (conflictos culturales) debemos, previamente, definir algunos conceptos, como interculturalidad y multiculturalidad.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><span style=\"text-decoration: underline;\"><strong>Interculturalidad:<\/strong><\/span> El concepto de interculturalidad puede considerarse como una concepci\u00f3n te\u00f3rica y pr\u00e1ctica de car\u00e1cter universal que atiende la diversidad cultural de todas las sociedades desde los principios de igualdad, interacci\u00f3n y transformaci\u00f3n social, implicando una opci\u00f3n \u00e9tica e ideol\u00f3gica de car\u00e1cter personal, una forma de entender y vivir las relaciones sociales y una manera de plantear y desarrollar la educaci\u00f3n (Lluch y Salinas, 1996). La interculturalidad hace referencia a la din\u00e1mica que se establece entre diversas comunidades culturales.<\/li>\n<li style=\"text-align: justify;\"><span style=\"text-decoration: underline;\"><strong>Multiculturalidad:<\/strong><\/span> Por su parte, la multiculturalidad marca el estado y la situaci\u00f3n de una sociedad plural desde el punto de vista de comunidades culturales con identidades diferenciadas (Alsina, 1997).<\/li>\n<\/ul>\n<div class=\"td-paragraph-padding-2\">\n<blockquote class=\"td_pull_quote td_pull_center\">\n<p style=\"text-align: justify;\">Bajo estos preceptos, comprendemos que una sociedad intercultural es una sociedad abierta, flexible, que es capaz de convivir agregando para s\u00ed todo lo bueno y eliminando los comportamientos o ideolog\u00edas negativas y, desde este enfoque de la interculturalidad se debe formar a los docentes. Dicha formaci\u00f3n tendr\u00eda que abarcar la mejora del conocimiento de uno mismo como de los dem\u00e1s, abriendo una v\u00eda a la gesti\u00f3n de los conflictos de valores inherentes a la pluralidad de las actuales sociedades occidentales (Cohen, 2013).<\/p>\n<\/blockquote>\n<\/div>\n<h2>Conflictos en el \u00e1mbito educativo<\/h2>\n<p style=\"text-align: justify;\">A la hora de hablar de conflictos en centros educativos lo m\u00e1s habitual es relacionar este t\u00e9rmino con los conceptos violencia, agresividad o acoso escolar. En realidad, el con\u00adflic\u00adto en los entornos escolares es algo que surge de ma\u00adne\u00adra na\u00adtu\u00adral, al igual que en el resto de los escenarios de la vida cotidiana, por lo que los docentes (de cualquier etapa educativa) han de estar formados para saber reconocerlos y, sobre todo, saber prevenirlos, afrontarlos, intervenir en ellos y disminuir aquellos que supongan un riesgo, elimin\u00e1ndolos siempre que sea posible, y cuando sea necesario.<\/p>\n<p style=\"text-align: justify;\">El hecho de que existan conflictos en el \u00e1mbito educativo es una realidad objetiva pero, parad\u00f3jicamente, frente a esta objetividad nos encontramos con la falta de consideraci\u00f3n que este asunto ha tenido como objeto de estudio pedag\u00f3gico.<\/p>\n<p style=\"text-align: justify;\">No podemos negar que <strong>los conflictos son una realidad dentro de la organizaci\u00f3n escolar<\/strong>, y ante esto debemos adoptar posiciones que nos permitan afrontarlos y aprender de ellos, pues \u201c<em>el conflicto y las posiciones discrepantes pueden y deben generar debate y servir de base para la cr\u00edtica pedag\u00f3gica, y, por supuesto, como una esfera de lucha ideol\u00f3gica y articulaci\u00f3n de pr\u00e1cticas sociales y educativas liberadoras<\/em>\u201d (Escudero, 1992).<\/p>\n<p style=\"text-align: justify;\">En este sentido, Girard y Koch (1997) manifiestan que los conflictos en la escuela, por s\u00ed mismos, no son ni negativos ni positivos, sino que constituyen una parte natural de la vida escolar, y hay que aprender a entender y analizarlos desde una perspectiva de apertura y di\u00e1logo.<\/p>\n<p style=\"text-align: justify;\">Sabariego (2002) establece similitudes entre los conflictos sociales y los acaecidos en las aulas, pues nuestras escuelas son un reflejo de nuestra sociedad, encontrando conflictos que se generan sin dificultad en m\u00faltiples espacios y momentos de la jornada escolar:<\/p>\n<ul>\n<li style=\"text-align: justify;\"><u>Conflictos en el aula:<\/u> Aquellos que ocurren durante el transcurso de las clases ordinarias, sobre todo derivados de las conversaciones entre compa\u00f1eros y por los problemas de trabajo en equipo, adem\u00e1s de la participaci\u00f3n habitual en clase, donde surgen discrepancias y diferencias evidentes de opini\u00f3n.<\/li>\n<li style=\"text-align: justify;\"><u>Conflictos en las zonas comunes:<\/u> En los intercambios de clase, en los aseos, en la comunicaci\u00f3n producida en reuniones de alumnos, grupos de trabajo, etc.<\/li>\n<li style=\"text-align: justify;\"><u>Conflictos en el patio:<\/u> Disputas por el espacio, los materiales, relaciones interpersonales, diferencias de edad, preferencias y juegos\u2026<\/li>\n<li style=\"text-align: justify;\"><u>Conflictos en el comedor:<\/u> Conflictos surgidos por falta de comunicaci\u00f3n, por las costumbres a la hora de comer, el comportamiento a la mesa&#8230;<\/li>\n<li style=\"text-align: justify;\"><u>Conflictos en la realizaci\u00f3n de actividades extraescolares<\/u>.<\/li>\n<li><u>Conflictos derivados de las manifestaciones religiosas en los centros<\/u>.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10216 size-large\" src=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto002-3-1024x683.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto002-3-1024x683.jpg 1024w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto002-3-150x100.jpg 150w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto002-3-300x200.jpg 300w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto002-3-768x512.jpg 768w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto002-3-600x400.jpg 600w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto002-3-696x464.jpg 696w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto002-3-1068x712.jpg 1068w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto002-3-630x420.jpg 630w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto002-3.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h2>Conflictos entre el alumnado<\/h2>\n<p style=\"text-align: justify;\">En los contextos educativos de diversidad cultural, los problemas que pueden surgir entre el alumnado, am\u00e9n de derivarse de los enfrentamientos entre car\u00e1cter u opiniones, pueden ser ocasionados por las diferencias culturales propiamente dichas, lo cual indicar\u00eda una falta en formaci\u00f3n de valores e inteligencia emocional, entre otros problemas.<\/p>\n<p style=\"text-align: justify;\">Muchos estudiosos en el tema opinan que todos los errores en la interacci\u00f3n entre culturas distintas se podr\u00eda erradicar mediante el conocimiento de \u00e9stas, procurando un <strong>moldeamiento<\/strong> y una adaptaci\u00f3n de ambas culturas, para llegar al entendimiento sin interrupciones y a una convivencia pac\u00edfica y respetuosa sin conflictos negativos.<\/p>\n<p style=\"text-align: justify;\">Nuestras escuelas, como venimos diciendo, han experimentado en los \u00faltimos tiempos una serie de transformaciones que est\u00e1n en consonancia con los cambios que se producen en la sociedad. Entre ellos, se puede afirmar que uno de los m\u00e1s sobresalientes es la propia composici\u00f3n de la poblaci\u00f3n escolar que se ha diversificado considerablemente en funci\u00f3n de criterios de procedencia, origen familia, contexto sociocultural, etc. Por este motivo, <strong>se plantea la necesidad de replantear desde otra perspectiva los procesos de ense\u00f1anza-aprendizaje, de manera que sean m\u00e1s efectivos para todos los alumnos<\/strong> (Del Olmo, 2005).<\/p>\n<p style=\"text-align: justify;\">Partiendo de la base de que la pluralidad de culturas es una caracter\u00edstica inherente en nuestra sociedad, los conflictos est\u00e1n asegurados. El problema vendr\u00eda cuando \u00e9stos con de corte negativo y se transforman en problemas de convivencia. Algunos de los problemas, por tanto, que pueden acontecer en el terreno educativo podr\u00edan darse debido a los siguientes aspectos (Bartolom\u00e9, 1997; Jord\u00e1n, 1999 y Essomba, 2003):<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>Problemas derivados por la divergencia entre opiniones y pensamientos:<\/strong> Cada alumno, en funci\u00f3n de su bagaje cultural, cuenta con una mentalidad particular, con diferente forma de ver la realidad y de entenderla, y con un sistema de valores integrado en su c\u00f3digo de comportamiento que puede ocasionar que a veces no comprenda las acciones del resto de compa\u00f1eros, impidiendo la relaci\u00f3n en trabajos en grupo y las actividades en equipo, por ejemplo.<\/li>\n<li style=\"text-align: justify;\"><strong>Problemas surgidos a partir de malentendidos:<\/strong> Las diferentes culturas hacen que los alumnos tengan problemas en cuanto a las costumbres que practican, sus propios ritos en distintos planos de su cotidianidad, expresiones particulares, uso del lenguaje\u2026<\/li>\n<li style=\"text-align: justify;\"><strong>Problemas de comunicaci\u00f3n:<\/strong> Entre culturas diferentes, lo m\u00e1s habitual va a ser encontrarnos problemas con los idiomas. Aprender otro idioma entra\u00f1a una dificultad importante, pero si adem\u00e1s es una necesidad, puede llegar a causar niveles altos de estr\u00e9s. Si nuestro alumnado no posee un sistema comunicativo com\u00fan, y tanto los nativos como los extranjeros tienen problemas para entender a los contrarios, podemos correr el riesgo de caer en una situaci\u00f3n bastante inquietante.<\/li>\n<li><strong>Problemas de costumbres: <\/strong>Entre la pluralidad cultural se manifiesta, l\u00f3gicamente, gran diversidad de costumbres y tradiciones arraigadas a unos y otros individuos, para las cuales es necesario encontrar una situaci\u00f3n de equidad y respeto mutuo.<\/li>\n<li style=\"text-align: justify;\"><strong>Problemas por estereotipos y\/o prejuicios:<\/strong> Un prejuicio puede ser entendido como una actitud hostil hacia una persona que pertenece a un determinado grupo, por el hecho de pertenecer a dicho grupo y se le atribuyen a \u00e9l mismo todas las cualidades negativas asociadas a dicho grupo (Allport, 1979). Esteriotipar, en cambio, consiste en simplificar y asociar un conjunto de ideas, generalmente adquiridas de otra persona, a una categor\u00eda. Como puede adivinarse, ning\u00fan comportamiento asociado a ideas generales, intuitivas o de suposici\u00f3n deber\u00eda ser aplicado al trato o consideraci\u00f3n que se tenga con una persona o grupo, por lo que hay que luchar por procurar cierto cambio en la mentalidad colectiva.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Sin duda alguna, para evitar los conflictos entre alumnado es necesario que los docentes responsables de su educaci\u00f3n creen un clima favorecedor de actitudes cooperativas y solidarias necesarias para una verdadera educaci\u00f3n intercultural (Calvo, 2003), pues solamente si conseguimos que los alumnos tengan un sentimiento de pertenencia al grupo se conseguir\u00e1 formar una sana identidad cultural y, por tanto, la integraci\u00f3n plena (Aguado, 2003).<\/p>\n<h2>El papel del mediador<\/h2>\n<p style=\"text-align: justify;\">En el plano escolar, <strong>la figura del mediador es contemplada como la encargada de facilitar la comunicaci\u00f3n<\/strong>, intermediando entre las partes y fomentando la cohesi\u00f3n social, a la par que promueve la autonom\u00eda y la inserci\u00f3n social de las minor\u00edas, actuando de catalizador, (Cohen, 1997).<\/p>\n<p style=\"text-align: justify;\">Aunque en la teor\u00eda parece muy f\u00e1cil hacer un listado de todo lo que hace falta para educar para prevenir el conflicto y todo lo necesario para considerar la educaci\u00f3n emocional y el desarrollo de competencias sociales en los alumnos, a la hora de llevarlo a la pr\u00e1ctica, en verdad, los docentes suelen tener serias dificultades, pues no han sido formados convenientemente para eso.<\/p>\n<p style=\"text-align: justify;\">La <strong>mediaci\u00f3n<\/strong> es <em>un proceso de comunicaci\u00f3n y entendimiento entre las partes de un conflicto con la ayuda de una o varias personas imparciales y cercanas, que facilitan que las partes en conflicto dialoguen y se escuchen de manera libre y segura, para se pueda llegar a un acuerdo que permita a los implicados establecer o restablecer una buena relaci\u00f3n<\/em> (Rom\u00e1n, 2015).<\/p>\n<blockquote class=\"td_pull_quote td_pull_center\">\n<div class=\"td-paragraph-padding-6\">\n<blockquote class=\"td_quote_box td_box_center\">\n<p style=\"text-align: justify;\">Seg\u00fan Lederach (1996), \u201cla mediaci\u00f3n es una t\u00e9cnica muy amplia, que consiste en la intervenci\u00f3n de un tercero (un individuo, un equipo, etc.) que facilita el logro de acuerdos en torno a un conflicto\u201d.<\/p>\n<\/blockquote>\n<\/div>\n<\/blockquote>\n<p style=\"text-align: justify;\"><strong>El mediador no debe ser el protagonista del proceso de mediaci\u00f3n, solo ha de garantizar que las partes puedan comunicarse en un espacio de libertad y seguridad<\/strong>, es decir que puedan hablar libremente sin faltar el respeto a nadie y sin coacciones o miedos. El mediador ni tiene prejuicios, ni se posiciona y no sanciona las actitudes y comportamientos de las partes en conflicto; solo procura que los participantes puedan encontrar por s\u00ed mismos soluciones satisfactorias a sus interesas y expectativas a trav\u00e9s de la comunicaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10217 size-large\" src=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto003-1-1024x683.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto003-1-1024x683.jpg 1024w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto003-1-150x100.jpg 150w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto003-1-300x200.jpg 300w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto003-1-768x512.jpg 768w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto003-1-600x400.jpg 600w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto003-1-696x464.jpg 696w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto003-1-1068x712.jpg 1068w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto003-1-630x420.jpg 630w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto003-1.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<h2 style=\"text-align: justify;\">Caracter\u00edsticas del mediador<\/h2>\n<p style=\"text-align: justify;\">Podemos encontrar varios autores para definir los principios generales que debe reunir la figura del mediador para poder cumplir tanto con la funci\u00f3n preventiva como con la rehabilitadora de su trabajo:<\/p>\n<ul>\n<li><em>Facilitar un clima propicio para intercambiar ideas.<\/em><\/li>\n<li style=\"text-align: justify;\"><em>Establecer unas reglas m\u00ednimas, negociadas y acordadas por todos los miembros, para el correcto desarrollo de la convivencia.<\/em><\/li>\n<li><em>Dotar a todos los implicados de las mismas posibilidades de expresar sus opiniones.<\/em><\/li>\n<li><em>Sintetizar, clarificar y explicar las posturas de cada uno de los implicados.<\/em><\/li>\n<li style=\"text-align: justify;\"><em>Gestionar unas conclusiones y unas actuaciones consensuadas y positivas para todos.<\/em><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Para comenzar, el mediador debe reconocer y aceptar la diversidad cultural de la sociedad actual y defender la igualdad de oportunidades para todos los grupos etnoculturales dentro de \u00e9sta. En el caso que nos ocupa, <strong>el mediador escolar deber\u00e1 de ejercer las funciones b\u00e1sicas de informar, definir, interpretar, difundir, educar, prevenir y acercar a las diferentes personas dentro del entorno escolar<\/strong>, intercediendo en la resoluci\u00f3n pac\u00edfica de conflictos y proporcionando t\u00e9cnicas para la prevenci\u00f3n de futuras situaciones problem\u00e1ticas, velando siempre por la cohesi\u00f3n grupal.<\/p>\n<h2 style=\"text-align: justify;\">Objetivos del mediador<\/h2>\n<p style=\"text-align: justify;\">Algunos de los <strong>objetivos que el mediador tiene que tener presentes<\/strong> (Aguado, 2003; Soriano, 2001) son:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Aplicar los principios democr\u00e1ticos de justicia social favoreciendo la participaci\u00f3n igualitaria.<\/li>\n<li style=\"text-align: justify;\">Analizar las desigualdades sociales entre los estudiantes.<\/li>\n<li>Estimular y facilitar el \u00e9xito acad\u00e9mico de todos los estudiantes proporcionando una educaci\u00f3n optima y en igualdad.<\/li>\n<li style=\"text-align: justify;\">Ofrecer a los estudiantes la oportunidad de ser cr\u00edticos y productivos miembros de una sociedad democr\u00e1tica.<\/li>\n<li>Promover la acci\u00f3n social frente al racismo, la discriminaci\u00f3n y la xenofobia.<\/li>\n<li style=\"text-align: justify;\">Valorar y aceptar la diversidad cultural como un elemento positivo para todos los ciudadanos.<\/li>\n<li>Fomentar los contactos e interacciones entre grupos culturales diversos dentro y fuera de la escuela para desarrollar la capacidad de funcionar eficazmente en medios multiculturales, e intervenir para la actuaci\u00f3n en situaciones formales e informales.<\/li>\n<li>Apoyar cambios no s\u00f3lo ideol\u00f3gicos, sino pol\u00edticos, econ\u00f3micos y educativos que afectan a todos los \u00e1mbitos de la vida diaria.<\/li>\n<li style=\"text-align: justify;\">Propiciar la adquisici\u00f3n de estrategias interculturales en todos los procesos de ense\u00f1anza-aprendizaje y contribuir a la formaci\u00f3n de profesores y orientadores interculturales.<\/li>\n<li style=\"text-align: justify;\">Extender la propuesta a todos los \u00e1mbitos sociales, no s\u00f3lo al educativo; y en \u00e9ste, no s\u00f3lo como atenci\u00f3n a minor\u00edas o inmigrantes, sino a todos y cada uno de los participantes en educaci\u00f3n.<\/li>\n<li style=\"text-align: justify;\">Atender preferentemente a la calidad de las relaciones m\u00e1s que a los medios y apoyos puestos en juego.<\/li>\n<li style=\"text-align: justify;\">Introducir nuevas estrategias en el aula, metodolog\u00edas, formaci\u00f3n del profesorado, en el clima escolar y en las relaciones con los padres y comunidad.<\/li>\n<li style=\"text-align: justify;\">Fomentar una actividad educativa inclusiva de conjunto, es decir, enfocada a todos los integrantes, no solamente al extranjero.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>El mediador es una herramienta a disposici\u00f3n del centro<\/strong> que en ning\u00fan caso puede actuar en sustituci\u00f3n a otros mecanismos, y cuya misi\u00f3n pudiera resumirse en procurar el logro de un aut\u00e9ntico centro intercultural, el cual tendr\u00eda las siguientes caracter\u00edsticas:<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10214 size-full\" src=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto004.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto004.jpg 1200w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto004-150x100.jpg 150w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto004-300x200.jpg 300w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto004-768x512.jpg 768w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto004-1024x683.jpg 1024w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto004-600x400.jpg 600w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto004-696x464.jpg 696w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto004-1068x712.jpg 1068w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/foto004-630x420.jpg 630w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p style=\"text-align: justify;\">No se pretende acabar con la posibilidad de aparici\u00f3n de conflictos en las aulas y en los centros, pues venimos sosteniendo que pueden ser aprovechados como algo positivo, sino que desde los centros educativos se debe procurar evitar aquellos conflictos considerados negativos, es decir, las situaciones en las que prima la violencia, la convivencia se ve perjudicada, existen agresiones, disputas que da\u00f1an las relaciones sociales, etc.<\/p>\n<p style=\"text-align: justify;\">Se debe mantener un punto de vista positivo, desde la neutralidad, puesto que la uni\u00f3n de culturas nos enriquece y nos hace m\u00e1s fuertes como sociedad unida y desarrollada. Pero lo m\u00e1s relevante es que los profesionales de los centros docentes nunca pueden extralimitarse en sus funciones y entrar en parcelas cuya responsabilidad es de otro compa\u00f1ero.<\/p>\n<div class=\"td-paragraph-padding-2\">\n<blockquote class=\"td_pull_quote td_pull_center\">\n<blockquote class=\"td_quote_box td_box_center\">\n<p style=\"text-align: justify;\">El mediador siempre busca el equilibrio y la interactuaci\u00f3n de todos con todos, lo que se traduje en el quehacer para la consolidaci\u00f3n de una sociedad homog\u00e9nea y sin prejuicios.<\/p>\n<\/blockquote>\n<\/blockquote>\n<\/div>\n<p style=\"text-align: justify;\">Ante todo, hay que evitar caer en lo que Girondella (2009) denomina <strong>relativismo cultural<\/strong> y es que siempre, de forma inconsciente, partimos desde nuestra propia cultura nativa arraigada en nuestro car\u00e1cter para entender todo lo que nos rodea, tendiendo a ver la realidad desde nuestra visi\u00f3n personal y considerando las culturas diferentes como inferiores o equivocadas.<\/p>\n<p style=\"text-align: justify;\">El art\u00edculo <a href=\"https:\/\/www.campuseducacion.com\/revista-digital-docente\/numeros\/4\/#22\"><em><strong>Mediaci\u00f3n Intercultural. Tratamiento de los conflictos en entornos escolares<\/strong><\/em><\/a> forma parte del <strong><a href=\"https:\/\/www.campuseducacion.com\/revista-digital-docente\/numeros\/4\/#\">n\u00famero 4<\/a><\/strong> de <strong><a href=\"https:\/\/www.campuseducacion.com\/revista-digital-docente\/\">Campus Educaci\u00f3n Revista Digital Docente<\/a><\/strong>, un proyecto destinado a la divulgaci\u00f3n de publicaciones de car\u00e1cter educativo que permite la difusi\u00f3n del conocimiento y pretende el enriquecimiento de toda la comunidad educativa.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.campuseducacion.com\/revista-digital-docente\/publicaciones\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9280 size-full\" src=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/03\/banner-recordatorio-publicaciones-02-copia.png\" alt=\"Recuerda que publicamos de forma gratuita tus art\u00edculos did\u00e1cticos, cient\u00edficos y de investigaci\u00f3n\" width=\"660\" height=\"291\" srcset=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/03\/banner-recordatorio-publicaciones-02-copia.png 660w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/03\/banner-recordatorio-publicaciones-02-copia-150x66.png 150w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/03\/banner-recordatorio-publicaciones-02-copia-300x132.png 300w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/03\/banner-recordatorio-publicaciones-02-copia-600x265.png 600w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/a><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;10213&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Mediaci\u00f3n intercultural&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            <span class=\"kksr-muted\"><\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mediaci\u00f3n intercultural y tratamiento de conflictos. Ante la diversidad inherente a las aulas, la labor de los docentes es la de crear un entorno de intercambio de conocimientos positivo que posibilite el encuentro, el trabajo conjunto y la armon\u00eda. Para ello, el educador tiene a su disposici\u00f3n una red multidisciplinar de profesionales, as\u00ed como diferentes [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":10218,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[884,798],"tags":[885],"class_list":{"0":"post-10213","1":"post","2":"type-post","3":"status-publish","4":"format-image","5":"has-post-thumbnail","7":"category-revista-digital-docente","8":"category-recursos","9":"tag-articulos-campus-educacion-revista-digital-docente","10":"post_format-post-format-image"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mediaci\u00f3n Intercultural<\/title>\n<meta name=\"description\" content=\"Mediaci\u00f3n intercultural y tratamiento de conflictos. Ante la diversidad inherente a las aulas, la labor de los docentes es la de crear un entorno de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mediaci\u00f3n Intercultural\" \/>\n<meta property=\"og:description\" content=\"Mediaci\u00f3n intercultural y tratamiento de conflictos. Ante la diversidad inherente a las aulas, la labor de los docentes es la de crear un entorno de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-16T08:01:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-26T09:48:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/destacada-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Juana Mar\u00eda Torres Utrera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juana Mar\u00eda Torres Utrera\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/mediacion-intercultural\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/mediacion-intercultural\\\/\"},\"author\":{\"name\":\"Juana Mar\u00eda Torres Utrera\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/c9ca0282afc231f78790b47bfececa2e\"},\"headline\":\"Mediaci\u00f3n intercultural\",\"datePublished\":\"2017-06-16T08:01:06+00:00\",\"dateModified\":\"2019-06-26T09:48:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/mediacion-intercultural\\\/\"},\"wordCount\":2999,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/mediacion-intercultural\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/destacada-4.jpg\",\"keywords\":[\"Art\u00edculos Campus Educaci\u00f3n Revista Digital Docente\"],\"articleSection\":[\"Campus Educaci\u00f3n Revista Digital Docente\",\"Recursos Educativos y Publicaciones Did\u00e1cticas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/mediacion-intercultural\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/mediacion-intercultural\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/mediacion-intercultural\\\/\",\"name\":\"Mediaci\u00f3n Intercultural\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/mediacion-intercultural\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/mediacion-intercultural\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/destacada-4.jpg\",\"datePublished\":\"2017-06-16T08:01:06+00:00\",\"dateModified\":\"2019-06-26T09:48:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/c9ca0282afc231f78790b47bfececa2e\"},\"description\":\"Mediaci\u00f3n intercultural y tratamiento de conflictos. Ante la diversidad inherente a las aulas, la labor de los docentes es la de crear un entorno de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/mediacion-intercultural\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/mediacion-intercultural\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/mediacion-intercultural\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/destacada-4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/destacada-4.jpg\",\"width\":1200,\"height\":627,\"caption\":\"Mediaci\u00f3n intercultural y tratamiento de conflictos escolares\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/mediacion-intercultural\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mediaci\u00f3n intercultural\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/c9ca0282afc231f78790b47bfececa2e\",\"name\":\"Juana Mar\u00eda Torres Utrera\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Captura-de-pantalla-2017-04-17-a-las-16.51.22-143x150.png\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Captura-de-pantalla-2017-04-17-a-las-16.51.22-143x150.png\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Captura-de-pantalla-2017-04-17-a-las-16.51.22-143x150.png\",\"caption\":\"Juana Mar\u00eda Torres Utrera\"},\"description\":\"Juana Mar\u00eda es diplomada en Magisterio de Educaci\u00f3n Infantil e Int\u00e9rprete de LSE. Actualmente trabaja como maestra especialista en Audici\u00f3n y Lenguaje en el centro La Pedrera de Yecla (Murcia).\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/juana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mediaci\u00f3n Intercultural","description":"Mediaci\u00f3n intercultural y tratamiento de conflictos. Ante la diversidad inherente a las aulas, la labor de los docentes es la de crear un entorno de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/","og_locale":"es_ES","og_type":"article","og_title":"Mediaci\u00f3n Intercultural","og_description":"Mediaci\u00f3n intercultural y tratamiento de conflictos. Ante la diversidad inherente a las aulas, la labor de los docentes es la de crear un entorno de","og_url":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2017-06-16T08:01:06+00:00","article_modified_time":"2019-06-26T09:48:44+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/destacada-4.jpg","type":"image\/jpeg"}],"author":"Juana Mar\u00eda Torres Utrera","twitter_card":"summary_large_image","twitter_creator":"@Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Juana Mar\u00eda Torres Utrera","Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/"},"author":{"name":"Juana Mar\u00eda Torres Utrera","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/c9ca0282afc231f78790b47bfececa2e"},"headline":"Mediaci\u00f3n intercultural","datePublished":"2017-06-16T08:01:06+00:00","dateModified":"2019-06-26T09:48:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/"},"wordCount":2999,"commentCount":0,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/destacada-4.jpg","keywords":["Art\u00edculos Campus Educaci\u00f3n Revista Digital Docente"],"articleSection":["Campus Educaci\u00f3n Revista Digital Docente","Recursos Educativos y Publicaciones Did\u00e1cticas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/","url":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/","name":"Mediaci\u00f3n Intercultural","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/destacada-4.jpg","datePublished":"2017-06-16T08:01:06+00:00","dateModified":"2019-06-26T09:48:44+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/c9ca0282afc231f78790b47bfececa2e"},"description":"Mediaci\u00f3n intercultural y tratamiento de conflictos. Ante la diversidad inherente a las aulas, la labor de los docentes es la de crear un entorno de","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/destacada-4.jpg","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/05\/destacada-4.jpg","width":1200,"height":627,"caption":"Mediaci\u00f3n intercultural y tratamiento de conflictos escolares"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/mediacion-intercultural\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Mediaci\u00f3n intercultural"}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/c9ca0282afc231f78790b47bfececa2e","name":"Juana Mar\u00eda Torres Utrera","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/04\/Captura-de-pantalla-2017-04-17-a-las-16.51.22-143x150.png","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/04\/Captura-de-pantalla-2017-04-17-a-las-16.51.22-143x150.png","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/04\/Captura-de-pantalla-2017-04-17-a-las-16.51.22-143x150.png","caption":"Juana Mar\u00eda Torres Utrera"},"description":"Juana Mar\u00eda es diplomada en Magisterio de Educaci\u00f3n Infantil e Int\u00e9rprete de LSE. Actualmente trabaja como maestra especialista en Audici\u00f3n y Lenguaje en el centro La Pedrera de Yecla (Murcia).","url":"https:\/\/www.campuseducacion.com\/blog\/autores\/juana\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/10213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=10213"}],"version-history":[{"count":4,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/10213\/revisions"}],"predecessor-version":[{"id":16911,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/10213\/revisions\/16911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/10218"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=10213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=10213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=10213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}