{"id":1258,"date":"2013-06-11T12:39:10","date_gmt":"2013-06-11T10:39:10","guid":{"rendered":"http:\/\/www.campuseducacion.com\/oposiciones\/?p=1258"},"modified":"2017-09-19T12:58:12","modified_gmt":"2017-09-19T10:58:12","slug":"castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/","title":{"rendered":"Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla &#8211; La Mancha: tribunales, lugar y fecha de comienzo de las pruebas."},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: Arial-BoldMT; font-size: medium;\">Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla &#8211; La Mancha. Resoluci\u00f3n de 07\/06\/2013, de la Direcci\u00f3n General de Recursos Humanos y Programaci\u00f3n Educativa, por la que se regula la <strong>organizaci\u00f3n y composici\u00f3n del tribunal y el inicio de la fase de oposici\u00f3n<\/strong> del procedimiento selectivo para el acceso al Cuerpo de Inspectores de Educaci\u00f3n convocado por la Resoluci\u00f3n de 04\/04\/2013, de la Consejer\u00eda de Educaci\u00f3n, Cultura y Deportes.<!--more--><\/span><\/p>\n<p style=\"text-align: justify;\">\n<h3 style=\"text-align: justify;\"><\/h3>\n<p style=\"text-align: justify;\">Debido a la antig\u00fcedad de la noticia, estos documentos ya no se encuentran en el <a href=\"http:\/\/www.educa.jccm.es\/es\">portal de educaci\u00f3n de Castilla &#8211; La Mancha<\/a>.<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;1258&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;44&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;4.5\\\/5 - (44 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla - La Mancha: tribunales, lugar y fecha de comienzo de las pruebas.&quot;,&quot;width&quot;:&quot;87.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 87.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            4.5\/5 - (44 votos)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla &#8211; La Mancha. Resoluci\u00f3n de 07\/06\/2013, de la Direcci\u00f3n General de Recursos Humanos y Programaci\u00f3n Educativa, por la que se regula la organizaci\u00f3n y composici\u00f3n del tribunal y el inicio de la fase de oposici\u00f3n del procedimiento selectivo para el acceso al Cuerpo de Inspectores de Educaci\u00f3n convocado por la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[33,19],"tags":[190],"class_list":{"0":"post-1258","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-inspeccion","8":"category-castilla-la-mancha","9":"tag-tribunales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla - La Mancha: tribunales, lugar y fecha de comienzo de las pruebas. - Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla - La Mancha. Resoluci\u00f3n de 07\/06\/2013, de la Direcci\u00f3n General de Recursos Humanos y Programaci\u00f3n Educativa,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla - La Mancha: tribunales, lugar y fecha de comienzo de las pruebas. - Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla - La Mancha. Resoluci\u00f3n de 07\/06\/2013, de la Direcci\u00f3n General de Recursos Humanos y Programaci\u00f3n Educativa,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-11T10:39:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-19T10:58:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/castilla_la_mancha.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campuseducacion.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\\\/\"},\"author\":{\"name\":\"Campuseducacion.com\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"headline\":\"Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla &#8211; La Mancha: tribunales, lugar y fecha de comienzo de las pruebas.\",\"datePublished\":\"2013-06-11T10:39:10+00:00\",\"dateModified\":\"2017-09-19T10:58:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\\\/\"},\"wordCount\":120,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/castilla_la_mancha.gif\",\"keywords\":[\"tribunales\"],\"articleSection\":[\"Inspecci\u00f3n Educativa\",\"Oposiciones Castilla-La Mancha\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\\\/\",\"name\":\"Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla - La Mancha: tribunales, lugar y fecha de comienzo de las pruebas. - Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/castilla_la_mancha.gif\",\"datePublished\":\"2013-06-11T10:39:10+00:00\",\"dateModified\":\"2017-09-19T10:58:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"description\":\"Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla - La Mancha. Resoluci\u00f3n de 07\\\/06\\\/2013, de la Direcci\u00f3n General de Recursos Humanos y Programaci\u00f3n Educativa,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/castilla_la_mancha.gif\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/castilla_la_mancha.gif\",\"width\":620,\"height\":330,\"caption\":\"Noticias de oposiciones de maestros y profesores de Castilla-La Mancha\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla &#8211; La Mancha: tribunales, lugar y fecha de comienzo de las pruebas.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\",\"name\":\"Campuseducacion.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"caption\":\"Campuseducacion.com\"},\"description\":\"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.\",\"sameAs\":[\"https:\\\/\\\/www.campuseducacion.com\",\"https:\\\/\\\/www.facebook.com\\\/Campuseducacion.es\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Campuseducacion\"],\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/adminopos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla - La Mancha: tribunales, lugar y fecha de comienzo de las pruebas. - Campuseducacion.com","description":"Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla - La Mancha. Resoluci\u00f3n de 07\/06\/2013, de la Direcci\u00f3n General de Recursos Humanos y Programaci\u00f3n Educativa,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/","og_locale":"es_ES","og_type":"article","og_title":"Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla - La Mancha: tribunales, lugar y fecha de comienzo de las pruebas. - Campuseducacion.com","og_description":"Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla - La Mancha. Resoluci\u00f3n de 07\/06\/2013, de la Direcci\u00f3n General de Recursos Humanos y Programaci\u00f3n Educativa,","og_url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_author":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2013-06-11T10:39:10+00:00","article_modified_time":"2017-09-19T10:58:12+00:00","og_image":[{"width":620,"height":330,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/castilla_la_mancha.gif","type":"image\/gif"}],"author":"Campuseducacion.com","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Campuseducacion.com","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/"},"author":{"name":"Campuseducacion.com","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"headline":"Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla &#8211; La Mancha: tribunales, lugar y fecha de comienzo de las pruebas.","datePublished":"2013-06-11T10:39:10+00:00","dateModified":"2017-09-19T10:58:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/"},"wordCount":120,"commentCount":0,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/castilla_la_mancha.gif","keywords":["tribunales"],"articleSection":["Inspecci\u00f3n Educativa","Oposiciones Castilla-La Mancha"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/","url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/","name":"Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla - La Mancha: tribunales, lugar y fecha de comienzo de las pruebas. - Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/castilla_la_mancha.gif","datePublished":"2013-06-11T10:39:10+00:00","dateModified":"2017-09-19T10:58:12+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"description":"Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla - La Mancha. Resoluci\u00f3n de 07\/06\/2013, de la Direcci\u00f3n General de Recursos Humanos y Programaci\u00f3n Educativa,","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/castilla_la_mancha.gif","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/castilla_la_mancha.gif","width":620,"height":330,"caption":"Noticias de oposiciones de maestros y profesores de Castilla-La Mancha"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-inspectores-de-educacion-tribunales-lugar-y-fecha-de-comienzo-de-las-pruebas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Oposici\u00f3n Inspectores de Educaci\u00f3n Castilla &#8211; La Mancha: tribunales, lugar y fecha de comienzo de las pruebas."}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f","name":"Campuseducacion.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","caption":"Campuseducacion.com"},"description":"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.","sameAs":["https:\/\/www.campuseducacion.com","https:\/\/www.facebook.com\/Campuseducacion.es","https:\/\/x.com\/https:\/\/twitter.com\/Campuseducacion"],"url":"https:\/\/www.campuseducacion.com\/blog\/autores\/adminopos\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/1258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=1258"}],"version-history":[{"count":8,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/1258\/revisions"}],"predecessor-version":[{"id":11733,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/1258\/revisions\/11733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/14"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=1258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=1258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=1258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}