{"id":1522,"date":"2013-06-25T09:03:40","date_gmt":"2013-06-25T07:03:40","guid":{"rendered":"http:\/\/www.campuseducacion.com\/oposiciones\/?p=1522"},"modified":"2017-09-19T13:20:42","modified_gmt":"2017-09-19T11:20:42","slug":"castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/","title":{"rendered":"Oposiciones Maestros Castilla-La Mancha 2013. Seguimiento personalizado desde el Portal de la Consejer\u00eda"},"content":{"rendered":"<p><strong>La Consejer\u00eda de Educaci\u00f3n de Castilla-La Mancha pone adisposici\u00f3n del opositor los siguientes enlaces para realizar el seguimiento personalizado.<\/strong><\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Debes acceder al portal de educaci\u00f3n de la <a href=\"http:\/\/www.educa.jccm.es\/es\">Junta de Comunidades de Castilla &#8211; La Mancha<\/a>.<\/p>\n<p>&nbsp;<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;1522&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;14&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;3.6&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;3.6\\\/5 - (14 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Oposiciones Maestros Castilla-La Mancha 2013. Seguimiento personalizado desde el Portal de la Consejer\u00eda&quot;,&quot;width&quot;:&quot;69.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 69.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            3.6\/5 - (14 votos)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Consejer\u00eda de Educaci\u00f3n de Castilla-La Mancha pone adisposici\u00f3n del opositor los siguientes enlaces para realizar el seguimiento personalizado.<\/p>\n","protected":false},"author":2,"featured_media":14,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[19,1058],"tags":[],"class_list":{"0":"post-1522","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-castilla-la-mancha","8":"category-oposiciones-maestros-2013"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oposiciones Maestros Castilla-La Mancha 2013. Seguimiento personalizado desde el Portal de la Consejer\u00eda - Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"La Consejer\u00eda de Educaci\u00f3n de Castilla-La Mancha pone adisposici\u00f3n del opositor los siguientes enlaces para realizar el seguimiento personalizado. Debes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oposiciones Maestros Castilla-La Mancha 2013. Seguimiento personalizado desde el Portal de la Consejer\u00eda - Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"La Consejer\u00eda de Educaci\u00f3n de Castilla-La Mancha pone adisposici\u00f3n del opositor los siguientes enlaces para realizar el seguimiento personalizado. Debes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-25T07:03:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-19T11:20:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/castilla_la_mancha.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campuseducacion.com\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\\\/\"},\"author\":{\"name\":\"Campuseducacion.com\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"headline\":\"Oposiciones Maestros Castilla-La Mancha 2013. Seguimiento personalizado desde el Portal de la Consejer\u00eda\",\"datePublished\":\"2013-06-25T07:03:40+00:00\",\"dateModified\":\"2017-09-19T11:20:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\\\/\"},\"wordCount\":53,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/castilla_la_mancha.gif\",\"articleSection\":[\"Oposiciones Castilla-La Mancha\",\"Oposiciones Maestros 2013\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\\\/\",\"name\":\"Oposiciones Maestros Castilla-La Mancha 2013. Seguimiento personalizado desde el Portal de la Consejer\u00eda - Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/castilla_la_mancha.gif\",\"datePublished\":\"2013-06-25T07:03:40+00:00\",\"dateModified\":\"2017-09-19T11:20:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"description\":\"La Consejer\u00eda de Educaci\u00f3n de Castilla-La Mancha pone adisposici\u00f3n del opositor los siguientes enlaces para realizar el seguimiento personalizado. Debes\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/castilla_la_mancha.gif\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/castilla_la_mancha.gif\",\"width\":620,\"height\":330,\"caption\":\"Noticias de oposiciones de maestros y profesores de Castilla-La Mancha\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-la-mancha\\\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oposiciones Maestros Castilla-La Mancha 2013. Seguimiento personalizado desde el Portal de la Consejer\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\",\"name\":\"Campuseducacion.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"caption\":\"Campuseducacion.com\"},\"description\":\"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.\",\"sameAs\":[\"https:\\\/\\\/www.campuseducacion.com\",\"https:\\\/\\\/www.facebook.com\\\/Campuseducacion.es\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Campuseducacion\"],\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/adminopos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oposiciones Maestros Castilla-La Mancha 2013. Seguimiento personalizado desde el Portal de la Consejer\u00eda - Campuseducacion.com","description":"La Consejer\u00eda de Educaci\u00f3n de Castilla-La Mancha pone adisposici\u00f3n del opositor los siguientes enlaces para realizar el seguimiento personalizado. Debes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/","og_locale":"es_ES","og_type":"article","og_title":"Oposiciones Maestros Castilla-La Mancha 2013. Seguimiento personalizado desde el Portal de la Consejer\u00eda - Campuseducacion.com","og_description":"La Consejer\u00eda de Educaci\u00f3n de Castilla-La Mancha pone adisposici\u00f3n del opositor los siguientes enlaces para realizar el seguimiento personalizado. Debes","og_url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_author":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2013-06-25T07:03:40+00:00","article_modified_time":"2017-09-19T11:20:42+00:00","og_image":[{"width":620,"height":330,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/castilla_la_mancha.gif","type":"image\/gif"}],"author":"Campuseducacion.com","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Campuseducacion.com"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/"},"author":{"name":"Campuseducacion.com","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"headline":"Oposiciones Maestros Castilla-La Mancha 2013. Seguimiento personalizado desde el Portal de la Consejer\u00eda","datePublished":"2013-06-25T07:03:40+00:00","dateModified":"2017-09-19T11:20:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/"},"wordCount":53,"commentCount":0,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/castilla_la_mancha.gif","articleSection":["Oposiciones Castilla-La Mancha","Oposiciones Maestros 2013"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/","url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/","name":"Oposiciones Maestros Castilla-La Mancha 2013. Seguimiento personalizado desde el Portal de la Consejer\u00eda - Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/castilla_la_mancha.gif","datePublished":"2013-06-25T07:03:40+00:00","dateModified":"2017-09-19T11:20:42+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"description":"La Consejer\u00eda de Educaci\u00f3n de Castilla-La Mancha pone adisposici\u00f3n del opositor los siguientes enlaces para realizar el seguimiento personalizado. Debes","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/castilla_la_mancha.gif","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/castilla_la_mancha.gif","width":620,"height":330,"caption":"Noticias de oposiciones de maestros y profesores de Castilla-La Mancha"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-la-mancha\/castilla-la-mancha-seguimiento-personalizado-desde-el-portal-de-la-consejeria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Oposiciones Maestros Castilla-La Mancha 2013. Seguimiento personalizado desde el Portal de la Consejer\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f","name":"Campuseducacion.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","caption":"Campuseducacion.com"},"description":"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.","sameAs":["https:\/\/www.campuseducacion.com","https:\/\/www.facebook.com\/Campuseducacion.es","https:\/\/x.com\/https:\/\/twitter.com\/Campuseducacion"],"url":"https:\/\/www.campuseducacion.com\/blog\/autores\/adminopos\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/1522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=1522"}],"version-history":[{"count":7,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/1522\/revisions"}],"predecessor-version":[{"id":11746,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/1522\/revisions\/11746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/14"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=1522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=1522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=1522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}