{"id":17929,"date":"2019-11-18T17:13:40","date_gmt":"2019-11-18T16:13:40","guid":{"rendered":"https:\/\/www.campuseducacion.com\/blog\/?p=17929"},"modified":"2019-11-18T17:13:40","modified_gmt":"2019-11-18T16:13:40","slug":"interinos-andalucia-bolsas-de-trabajo-para-profesores-2","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/","title":{"rendered":"Interinos Andaluc\u00eda: Bolsas de Trabajo para Profesores"},"content":{"rendered":"<p><strong>Andaluc\u00eda<\/strong> abre varias <strong>bolsas de trabajo<\/strong> extraordinarias para<strong> profesores<\/strong> de Ense\u00f1anzas Medias.<\/p>\n<span class='bctt-click-to-tweet'><span class='bctt-ctt-text'><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.campuseducacion.com%2Fblog%2Fbolsas-de-trabajo%2Fbolsas-andalucia%2Finterinos-andalucia-bolsas-de-trabajo-para-profesores-2%2F&#038;text=%23BolsasDeTrabajo%20abiertas%20para%20profesores%20%23InterinosAndaluc%C3%ADa&#038;via=Campuseducacion&#038;related=Campuseducacion' target='_blank'rel=\"noopener noreferrer\">#BolsasDeTrabajo abiertas para profesores #InterinosAndaluc\u00eda <\/a><\/span><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.campuseducacion.com%2Fblog%2Fbolsas-de-trabajo%2Fbolsas-andalucia%2Finterinos-andalucia-bolsas-de-trabajo-para-profesores-2%2F&#038;text=%23BolsasDeTrabajo%20abiertas%20para%20profesores%20%23InterinosAndaluc%C3%ADa&#038;via=Campuseducacion&#038;related=Campuseducacion' target='_blank' class='bctt-ctt-btn'rel=\"noopener noreferrer\">Compartir en X<\/a><\/span>\n<p>La Consejer\u00eda de Educaci\u00f3n de la Junta de Andaluc\u00eda y Deporte\u00a0realiza convocatoria para el<br \/>\nacceso extraordinario a las bolsas de trabajo de determinadas especialidades del <strong>Cuerpo de Profesores de Ense\u00f1anza Secundaria<\/strong>, del <strong>Cuerpo de Profesores T\u00e9cnicos de Formaci\u00f3n Profesional<\/strong>, del <strong>Cuerpo de Profesores de Escuelas Oficiales de Idiomas<\/strong>, del <strong>Cuerpo de Profesores de M\u00fasica y Artes Esc\u00e9nicas<\/strong>, del <strong>Cuerpo de Profesores de Artes Pl\u00e1sticas y Dise\u00f1o<\/strong> y <strong>Cuerpo de Maestros de Taller de Artes Pl\u00e1sticas y Dise\u00f1o<\/strong>, as\u00ed como a determinadas bolsas con perfil biling\u00fce.<\/p>\n<p>Las especialidades convocadas se encuentran en la convocatoria.<\/p>\n<ul>\n<li><strong><a href=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2019\/11\/Convocatoria-6.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Convocatoria<\/a><\/strong><\/li>\n<\/ul>\n<p><strong>Plazo de presentaci\u00f3n de solicitudes:<\/strong> Del 19 de noviembre al 2 de diciembre.<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;17929&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;2&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;2\\\/5 - (1 voto)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Interinos Andaluc\u00eda: Bolsas de Trabajo para Profesores&quot;,&quot;width&quot;:&quot;37.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 37.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            2\/5 - (1 voto)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Andaluc\u00eda abre varias bolsas de trabajo extraordinarias para profesores de Ense\u00f1anzas Medias. La Consejer\u00eda de Educaci\u00f3n de la Junta de Andaluc\u00eda y Deporte\u00a0realiza convocatoria para el acceso extraordinario a las bolsas de trabajo de determinadas especialidades del Cuerpo de Profesores de Ense\u00f1anza Secundaria, del Cuerpo de Profesores T\u00e9cnicos de Formaci\u00f3n Profesional, del Cuerpo de Profesores [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":6220,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[200],"tags":[],"class_list":{"0":"post-17929","1":"post","2":"type-post","3":"status-publish","4":"format-image","5":"has-post-thumbnail","7":"category-bolsas-andalucia","8":"post_format-post-format-image"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interinos Andaluc\u00eda: Bolsas de Trabajo para Profesores- Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"Andaluc\u00eda abre varias bolsas de trabajo extraordinarias para profesores de Ense\u00f1anzas Medias.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interinos Andaluc\u00eda: Bolsas de Trabajo para Profesores- Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"Andaluc\u00eda abre varias bolsas de trabajo extraordinarias para profesores de Ense\u00f1anzas Medias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-18T16:13:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/andalucia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campuseducacion.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-andalucia\\\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-andalucia\\\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\\\/\"},\"author\":{\"name\":\"Campuseducacion.com\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/56e876ff8f12e337395ee2ae40c5fb57\"},\"headline\":\"Interinos Andaluc\u00eda: Bolsas de Trabajo para Profesores\",\"datePublished\":\"2019-11-18T16:13:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-andalucia\\\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\\\/\"},\"wordCount\":152,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-andalucia\\\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/andalucia.jpg\",\"articleSection\":[\"Bolsas Andaluc\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-andalucia\\\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-andalucia\\\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-andalucia\\\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\\\/\",\"name\":\"Interinos Andaluc\u00eda: Bolsas de Trabajo para Profesores- Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-andalucia\\\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-andalucia\\\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/andalucia.jpg\",\"datePublished\":\"2019-11-18T16:13:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/56e876ff8f12e337395ee2ae40c5fb57\"},\"description\":\"Andaluc\u00eda abre varias bolsas de trabajo extraordinarias para profesores de Ense\u00f1anzas Medias.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-andalucia\\\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-andalucia\\\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-andalucia\\\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/andalucia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/andalucia.jpg\",\"width\":1200,\"height\":627,\"caption\":\"bandera Andaluc\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-andalucia\\\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interinos Andaluc\u00eda: Bolsas de Trabajo para Profesores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/56e876ff8f12e337395ee2ae40c5fb57\",\"name\":\"Campuseducacion.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g\",\"caption\":\"Campuseducacion.com\"},\"description\":\"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.\",\"sameAs\":[\"https:\\\/\\\/www.campuseducacion.com\",\"https:\\\/\\\/www.facebook.com\\\/Campuseducacion.es\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Campuseducacion\"],\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/campuseducacion-com-4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interinos Andaluc\u00eda: Bolsas de Trabajo para Profesores- Campuseducacion.com","description":"Andaluc\u00eda abre varias bolsas de trabajo extraordinarias para profesores de Ense\u00f1anzas Medias.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/","og_locale":"es_ES","og_type":"article","og_title":"Interinos Andaluc\u00eda: Bolsas de Trabajo para Profesores- Campuseducacion.com","og_description":"Andaluc\u00eda abre varias bolsas de trabajo extraordinarias para profesores de Ense\u00f1anzas Medias.","og_url":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_author":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2019-11-18T16:13:40+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/andalucia.jpg","type":"image\/jpeg"}],"author":"Campuseducacion.com","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Campuseducacion.com","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/"},"author":{"name":"Campuseducacion.com","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/56e876ff8f12e337395ee2ae40c5fb57"},"headline":"Interinos Andaluc\u00eda: Bolsas de Trabajo para Profesores","datePublished":"2019-11-18T16:13:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/"},"wordCount":152,"commentCount":0,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/andalucia.jpg","articleSection":["Bolsas Andaluc\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/","url":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/","name":"Interinos Andaluc\u00eda: Bolsas de Trabajo para Profesores- Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/andalucia.jpg","datePublished":"2019-11-18T16:13:40+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/56e876ff8f12e337395ee2ae40c5fb57"},"description":"Andaluc\u00eda abre varias bolsas de trabajo extraordinarias para profesores de Ense\u00f1anzas Medias.","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/andalucia.jpg","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/andalucia.jpg","width":1200,"height":627,"caption":"bandera Andaluc\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-andalucia\/interinos-andalucia-bolsas-de-trabajo-para-profesores-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Interinos Andaluc\u00eda: Bolsas de Trabajo para Profesores"}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/56e876ff8f12e337395ee2ae40c5fb57","name":"Campuseducacion.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g","caption":"Campuseducacion.com"},"description":"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.","sameAs":["https:\/\/www.campuseducacion.com","https:\/\/www.facebook.com\/Campuseducacion.es","https:\/\/x.com\/https:\/\/twitter.com\/Campuseducacion"],"url":"https:\/\/www.campuseducacion.com\/blog\/autores\/campuseducacion-com-4\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/17929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=17929"}],"version-history":[{"count":1,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/17929\/revisions"}],"predecessor-version":[{"id":17931,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/17929\/revisions\/17931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/6220"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=17929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=17929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=17929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}