{"id":19657,"date":"2020-06-16T10:35:28","date_gmt":"2020-06-16T08:35:28","guid":{"rendered":"https:\/\/www.campuseducacion.com\/blog\/?p=19657"},"modified":"2020-10-26T13:04:58","modified_gmt":"2020-10-26T12:04:58","slug":"prevencion-de-suicidios-entre-adolescentes","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/","title":{"rendered":"Prevenci\u00f3n de suicidios entre adolescentes"},"content":{"rendered":"<blockquote class=\"td_quote_box td_box_center\">\n<p style=\"text-align: left;\"><strong>Resumen: <\/strong>La Organizaci\u00f3n Mundial de la Salud considera el suicidio como el principal problema de salud p\u00fablica en Europa, y, en Espa\u00f1a, los suicidios de menores de 25 a\u00f1os se han multiplicado por tres desde 1990. Ante esta situaci\u00f3n, resulta necesario abordar este complejo problema desde la instituci\u00f3n educativa, haciendo uso de metodolog\u00edas innovadoras y recursos audiovisuales.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\"><strong>Palabras clave: <\/strong>Prevenci\u00f3n; Suicidio; Intervenci\u00f3n Educativa; Recursos Audiovisuales.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\"><strong>Abstract:<\/strong> The World Health Organization considers suicide as the main public health problem in Europe and, in Spain, children\u2019s suicides under 25 have increased by a factor of three since 1990. Given this situation, it is necessary to approach this complex problem from the educational institution, employing innovative teaching methodologies and audiovisual resources.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\"><strong>Keywords: <\/strong>Suicide prevention; Suicide; Educational Intervention; Video resources.<\/p>\n<\/blockquote>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.campuseducacion.com\/revista-digital-docente\/numeros\/18\/files\/assets\/basic-html\/page-5.html#\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>PREVENCI\u00d3N DE SUICIDIOS ENTRE ADOLESCENTES<\/strong><\/a><\/p>\n<span class='bctt-click-to-tweet'><span class='bctt-ctt-text'><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.campuseducacion.com%2Fblog%2Frevista-digital-docente%2Fprevencion-de-suicidios-entre-adolescentes%2F&#038;text=Prevenci%C3%B3n%20del%20suicidio%20entre%20adolescentes%20%23CEdRevistaDigitalDocente&#038;via=Campuseducacion&#038;related=Campuseducacion' target='_blank'rel=\"noopener noreferrer\">Prevenci\u00f3n del suicidio entre adolescentes #CEdRevistaDigitalDocente <\/a><\/span><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.campuseducacion.com%2Fblog%2Frevista-digital-docente%2Fprevencion-de-suicidios-entre-adolescentes%2F&#038;text=Prevenci%C3%B3n%20del%20suicidio%20entre%20adolescentes%20%23CEdRevistaDigitalDocente&#038;via=Campuseducacion&#038;related=Campuseducacion' target='_blank' class='bctt-ctt-btn'rel=\"noopener noreferrer\">Compartir en X<\/a><\/span>\n<h2>Un problema de a\u00f1os<\/h2>\n<p>El suicidio ha sido una problem\u00e1tica presente en la sociedad occidental desde hace a\u00f1os. La Organizaci\u00f3n Mundial de la Salud (OMS, 1976) define el suicidio como \u201cun acto con resultado letal, deliberadamente iniciado y realizado por el sujeto sabiendo o esperando su resultado letal\u201d. Es decir, es un acto intencional, en el que la persona que lo lleva a cabo decide quitarse de manera deliberada la vida.<\/p>\n<blockquote class=\"td_quote_box td_box_center\"><p>El suicidio ha sido un tema muy complejo por el gran impacto que tiene, tanto para el entorno directo del suicida, como para el entorno social. Es importante manejar con precisi\u00f3n la terminolog\u00eda relacionada con el mismo para no confundir elementos, sobre todo a la hora de acceder a datos y resultados de investigaciones.<\/p><\/blockquote>\n<p>Como indica el Ministerio de Sanidad, Pol\u00edticas Sociales e Igualdad (2018) en su <em>Gu\u00eda de Pr\u00e1ctica Cl\u00ednica sobre la Depresi\u00f3n Mayor en la Infancia y la <\/em><em>Adolescencia<\/em>, otros conceptos importantes relacionados con el suicidio son:<\/p>\n<ul>\n<li><strong>Conductas autolesivas<\/strong><\/li>\n<\/ul>\n<p>Lesiones autoinfligidas que producen un da\u00f1o corporal manifiesto sin llegar a comprometer la vida del paciente. Este comportamiento autolesivo consiste en infligirse el da\u00f1o corporal sin intencionalidad suicida.<\/p>\n<ul>\n<li><strong>Amenazas o ideaciones suicidas<\/strong><\/li>\n<\/ul>\n<p>Se utiliza para definir aquellas expresiones manifiestas que indican a otros la intenci\u00f3n de llevar a cabo un suicidio. Pueden ir acompa\u00f1adas de acciones para iniciar el suicidio.<\/p>\n<p>Algunas investigaciones muestran alta asociaci\u00f3n entre conductas autolesivas e ideaciones suicidas. Como indican Kirchner, Ferrer, Forns y Zanini (2011) en un estudio sobre conducta autolesiva e ideaciones suicidas en estudiantes de secundaria, la gran mayor\u00eda de adolescentes que han pensado en suicidarse tambi\u00e9n han efectuado un acto autol\u00edtico o un intento de suicidio en alg\u00fan momento. Por lo tanto, es importante prestar atenci\u00f3n a estas primeras formas de aviso, que pueden desencadenar la conducta suicida.<\/p>\n<h2>Datos<\/h2>\n<p>Parece ser que el suicidio alcanza magnitudes mayores de las esperadas, siendo considerado como el mayor problema de salud p\u00fablica de Europa (OMS, 2014), y en nuestro pa\u00eds el Instituto Nacional de Estad\u00edstica (INE, 2018) lo sit\u00faa entre las principales causas de muerte.<\/p>\n<blockquote class=\"td_pull_quote td_pull_center\"><p>Concretamente, el suicidio adolescente, a nivel mundial, se sit\u00faa como una de las tres causas de muerte m\u00e1s frecuentes entre los j\u00f3venes de 15 a 24 a\u00f1os, mientras que en Espa\u00f1a es la tercera causa de muerte, siendo superado \u00fanicamente por los accidentes de tr\u00e1fico y los tumores (INE, 2018).<\/p><\/blockquote>\n<h2>Estrategias de prevenci\u00f3n<\/h2>\n<p>Actualmente, existen teor\u00edas contrapuestas sobre c\u00f3mo abordar el suicidio en la esfera p\u00fablica, especialmente en lo relativo a los medios de comunicaci\u00f3n. El soci\u00f3logo Philips (1974) bautiz\u00f3 como el \u201c<strong>efecto Werther<\/strong>\u201d a la conducta mim\u00e9tica que se da tras la sobreexposici\u00f3n a la informaci\u00f3n concerniente al suicidio de una persona famosa o personaje p\u00fablico y que desencadena la imitaci\u00f3n del mismo.<\/p>\n<p>Por otro lado, Niederkrotenthaler (2012) habla del \u201c<strong>efecto Papageno<\/strong>\u201d, bas\u00e1ndose en la idea del impacto que puede provocar el estudio de casos reales de suicidio para evitar que otros sigan el mismo camino, teniendo as\u00ed un efecto protector.<\/p>\n<p>En esta l\u00ednea giran las indicaciones establecidas por la OMS (2000) al afirmar que informar del suicidio de manera apropiada, exacta y potencialmente \u00fatil a trav\u00e9s de medios de comunicaci\u00f3n puede prevenir una tr\u00e1gica p\u00e9rdida de vidas, y recoge una serie de indicaciones para que la transmisi\u00f3n de informaci\u00f3n en medios de comunicaci\u00f3n juegue un papel preventivo, como presentar los datos solo en las p\u00e1ginas interiores, en el caso de los peri\u00f3dicos, proporcionar informaci\u00f3n sobre l\u00edneas de ayuda y recursos comunitarios y publicitar indicadores de riesgo y se\u00f1ales de advertencia.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19660 size-full\" src=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto02.jpg\" alt=\"prevenci\u00f3n del suicidio entre adolescentes\" width=\"1200\" height=\"675\" srcset=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto02.jpg 1200w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto02-300x169.jpg 300w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto02-1024x576.jpg 1024w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto02-150x84.jpg 150w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto02-768x432.jpg 768w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto02-600x338.jpg 600w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto02-696x392.jpg 696w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto02-1068x601.jpg 1068w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto02-747x420.jpg 747w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/h2>\n<p>En cuanto al \u00e1mbito de la salud mental, la mayor\u00eda de las asociaciones apuestan por romper tab\u00faes y hablar del suicidio de forma expl\u00edcita como una forma directa de prevenirlo. Es el caso de la International Association for Suicide Prevention (IASP), que lanz\u00f3 en 2015 una campa\u00f1a bajo el lema \u201cPrevenir el Suicidio: Tender la mano y salvar vidas\u201d (2015). En Espa\u00f1a, se dedic\u00f3 el D\u00eda Mundial de la Salud Mental de 2019 a la prevenci\u00f3n del suicidio, con una campa\u00f1a lanzada por la Fundaci\u00f3n Salud Mental Espa\u00f1a bajo el lema \u201cconect@ con la vida\u201d.<\/p>\n<p>Por su parte, el Colegio Oficial de Psic\u00f3logos de Espa\u00f1a tambi\u00e9n apuesta por mantener esta l\u00ednea de intervenci\u00f3n.<\/p>\n<blockquote class=\"td_quote_box td_box_center\"><p>El estigma en torno al suicidio entorpece la prevenci\u00f3n al disuadir de buscar ayuda a muchas personas que piensan en quitarse la vida o han tratado de hacerlo. Por ello, es importante aumentar la sensibilidad de la comunidad y superar el tab\u00fa para que los pa\u00edses avancen en la prevenci\u00f3n del suicidio (COP, 2018)<\/p><\/blockquote>\n<p>Todo parece indicar que la prevenci\u00f3n m\u00e1s eficaz contra las actitudes sucidias es el abordaje directo del problema, superando el tab\u00fa y manejando herramientas diversas para poder hablar y reflexionar sobre ello.<\/p>\n<h2>La prevenci\u00f3n desde la instituci\u00f3n educativa<\/h2>\n<p>El papel de la escuela es fundamental para evitar el riesgo de suicidio. Igualmente, la funci\u00f3n socializadora de la misma resulta muy beneficiosa para el desarrollo de labores de prevenci\u00f3n, pudiendo enfocar el problema desde un pusto de vista social, adem\u00e1s de puramente educativo.<\/p>\n<p>El grupo juega un papel fundamental, tanto por su protagonismo en el proceso de ense\u00f1anza-aprendizaje como por el papel que el <strong>grupo de iguales<\/strong> juega en el periodo adolescente. Para el adolescente, la integraci\u00f3n en el grupo de iguales es fundamental puesto que le aporta un sentimiento de pertenencia y una validaci\u00f3n de su identidad (Musitu y Cava, 2003).<\/p>\n<p>El grupo de iguales constituye un pilar fundamental en el adolescente, convirti\u00e9ndose en el <strong>contexto de socializaci\u00f3n<\/strong> m\u00e1s influyente que desplaza a la familia como principal foco de apoyo (Oliva, Parra y S\u00e1nchez, 2002). No obstante, existe cierta controversia en cuanto al papel del grupo como factor de riesgo para conductas suicidas o como factor de protecci\u00f3n.<\/p>\n<p>Encontramos que el grupo puede ser desencadenante de conductas suicidas cuando en su seno se produce acoso o <strong>bullying<\/strong>, dando lugar al \u201cbully-cidio\u201d (Picazo-Zappino, 2014).<\/p>\n<p>Olweus, precursor del concepto, defini\u00f3 el Bullying como un fen\u00f3meno de agresi\u00f3n intencional de uno o unos sobre otro u otros de forma reiterada y mantenida en el tiempo, en la que existe desequilibrio de poder entre quien agrede y quien es agredido (1993).<\/p>\n<p>Vemos que el papel del grupo ha ido cobrando mayor importancia a medida que se estudia el fen\u00f3meno del bullying, incluy\u00e9ndose ahora dicho papel en gran parte de los planes de prevenci\u00f3n del acoso. Adem\u00e1s, se ha observado que, cuando el grupo interviene para detener el acoso, este se detiene (D\u00edaz-Aguado, Mart\u00ednez y Mart\u00edn, 2013).<\/p>\n<p>El papel que el grupo puede jugar en una situaci\u00f3n de acoso es ambivalente: como incitador, como observador o c\u00f3mplice, o como protecci\u00f3n. Esto podr\u00eda ser extrapolable a cualquier tipo de conducta de riesgo, incluida la conducta suicida, muy relacionada en la adolescencia con situaciones de acoso (Picazo-Zappino, 2014).<\/p>\n<blockquote class=\"td_pull_quote td_pull_center\"><p>De todas las conductas de riesgo que pueden incitar al suicidio a un adolescente, el bullying cobra especial relevancia precisamente por la implicaci\u00f3n del grupo, y porque presenta una mayor posibilidad de intervenci\u00f3n en el contexto educativo.<\/p><\/blockquote>\n<p>Se ha encontrado asociaci\u00f3n entre las relaciones pobres con el grupo de iguales y la ideaci\u00f3n suicida; tambi\u00e9n se ha encontrado asociaci\u00f3n entre problemas en la relaci\u00f3n con los iguales e intentos de suicidio (Ministerio de Sanidad, 2018). Por otro lado, son numerosas las investigaciones que relacionan una buena relaci\u00f3n con los compa\u00f1eros con una alta autoestima (Robinson, 1995), y un menor riesgo de tener problemas emocionales y de conducta (Oliva et al. 2002), siendo el grupo un factor de protecci\u00f3n frente al suicidio.<\/p>\n<h2>Propuestas metodol\u00f3gicas de intervenci\u00f3n<\/h2>\n<p>En base a lo expuesto, y como coinciden la gran mayor\u00eda de autores e instituciones autorizadas, a la hora de abordar la problem\u00e1tica deberemos hacer uso de estrategias metodol\u00f3gicas que favorezcan la interacci\u00f3n entre el grupo de iguales, y que permitan generar relaciones positivas.<\/p>\n<p>Para aterrizar propuestas concretas que desarrollar en el aula se puede partir de la importancia del aprendizaje en grupo. Escogiendo metodolog\u00edas que se fundamenten en la interacci\u00f3n entre iguales, la cooperaci\u00f3n y el desarrollo colaborativo de diversas actividades encontramos un punto clave de prevenci\u00f3n frente a actitudes desmotivadas, pesimistas o de baja autoestima que puedan degenerar en pensamientos suicidas. Tal es el caso del Aprendizaje Basado en Proyectos.<\/p>\n<p>El <strong>Aprendizaje Basado en Proyectos<\/strong> (en adelante ABP) es una metodolog\u00eda did\u00e1ctica en la que los alumnos, organizados por grupos, aprenden a trav\u00e9s de su propia investigaci\u00f3n los conceptos m\u00e1s importantes de la materia o el tema en el que se encuentran.<\/p>\n<blockquote class=\"td_quote_box td_box_center\"><p>El ABP fomenta habilidades como el trabajo en grupo, el aprendizaje aut\u00f3nomo, la capacidad de autoevaluaci\u00f3n, la planificaci\u00f3n del tiempo y la expresi\u00f3n oral y escrita (Reverte, Gallego, Molina y Satorre, 2008).<\/p><\/blockquote>\n<p>Usar esta metodolog\u00eda, por tanto, no s\u00f3lo contribuye a una mayor motivaci\u00f3n, sino que permite afianzar la relaci\u00f3n entre iguales y puede servir al docente como un factor de protecci\u00f3n frente a posibles conductas suicidas.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19659 size-full\" src=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto01.jpg\" alt=\"prevenci\u00f3n del suicidio entre adolescentes\" width=\"1200\" height=\"675\" srcset=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto01.jpg 1200w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto01-300x169.jpg 300w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto01-1024x576.jpg 1024w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto01-150x84.jpg 150w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto01-768x432.jpg 768w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto01-600x338.jpg 600w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto01-696x392.jpg 696w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto01-1068x601.jpg 1068w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/foto01-747x420.jpg 747w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/h2>\n<h2>Uso de recursos audiovisuales<\/h2>\n<p>Adem\u00e1s de servirnos de estrategias metodol\u00f3gicas que fomenten el trabajo en grupo y la interacci\u00f3n entre el alumnado, podemos hacer uso de recursos audiovisuales muy diversos como forma de potenciar la motivaci\u00f3n del alumno hacia la tem\u00e1tica a tratar.<\/p>\n<p>En el entorno de las nuevas tecnolog\u00edas y el uso de los recursos educativos digitales en el que el terreno educativo se encuentra hoy sumido, el uso did\u00e1ctico de materiales audiovisuales puede resultar f\u00e1cilmente aplicable.<\/p>\n<blockquote class=\"td_pull_quote td_pull_center\"><p>El uso de material audiovisual, como el cine, ayuda a pensar y sentir, consolida conocimientos y genera actitudes (De la Torre, Pujol y Rajadell, 2005).<\/p><\/blockquote>\n<p>Lo fundamental es que se ponga en marcha el <strong>desarrollo de recursos audiovisuales en los que el alumno sea el protagonista<\/strong>. Desde el constructivismo, que es el paradigma que fundamenta el curr\u00edculo actual, se entiende al alumno como sujeto activo y constructor de su propio conocimiento. Por lo tanto, debemos hacer que sea \u00e9l mismo quien construya su propio aprendizaje.<\/p>\n<p>Para lograr esto en base al uso de medios audiovisuales, se puede poner en marcha la creaci\u00f3n de un corto-documental que permitir\u00e1 al alumnado convertirse en agente activo, usando una herramienta motivadora, como es el cine, para poder prevenir de manera efectiva haciendo que el aprendizaje sea realmente significativo.<\/p>\n<p>Otra propuesta puede ser la puesta en marcha de un programa de radio, donde el alumno tenga que trasladar, junto a su grupo, las herramientas de prevenci\u00f3n del suicidio que se hayan trabajado previamente en clase.<\/p>\n<h2>La prevenci\u00f3n del suicidio dentro y fuera del aula<\/h2>\n<p>En el propio aula, es interesante comentar que las actuaciones que se lleven a cabo por parte del profesor-tutor sobre la prevenci\u00f3n del suicidio pueden y deben desarrollarse tanto en las horas lectivas destinadas a las tutor\u00edas, como de forma transversal a lo largo de todas las \u00e1reas y materias en los diferentes niveles educativos en los que se decida abordar el tema.<\/p>\n<p>Para poder hacer una <strong>prevenci\u00f3n transversal<\/strong>, que complemente a la intervenci\u00f3n espec\u00edfica en el horario de tutor\u00eda, se deben seleccionar y aunar coherentemente los contenidos de las diferentes materias, en funci\u00f3n de las posibilidades que ofrezca la propia tem\u00e1tica transversal.<\/p>\n<p>Por ello, se deber\u00e1 <strong>formar al profesorado<\/strong> en todo lo relativo a mitos sobre el suicidio, epidemiolog\u00eda, causas multifactoriales y herramientas de intervenci\u00f3n, tanto metodol\u00f3gicas como materiales, entre otros. Cada centro podr\u00e1 adaptar las herramientas que utilice en funci\u00f3n de los recursos con que cuente, pero es fundamental la implicaci\u00f3n del personal docente en su totalidad para poder tratar este tema. Especialmente importante ser\u00e1 la formaci\u00f3n en s\u00edntomas que puedan dar pistas sobre posible conducta de aut\u00f3lisis y recursos externos a los que pedir ayuda.<\/p>\n<p>Para que la intervenci\u00f3n sea completa, ser\u00e1 necesario <strong>trabajar activamente tambi\u00e9n con las familias<\/strong> acerca de estas cuestiones, con especial hincapi\u00e9 en la detecci\u00f3n precoz de s\u00edntomas y en recursos de apoyo. Se puede hacer a trav\u00e9s de la modalidad de Escuela de Padres y Madres, o bien mediante circular, pero se debe siempre incorporar a las figuras parentales (o tutores legales) para asegurar una mejor prevenci\u00f3n frente a la conducta suicida.<\/p>\n<blockquote class=\"td_quote_box td_box_center\"><p>En base a lo expuesto a lo largo del art\u00edculo, queda evidenciada la necesidad de poner en marcha acciones que contribuyan a la prevenci\u00f3n del suicidio adolescente, especialmente mediante programas espec\u00edficos que puedan desarrollarse en el aula, pero tambi\u00e9n formando a la comunidad educativa para una detecci\u00f3n precoz de la sintomatolog\u00eda asociada a la conducta suicida.<\/p><\/blockquote>\n<p>Lo principal debe ser la voluntad por parte de todos los agentes educativos para poner en marcha actuaciones para resolver este conflicto. Es necesario superar tab\u00faes y hablar abiertamente del suicidio, pues lo que no se nombra no existe, y lo que no existe, no se puede resolver. Para ello, seguir las indicaciones que los organismos profesionales establecen permitir\u00e1 tratar el tema con delicadeza y responsabilidad.<\/p>\n<p>Poner en marcha estrategias para prevenir el suicidio desde el \u00e1mbito escolar puede salvar vidas.<\/p>\n<h2>Te puede interesar&#8230;<\/h2>\n<h3>F\u00f3rmate en T\u00e9cnicas Piscopedag\u00f3gicas<\/h3>\n<p>En <a href=\"https:\/\/www.campuseducacion.com\/cursos-homologados-online\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Campuseducacion.com<\/strong><\/a> contamos con varios<strong> cursos<\/strong> de formaci\u00f3n, <strong>v\u00e1lidos para Oposiciones y CGT, homologados por la Universidad Camilo Jos\u00e9 Cela y 100 % online<\/strong> con los que poder ampliar tus conocimientos sobre \u00e9ste y otros aspectos relacionados:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.campuseducacion.com\/curso-oposiciones-profesores-secundaria-herramientas\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Herramientas did\u00e1cticas en el aula de Educaci\u00f3n Secundaria. Din\u00e1micas de grupo.<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/www.campuseducacion.com\/curso-oposiciones-maestros-profesores-dinamicas-relacion-interpersonal\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Recursos did\u00e1cticos y psicopedag\u00f3gicos: Din\u00e1micas de relaci\u00f3n interpersonal en el aula.<\/strong><\/a><\/li>\n<\/ul>\n<h3>Publica con nosotros<\/h3>\n<p><strong>Campus Educaci\u00f3n Revista Digital Docente<\/strong> ofrece la posibilidad a la comunidad docente de publicar art\u00edculos cient\u00edficos y did\u00e1cticos de forma totalmente gratuita, permitiendo as\u00ed la divulgaci\u00f3n del quehacer profesional docente, contribuyendo al avance de las Ciencias de la Educaci\u00f3n.<\/p>\n<p>Los autores de Campus Educaci\u00f3n Revista Digital Docente ven en este medio un lugar ideal para la investigaci\u00f3n pedag\u00f3gica, a la vez que reciben un <strong>certificado de autor\u00eda que les puede ayudar a sumar puntos en diferentes procesos selectivos y baremo de m\u00e9ritos, como en las Oposiciones Docentes o el Concurso General de Traslados<\/strong>.<\/p>\n<p style=\"text-align: left;\">Ahora puedes conseguir\u00a0<strong>4 certificaciones gratuitas<\/strong> en Campus Educaci\u00f3n Revista Digital Docente si te matriculas de 3 o m\u00e1s<strong><a href=\"https:\/\/www.campuseducacion.com\/cursos-homologados\/oposiciones-maestros-profesores\" target=\"_blank\" rel=\"noopener noreferrer\"> cursos homologados para Oposiciones y Concurso General de Traslados<\/a> <\/strong>con Campuseducacion.com.<\/p>\n<p><a href=\"https:\/\/www.campuseducacion.com\/revista-digital-docente\/publicaciones\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19043 size-full\" src=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/03\/banner-recordatorio-publicaciones-2020.jpg\" alt=\"\" width=\"1320\" height=\"582\" srcset=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/03\/banner-recordatorio-publicaciones-2020.jpg 1320w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/03\/banner-recordatorio-publicaciones-2020-300x132.jpg 300w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/03\/banner-recordatorio-publicaciones-2020-1024x451.jpg 1024w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/03\/banner-recordatorio-publicaciones-2020-150x66.jpg 150w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/03\/banner-recordatorio-publicaciones-2020-768x339.jpg 768w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/03\/banner-recordatorio-publicaciones-2020-600x265.jpg 600w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/03\/banner-recordatorio-publicaciones-2020-696x307.jpg 696w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/03\/banner-recordatorio-publicaciones-2020-1068x471.jpg 1068w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/03\/banner-recordatorio-publicaciones-2020-953x420.jpg 953w\" sizes=\"auto, (max-width: 1320px) 100vw, 1320px\" \/><\/a><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;19657&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Prevenci\u00f3n de suicidios entre adolescentes&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            <span class=\"kksr-muted\"><\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Resumen: La Organizaci\u00f3n Mundial de la Salud considera el suicidio como el principal problema de salud p\u00fablica en Europa, y, en Espa\u00f1a, los suicidios de menores de 25 a\u00f1os se han multiplicado por tres desde 1990. Ante esta situaci\u00f3n, resulta necesario abordar este complejo problema desde la instituci\u00f3n educativa, haciendo uso de metodolog\u00edas innovadoras y [&hellip;]<\/p>\n","protected":false},"author":123,"featured_media":19658,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[884,1,798],"tags":[],"class_list":{"0":"post-19657","1":"post","2":"type-post","3":"status-publish","4":"format-image","5":"has-post-thumbnail","7":"category-revista-digital-docente","8":"category-general","9":"category-recursos","10":"post_format-post-format-image"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prevenci\u00f3n de suicidios entre adolescentes- Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"Intervenci\u00f3n educativa ante el suicidio como el principal problema de salud p\u00fablica en Europa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prevenci\u00f3n de suicidios entre adolescentes- Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"Intervenci\u00f3n educativa ante el suicidio como el principal problema de salud p\u00fablica en Europa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-16T08:35:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-26T12:04:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/destacada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristina Gonz\u00e1lez P\u00e9rez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristina Gonz\u00e1lez P\u00e9rez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/prevencion-de-suicidios-entre-adolescentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/prevencion-de-suicidios-entre-adolescentes\\\/\"},\"author\":{\"name\":\"Cristina Gonz\u00e1lez P\u00e9rez\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/390fa5e1deeba872cc626c7159ce56cd\"},\"headline\":\"Prevenci\u00f3n de suicidios entre adolescentes\",\"datePublished\":\"2020-06-16T08:35:28+00:00\",\"dateModified\":\"2020-10-26T12:04:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/prevencion-de-suicidios-entre-adolescentes\\\/\"},\"wordCount\":2645,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/prevencion-de-suicidios-entre-adolescentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/destacada.jpg\",\"articleSection\":[\"Campus Educaci\u00f3n Revista Digital Docente\",\"General\",\"Recursos Educativos y Publicaciones Did\u00e1cticas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/prevencion-de-suicidios-entre-adolescentes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/prevencion-de-suicidios-entre-adolescentes\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/prevencion-de-suicidios-entre-adolescentes\\\/\",\"name\":\"Prevenci\u00f3n de suicidios entre adolescentes- Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/prevencion-de-suicidios-entre-adolescentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/prevencion-de-suicidios-entre-adolescentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/destacada.jpg\",\"datePublished\":\"2020-06-16T08:35:28+00:00\",\"dateModified\":\"2020-10-26T12:04:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/390fa5e1deeba872cc626c7159ce56cd\"},\"description\":\"Intervenci\u00f3n educativa ante el suicidio como el principal problema de salud p\u00fablica en Europa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/prevencion-de-suicidios-entre-adolescentes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/prevencion-de-suicidios-entre-adolescentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/prevencion-de-suicidios-entre-adolescentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/destacada.jpg\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/destacada.jpg\",\"width\":1200,\"height\":675,\"caption\":\"prevenci\u00f3n del suicidio entre adolescentes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/revista-digital-docente\\\/prevencion-de-suicidios-entre-adolescentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prevenci\u00f3n de suicidios entre adolescentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/390fa5e1deeba872cc626c7159ce56cd\",\"name\":\"Cristina Gonz\u00e1lez P\u00e9rez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Cristina-Gonz\u00e1lez-P\u00e9rez-foto-113x150.png\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Cristina-Gonz\u00e1lez-P\u00e9rez-foto-113x150.png\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Cristina-Gonz\u00e1lez-P\u00e9rez-foto-113x150.png\",\"caption\":\"Cristina Gonz\u00e1lez P\u00e9rez\"},\"description\":\"Licenciada en Psicolog\u00eda, Cristina es M\u00e1ster en Terapia Familiar y en Formaci\u00f3n del Profesorado (Murcia)\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/cristinag\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prevenci\u00f3n de suicidios entre adolescentes- Campuseducacion.com","description":"Intervenci\u00f3n educativa ante el suicidio como el principal problema de salud p\u00fablica en Europa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/","og_locale":"es_ES","og_type":"article","og_title":"Prevenci\u00f3n de suicidios entre adolescentes- Campuseducacion.com","og_description":"Intervenci\u00f3n educativa ante el suicidio como el principal problema de salud p\u00fablica en Europa","og_url":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2020-06-16T08:35:28+00:00","article_modified_time":"2020-10-26T12:04:58+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/destacada.jpg","type":"image\/jpeg"}],"author":"Cristina Gonz\u00e1lez P\u00e9rez","twitter_card":"summary_large_image","twitter_creator":"@Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Cristina Gonz\u00e1lez P\u00e9rez","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/"},"author":{"name":"Cristina Gonz\u00e1lez P\u00e9rez","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/390fa5e1deeba872cc626c7159ce56cd"},"headline":"Prevenci\u00f3n de suicidios entre adolescentes","datePublished":"2020-06-16T08:35:28+00:00","dateModified":"2020-10-26T12:04:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/"},"wordCount":2645,"commentCount":0,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/destacada.jpg","articleSection":["Campus Educaci\u00f3n Revista Digital Docente","General","Recursos Educativos y Publicaciones Did\u00e1cticas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/","url":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/","name":"Prevenci\u00f3n de suicidios entre adolescentes- Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/destacada.jpg","datePublished":"2020-06-16T08:35:28+00:00","dateModified":"2020-10-26T12:04:58+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/390fa5e1deeba872cc626c7159ce56cd"},"description":"Intervenci\u00f3n educativa ante el suicidio como el principal problema de salud p\u00fablica en Europa","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/destacada.jpg","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/destacada.jpg","width":1200,"height":675,"caption":"prevenci\u00f3n del suicidio entre adolescentes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/revista-digital-docente\/prevencion-de-suicidios-entre-adolescentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Prevenci\u00f3n de suicidios entre adolescentes"}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/390fa5e1deeba872cc626c7159ce56cd","name":"Cristina Gonz\u00e1lez P\u00e9rez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/Cristina-Gonz\u00e1lez-P\u00e9rez-foto-113x150.png","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/Cristina-Gonz\u00e1lez-P\u00e9rez-foto-113x150.png","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/06\/Cristina-Gonz\u00e1lez-P\u00e9rez-foto-113x150.png","caption":"Cristina Gonz\u00e1lez P\u00e9rez"},"description":"Licenciada en Psicolog\u00eda, Cristina es M\u00e1ster en Terapia Familiar y en Formaci\u00f3n del Profesorado (Murcia)","url":"https:\/\/www.campuseducacion.com\/blog\/autores\/cristinag\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/19657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/123"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=19657"}],"version-history":[{"count":5,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/19657\/revisions"}],"predecessor-version":[{"id":20653,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/19657\/revisions\/20653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/19658"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=19657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=19657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=19657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}