{"id":2014,"date":"2013-07-25T10:27:17","date_gmt":"2013-07-25T08:27:17","guid":{"rendered":"http:\/\/www.campuseducacion.com\/oposiciones\/?p=2014"},"modified":"2013-08-13T14:19:43","modified_gmt":"2013-08-13T12:19:43","slug":"comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/","title":{"rendered":"Oposiciones Maestros y Profesores Comunidad Valenciana 2013.Resultados obtenidos y aprobados"},"content":{"rendered":"<p>Oposiciones Maestros y Profesores Comunidad Valenciana\u00a02013.Consulta de resultados obtenidos con D.N.I. y en listados. Documentaci\u00f3n a presentar por los aprobados con plaza en la Comunidad Valenciana.<!--more--><\/p>\n<div id=\"enlaces\">Enlaces relacionados:<\/div>\n<div id=\"listaenlaces2\">\n<ul>\n<li><a href=\"https:\/\/appweb.edu.gva.es\/hdfi41\/OPOSICION\/OPO_APROBADOS_cdef.jsp\" target=\"_blank\"><b>1) Accede a la Consulta con DNI<\/b><\/a><\/li>\n<li><a href=\"http:\/\/www.cece.gva.es\/per\/es\/oposiciones.htm?cont=135\" target=\"_blank\"><b> 2) MAESTROS: Listados y Acceso a Petici\u00f3n Telem\u00e1tica<\/b><\/a><\/li>\n<li><a href=\"http:\/\/www.cece.gva.es\/per\/es\/oposiciones.htm?cont=235\" target=\"_blank\"><b>3) SECUNDARIA y OTROS CUERPOS: : Listados y Acceso a Petici\u00f3n Telem\u00e1tica<\/b><\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\">OPOSICIONES<\/span>: Reclamaci\u00f3n de M\u00c9RITOS.<\/p>\n<p><span style=\"text-decoration: underline;\">Si has aprobado sin plaza<\/span>, es muy importante que alcances el m\u00e1ximo posible en M\u00c9RITOS, en tu caso, cuentan para la ordenaci\u00f3n en BOLSA.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>DOCUMENTACI\u00d3N A PRESENTAR si has aprobado CON PLAZA (dispones de un mes):<\/strong><\/p>\n<p>&#8211; Titulaci\u00f3n de tu carrera universitaria.<\/p>\n<p>&#8211; Certificado m\u00e9dico que acredite que no padeces enfermedad ni f\u00edsica ni ps\u00edquica que te impida ejercer la docencia.<\/p>\n<p>&#8211; Titulaci\u00f3n de valenciano.<\/p>\n<p>&#8211; Si has accedido por el turno de DISCAPACITADOS, documentaci\u00f3n que acredite tu condici\u00f3n.<\/p>\n<p>&#8211; Fotocopia de la cartilla de tu cuenta bancaria.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Y, adem\u00e1s, estos documentos:<\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/www.cece.gva.es\/per\/docs\/adjudicaciones\/modelos\/ANEXO_I_pagohaberes.pdf\" target=\"_blank\">ANEXO I: Pago de Haberes<\/a><\/li>\n<li><a href=\"http:\/\/www.cece.gva.es\/per\/docs\/adjudicaciones\/modelos\/ANEXO_II_constitucion.pdf\" target=\"_blank\">ANEXO II: Declaraci\u00f3n Jurada<\/a><\/li>\n<li><a href=\"http:\/\/www.cece.gva.es\/per\/docs\/adjudicaciones\/modelos\/ANEXO_III_manifiesto.pdf\" target=\"_blank\">ANEXO III: Manifiesto<\/a><\/li>\n<li><a href=\"http:\/\/www.cece.gva.es\/per\/docs\/adjudicaciones\/modelos\/modelo145.pdf\" target=\"_blank\">Modelo 145 &#8211; IRPF<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;2014&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;53&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.1&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;4.1\\\/5 - (53 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Oposiciones Maestros y Profesores Comunidad Valenciana 2013.Resultados obtenidos y aprobados&quot;,&quot;width&quot;:&quot;79.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 79.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            4.1\/5 - (53 votos)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Oposiciones Maestros y Profesores Comunidad Valenciana\u00a02013.Consulta de resultados obtenidos con D.N.I. y en listados. Documentaci\u00f3n a presentar por los aprobados con plaza en la Comunidad Valenciana.<\/p>\n","protected":false},"author":2,"featured_media":227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[6,21,22],"tags":[29],"class_list":{"0":"post-2014","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-comunidad-valenciana","8":"category-primaria","9":"category-secundaria","10":"tag-profesores"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oposiciones Maestros y Profesores Comunidad Valenciana 2013.Resultados obtenidos y aprobados - Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"Oposiciones Maestros y Profesores Comunidad Valenciana\u00a02013.Consulta de resultados obtenidos con D.N.I. y en listados. Documentaci\u00f3n a presentar por los\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oposiciones Maestros y Profesores Comunidad Valenciana 2013.Resultados obtenidos y aprobados - Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"Oposiciones Maestros y Profesores Comunidad Valenciana\u00a02013.Consulta de resultados obtenidos con D.N.I. y en listados. Documentaci\u00f3n a presentar por los\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-25T08:27:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-08-13T12:19:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/Comunidad_Valenciana.png\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campuseducacion.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/comunidad-valenciana\\\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/comunidad-valenciana\\\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\\\/\"},\"author\":{\"name\":\"Campuseducacion.com\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"headline\":\"Oposiciones Maestros y Profesores Comunidad Valenciana 2013.Resultados obtenidos y aprobados\",\"datePublished\":\"2013-07-25T08:27:17+00:00\",\"dateModified\":\"2013-08-13T12:19:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/comunidad-valenciana\\\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\\\/\"},\"wordCount\":200,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/comunidad-valenciana\\\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/Comunidad_Valenciana.png\",\"keywords\":[\"profesores\"],\"articleSection\":[\"Oposiciones Comunidad Valenciana\",\"Oposiciones Maestros\",\"Oposiciones Secundaria\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/comunidad-valenciana\\\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/comunidad-valenciana\\\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/comunidad-valenciana\\\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\\\/\",\"name\":\"Oposiciones Maestros y Profesores Comunidad Valenciana 2013.Resultados obtenidos y aprobados - Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/comunidad-valenciana\\\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/comunidad-valenciana\\\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/Comunidad_Valenciana.png\",\"datePublished\":\"2013-07-25T08:27:17+00:00\",\"dateModified\":\"2013-08-13T12:19:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"description\":\"Oposiciones Maestros y Profesores Comunidad Valenciana\u00a02013.Consulta de resultados obtenidos con D.N.I. y en listados. Documentaci\u00f3n a presentar por los\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/comunidad-valenciana\\\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/comunidad-valenciana\\\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/comunidad-valenciana\\\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/Comunidad_Valenciana.png\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/Comunidad_Valenciana.png\",\"width\":620,\"height\":330,\"caption\":\"Noticias de oposiciones de maestros y profesores de la Comunidad Valenciana\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/comunidad-valenciana\\\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oposiciones Maestros y Profesores Comunidad Valenciana 2013.Resultados obtenidos y aprobados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\",\"name\":\"Campuseducacion.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"caption\":\"Campuseducacion.com\"},\"description\":\"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.\",\"sameAs\":[\"https:\\\/\\\/www.campuseducacion.com\",\"https:\\\/\\\/www.facebook.com\\\/Campuseducacion.es\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Campuseducacion\"],\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/adminopos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oposiciones Maestros y Profesores Comunidad Valenciana 2013.Resultados obtenidos y aprobados - Campuseducacion.com","description":"Oposiciones Maestros y Profesores Comunidad Valenciana\u00a02013.Consulta de resultados obtenidos con D.N.I. y en listados. Documentaci\u00f3n a presentar por los","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/","og_locale":"es_ES","og_type":"article","og_title":"Oposiciones Maestros y Profesores Comunidad Valenciana 2013.Resultados obtenidos y aprobados - Campuseducacion.com","og_description":"Oposiciones Maestros y Profesores Comunidad Valenciana\u00a02013.Consulta de resultados obtenidos con D.N.I. y en listados. Documentaci\u00f3n a presentar por los","og_url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_author":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2013-07-25T08:27:17+00:00","article_modified_time":"2013-08-13T12:19:43+00:00","og_image":[{"width":620,"height":330,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/Comunidad_Valenciana.png","type":"image\/png"}],"author":"Campuseducacion.com","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Campuseducacion.com","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/"},"author":{"name":"Campuseducacion.com","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"headline":"Oposiciones Maestros y Profesores Comunidad Valenciana 2013.Resultados obtenidos y aprobados","datePublished":"2013-07-25T08:27:17+00:00","dateModified":"2013-08-13T12:19:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/"},"wordCount":200,"commentCount":0,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/Comunidad_Valenciana.png","keywords":["profesores"],"articleSection":["Oposiciones Comunidad Valenciana","Oposiciones Maestros","Oposiciones Secundaria"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/","url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/","name":"Oposiciones Maestros y Profesores Comunidad Valenciana 2013.Resultados obtenidos y aprobados - Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/Comunidad_Valenciana.png","datePublished":"2013-07-25T08:27:17+00:00","dateModified":"2013-08-13T12:19:43+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"description":"Oposiciones Maestros y Profesores Comunidad Valenciana\u00a02013.Consulta de resultados obtenidos con D.N.I. y en listados. Documentaci\u00f3n a presentar por los","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/Comunidad_Valenciana.png","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/Comunidad_Valenciana.png","width":620,"height":330,"caption":"Noticias de oposiciones de maestros y profesores de la Comunidad Valenciana"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/comunidad-valenciana\/comunidad-valenciana-resultados-obtenidos-y-aprobados-oposiciones-maestros-y-profesores-2013\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Oposiciones Maestros y Profesores Comunidad Valenciana 2013.Resultados obtenidos y aprobados"}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f","name":"Campuseducacion.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","caption":"Campuseducacion.com"},"description":"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.","sameAs":["https:\/\/www.campuseducacion.com","https:\/\/www.facebook.com\/Campuseducacion.es","https:\/\/x.com\/https:\/\/twitter.com\/Campuseducacion"],"url":"https:\/\/www.campuseducacion.com\/blog\/autores\/adminopos\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/2014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=2014"}],"version-history":[{"count":7,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/2014\/revisions"}],"predecessor-version":[{"id":2519,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/2014\/revisions\/2519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/227"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=2014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=2014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=2014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}