{"id":23653,"date":"2021-11-29T16:56:50","date_gmt":"2021-11-29T15:56:50","guid":{"rendered":"https:\/\/www.campuseducacion.com\/blog\/?p=23653"},"modified":"2021-11-29T16:56:50","modified_gmt":"2021-11-29T15:56:50","slug":"oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/","title":{"rendered":"Oposiciones 2022 Canarias: 3.648 plazas para los pr\u00f3ximos 3 a\u00f1os"},"content":{"rendered":"<p>Canarias convocar\u00e1 <strong>3.648 plazas para las Oposiciones docentes de los pr\u00f3ximos 3 a\u00f1os<\/strong>.<\/p>\n<span class='bctt-click-to-tweet'><span class='bctt-ctt-text'><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.campuseducacion.com%2Fblog%2Foposiciones%2Fcomunidades%2Fislas-canarias%2Foposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos%2F&#038;text=3.658%20plazas%20para%20los%20pr%C3%B3ximos%203%20a%C3%B1os%20en%20las%20%23Oposociones%20de%20%23IslasCanarias&#038;via=Campuseducacion&#038;related=Campuseducacion' target='_blank'rel=\"noopener noreferrer\">3.658 plazas para los pr\u00f3ximos 3 a\u00f1os en las #Oposociones de #IslasCanarias <\/a><\/span><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.campuseducacion.com%2Fblog%2Foposiciones%2Fcomunidades%2Fislas-canarias%2Foposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos%2F&#038;text=3.658%20plazas%20para%20los%20pr%C3%B3ximos%203%20a%C3%B1os%20en%20las%20%23Oposociones%20de%20%23IslasCanarias&#038;via=Campuseducacion&#038;related=Campuseducacion' target='_blank' class='bctt-ctt-btn'rel=\"noopener noreferrer\">Compartir en X<\/a><\/span>\n<p>Tras la \u00faltima propuesta presentada por el Gobierno canario de 1.578 plazas para las pr\u00f3ximas Oposiciones a Maestros de 2022 (<a href=\"https:\/\/www3.gobiernodecanarias.org\/noticias\/educacion-aprueba-en-mesa-sectorial-la-oferta-publica-de-empleo-de-personal-docente-2021\/\" target=\"_blank\" rel=\"noopener\"><strong>Oposiciones 2022 Canarias: Propuesta y distribuci\u00f3n de 1.578 plazas para maestros<\/strong><\/a>), la Consejer\u00eda de Educaci\u00f3n, Universidades, Cultura y Deportes del Gobierno de Canarias ha acordado en mesa sectorial la OPE de 2021, la cual se ha fijando con unas <strong>3.648 plazas para los pr\u00f3ximos 3 a\u00f1os<\/strong>.<\/p>\n<p>En el reparto de plazas de dicha OPE para los pr\u00f3ximos a\u00f1os y en los diferentes cuerpos docentes no universitarios, <strong>para el Cuerpo de Maestros<\/strong> se contempla un ligero aumento de plazas; en concreto <strong>unas 1.595 plazas<\/strong>.<\/p>\n<p>Pr\u00f3ximamente el gobierno de las islas confirmar\u00e1 el total de plazas a convocar en las Oposiciones de 2022.<\/p>\n<blockquote class=\"td_quote_box td_box_center\"><p>Si quieres saber <a href=\"https:\/\/www.campuseducacion.com\/blog\/guia-oposiciones\/como-son-las-oposiciones-de-maestros-y-profesores-en-canarias\/\" target=\"_blank\" rel=\"noopener\"><strong>C\u00f3mo son las Oposiciones de Maestros y Profesores en Islas Canarias <\/strong><\/a>te aconsejamos que consultes nuestro post:<\/p>\n<p><a href=\"https:\/\/www.campuseducacion.com\/blog\/guia-oposiciones\/como-son-las-oposiciones-de-maestros-y-profesores-en-canarias\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-20689 \" src=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/10\/Como-son-Oposiciones-Maestros-Profesores-Canarias.jpg\" alt=\"\" width=\"367\" height=\"207\" srcset=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/10\/Como-son-Oposiciones-Maestros-Profesores-Canarias.jpg 1200w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/10\/Como-son-Oposiciones-Maestros-Profesores-Canarias-300x169.jpg 300w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/10\/Como-son-Oposiciones-Maestros-Profesores-Canarias-1024x576.jpg 1024w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/10\/Como-son-Oposiciones-Maestros-Profesores-Canarias-150x84.jpg 150w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/10\/Como-son-Oposiciones-Maestros-Profesores-Canarias-768x432.jpg 768w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/10\/Como-son-Oposiciones-Maestros-Profesores-Canarias-600x338.jpg 600w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/10\/Como-son-Oposiciones-Maestros-Profesores-Canarias-696x392.jpg 696w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/10\/Como-son-Oposiciones-Maestros-Profesores-Canarias-1068x601.jpg 1068w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2020\/10\/Como-son-Oposiciones-Maestros-Profesores-Canarias-747x420.jpg 747w\" sizes=\"auto, (max-width: 367px) 100vw, 367px\" \/><\/a><\/p><\/blockquote>\n<p>Recuerda que en el <strong>baremo de m\u00e9ritos<\/strong> de las oposiciones en <strong>Islas Canarias<\/strong>\u00a0puedes acumular hasta <strong>2 puntos extra<\/strong> si realizas <a href=\"https:\/\/www.campuseducacion.com\/cursos-homologados\/oposiciones-canarias\" target=\"_blank\" rel=\"noopener\">Cursos Homologados para Oposiciones<\/a>.<\/p>\n<p>En concreto, en <strong>Islas Canarias\u00a0<\/strong>es necesario realizar <strong><a href=\"https:\/\/www.campuseducacion.com\/cursos-homologados\/oposiciones-canarias\" target=\"_blank\" rel=\"noopener\">4 Cursos Homologados para Oposiciones<\/a><\/strong> para poder <strong>tener completamente cubierto ese aparatado y sumar as\u00ed 2 PUNTOS ADICIONALES<\/strong> en la nota de oposiciones.<\/p>\n<p>Los <a href=\"https:\/\/www.campuseducacion.com\/cursos-homologados\/oposiciones-canarias\" target=\"_blank\" rel=\"noopener\">Cursos Homologados para Oposiciones de Campuseducacion.com<\/a> son perfectamente <strong>v\u00e1lidos y<\/strong> est\u00e1n <strong>adaptados<\/strong> a los requisitos espec\u00edficos de <strong>Islas Canarias\u00a0<\/strong>, y est\u00e1n <strong>homologados por la Universidad Camilo Jos\u00e9 Cela<\/strong>.<\/p>\n<p style=\"text-align: center;\"><strong>\u00a1No pierdas tiempo y EMPIEZA YA a SUMAR PUNTOS PARA LAS OPOSICIONES!<\/strong><\/p>\n<p><a href=\"https:\/\/www.campuseducacion.com\/cursos-homologados\/oposiciones-canarias\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-21671 size-full\" src=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/01\/suma-canarias.png\" alt=\"cursos canarias\" width=\"688\" height=\"145\" srcset=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/01\/suma-canarias.png 688w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/01\/suma-canarias-300x63.png 300w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/01\/suma-canarias-150x32.png 150w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/01\/suma-canarias-600x126.png 600w\" sizes=\"auto, (max-width: 688px) 100vw, 688px\" \/><\/a><\/p>\n<p><strong>Fuente: <\/strong><a href=\"https:\/\/www3.gobiernodecanarias.org\/noticias\/educacion-aprueba-en-mesa-sectorial-la-oferta-publica-de-empleo-de-personal-docente-2021\/\" target=\"_blank\" rel=\"noopener\">Gobiernodecanarias.org<\/a><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;23653&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Oposiciones 2022 Canarias: 3.648 plazas para los pr\u00f3ximos 3 a\u00f1os&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            <span class=\"kksr-muted\"><\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Canarias convocar\u00e1 3.648 plazas para las Oposiciones docentes de los pr\u00f3ximos 3 a\u00f1os. Tras la \u00faltima propuesta presentada por el Gobierno canario de 1.578 plazas para las pr\u00f3ximas Oposiciones a Maestros de 2022 (Oposiciones 2022 Canarias: Propuesta y distribuci\u00f3n de 1.578 plazas para maestros), la Consejer\u00eda de Educaci\u00f3n, Universidades, Cultura y Deportes del Gobierno de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":23658,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,10,1203],"tags":[],"class_list":{"0":"post-23653","1":"post","2":"type-post","3":"status-publish","4":"format-image","5":"has-post-thumbnail","7":"category-general","8":"category-islas-canarias","9":"category-oposiciones-maestros-2022","10":"post_format-post-format-image"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oposiciones 2022 Canarias: 3.648 plazas para los pr\u00f3ximos 3 a\u00f1os- Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"Canarias convocar\u00e1 3.648 plazas para las Oposiciones docentes de los pr\u00f3ximos 3 a\u00f1os.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oposiciones 2022 Canarias: 3.648 plazas para los pr\u00f3ximos 3 a\u00f1os- Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"Canarias convocar\u00e1 3.648 plazas para las Oposiciones docentes de los pr\u00f3ximos 3 a\u00f1os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-29T15:56:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/11\/Opos-Canarias-3648-plazas-prox-3-anos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campuseducacion.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/islas-canarias\\\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/islas-canarias\\\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\\\/\"},\"author\":{\"name\":\"Campuseducacion.com\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/56e876ff8f12e337395ee2ae40c5fb57\"},\"headline\":\"Oposiciones 2022 Canarias: 3.648 plazas para los pr\u00f3ximos 3 a\u00f1os\",\"datePublished\":\"2021-11-29T15:56:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/islas-canarias\\\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\\\/\"},\"wordCount\":283,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/islas-canarias\\\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Opos-Canarias-3648-plazas-prox-3-anos.jpg\",\"articleSection\":[\"General\",\"Oposiciones Islas Canarias\",\"Oposiciones Maestros 2022\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/islas-canarias\\\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/islas-canarias\\\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\\\/\",\"name\":\"Oposiciones 2022 Canarias: 3.648 plazas para los pr\u00f3ximos 3 a\u00f1os- Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/islas-canarias\\\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/islas-canarias\\\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Opos-Canarias-3648-plazas-prox-3-anos.jpg\",\"datePublished\":\"2021-11-29T15:56:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/56e876ff8f12e337395ee2ae40c5fb57\"},\"description\":\"Canarias convocar\u00e1 3.648 plazas para las Oposiciones docentes de los pr\u00f3ximos 3 a\u00f1os.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/islas-canarias\\\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/islas-canarias\\\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/islas-canarias\\\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Opos-Canarias-3648-plazas-prox-3-anos.jpg\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Opos-Canarias-3648-plazas-prox-3-anos.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/islas-canarias\\\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oposiciones 2022 Canarias: 3.648 plazas para los pr\u00f3ximos 3 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/56e876ff8f12e337395ee2ae40c5fb57\",\"name\":\"Campuseducacion.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g\",\"caption\":\"Campuseducacion.com\"},\"description\":\"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.\",\"sameAs\":[\"https:\\\/\\\/www.campuseducacion.com\",\"https:\\\/\\\/www.facebook.com\\\/Campuseducacion.es\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Campuseducacion\"],\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/campuseducacion-com-4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oposiciones 2022 Canarias: 3.648 plazas para los pr\u00f3ximos 3 a\u00f1os- Campuseducacion.com","description":"Canarias convocar\u00e1 3.648 plazas para las Oposiciones docentes de los pr\u00f3ximos 3 a\u00f1os.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/","og_locale":"es_ES","og_type":"article","og_title":"Oposiciones 2022 Canarias: 3.648 plazas para los pr\u00f3ximos 3 a\u00f1os- Campuseducacion.com","og_description":"Canarias convocar\u00e1 3.648 plazas para las Oposiciones docentes de los pr\u00f3ximos 3 a\u00f1os.","og_url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_author":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2021-11-29T15:56:50+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/11\/Opos-Canarias-3648-plazas-prox-3-anos.jpg","type":"image\/jpeg"}],"author":"Campuseducacion.com","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Campuseducacion.com","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/"},"author":{"name":"Campuseducacion.com","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/56e876ff8f12e337395ee2ae40c5fb57"},"headline":"Oposiciones 2022 Canarias: 3.648 plazas para los pr\u00f3ximos 3 a\u00f1os","datePublished":"2021-11-29T15:56:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/"},"wordCount":283,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/11\/Opos-Canarias-3648-plazas-prox-3-anos.jpg","articleSection":["General","Oposiciones Islas Canarias","Oposiciones Maestros 2022"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/","url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/","name":"Oposiciones 2022 Canarias: 3.648 plazas para los pr\u00f3ximos 3 a\u00f1os- Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/11\/Opos-Canarias-3648-plazas-prox-3-anos.jpg","datePublished":"2021-11-29T15:56:50+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/56e876ff8f12e337395ee2ae40c5fb57"},"description":"Canarias convocar\u00e1 3.648 plazas para las Oposiciones docentes de los pr\u00f3ximos 3 a\u00f1os.","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/11\/Opos-Canarias-3648-plazas-prox-3-anos.jpg","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/11\/Opos-Canarias-3648-plazas-prox-3-anos.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/islas-canarias\/oposiciones-2022-canarias-3-648-plazas-para-los-proximos-3-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Oposiciones 2022 Canarias: 3.648 plazas para los pr\u00f3ximos 3 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/56e876ff8f12e337395ee2ae40c5fb57","name":"Campuseducacion.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g","caption":"Campuseducacion.com"},"description":"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.","sameAs":["https:\/\/www.campuseducacion.com","https:\/\/www.facebook.com\/Campuseducacion.es","https:\/\/x.com\/https:\/\/twitter.com\/Campuseducacion"],"url":"https:\/\/www.campuseducacion.com\/blog\/autores\/campuseducacion-com-4\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/23653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=23653"}],"version-history":[{"count":1,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/23653\/revisions"}],"predecessor-version":[{"id":23659,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/23653\/revisions\/23659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/23658"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=23653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=23653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=23653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}