{"id":24179,"date":"2022-02-17T18:02:41","date_gmt":"2022-02-17T17:02:41","guid":{"rendered":"https:\/\/www.campuseducacion.com\/blog\/?p=24179"},"modified":"2022-02-17T18:02:41","modified_gmt":"2022-02-17T17:02:41","slug":"interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/","title":{"rendered":"Interinos en el exterior: Plazas para Maestros y Profesores en varios pa\u00edses"},"content":{"rendered":"<p><strong>Portugal, Alemania, Pa\u00edses Bajos, Luxemburgo y B\u00e9lgica<\/strong> abren listas para cubrir plazas durante el curso 2022\/2023.<\/p>\n<span class='bctt-click-to-tweet'><span class='bctt-ctt-text'><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.campuseducacion.com%2Fblog%2Fbolsas-de-trabajo%2Finterinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises%2F&#038;text=Plazas%20para%20Maestros%20y%20Profesores%20%23InterinosExterior&#038;via=Campuseducacion&#038;related=Campuseducacion' target='_blank'rel=\"noopener noreferrer\">Plazas para Maestros y Profesores #InterinosExterior <\/a><\/span><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.campuseducacion.com%2Fblog%2Fbolsas-de-trabajo%2Finterinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises%2F&#038;text=Plazas%20para%20Maestros%20y%20Profesores%20%23InterinosExterior&#038;via=Campuseducacion&#038;related=Campuseducacion' target='_blank' class='bctt-ctt-btn'rel=\"noopener noreferrer\">Compartir en X<\/a><\/span>\n<p>Las Consejer\u00edas de Educaci\u00f3n en Portugal, Alemania, Pa\u00edses Bajos, Luxemburgo y B\u00e9lgica publican<strong> convocatoria para la formaci\u00f3n de listas de aspirantes para cubrir puestos docentes en r\u00e9gimen de interinidad en diferentes especialidades<\/strong> para los Cuerpos de Maestros y Profesores de Ense\u00f1anza Secundaria.<\/p>\n<p><strong>Portugal<\/strong><\/p>\n<ul>\n<li><strong><a href=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2022\/02\/Convocatoria-Portugal.pdf\" target=\"_blank\" rel=\"noopener\">Convocatoria Portugal<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/www.educacionyfp.gob.es\/servicios-al-ciudadano\/catalogo\/general\/20\/200334\/portugal\/200334-portugal-2022-2023.html\" target=\"_blank\" rel=\"noopener\">Informaci\u00f3n y tramites<\/a><\/strong><\/li>\n<li><strong>Plazo de presentaci\u00f3n de solicitudes:<\/strong> hasta el 1 de marzo.<\/li>\n<\/ul>\n<p><strong>Alemania\u00a0<\/strong><\/p>\n<ul>\n<li><strong><a href=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2022\/02\/Convocatoria-Alemania.pdf\" target=\"_blank\" rel=\"noopener\">Convocatoria Alemania<\/a><\/strong><\/li>\n<li><a href=\"https:\/\/www.educacionyfp.gob.es\/servicios-al-ciudadano\/catalogo\/general\/20\/200334\/alemania\/200334-alemania-2021-2022.html\" target=\"_blank\" rel=\"noopener\"><strong>Informaci\u00f3n y tramites<\/strong><\/a><\/li>\n<li><strong>Plazo de presentaci\u00f3n de solicitudes:<\/strong> hasta el 7 de marzo.<\/li>\n<\/ul>\n<p><strong>Pa\u00edses Bajos\u00a0<\/strong><\/p>\n<ul>\n<li><strong><a href=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2022\/02\/Convocatoria-Paises-Bajos.pdf\" target=\"_blank\" rel=\"noopener\">Convocatoria Pa\u00edses Bajos<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/www.educacionyfp.gob.es\/servicios-al-ciudadano\/catalogo\/general\/20\/200334\/belgica-paises-bajos-luxemburgo\/200334-paises-bajos-2022-2023.html#dc\" target=\"_blank\" rel=\"noopener\">Informaci\u00f3n y tramites\u00a0<\/a><\/strong><\/li>\n<li><strong>Plazo de presentaci\u00f3n de solicitudes:<\/strong> hasta el 7 de marzo.<\/li>\n<\/ul>\n<p><strong>B\u00e9lgica y Luxemburgo<\/strong><\/p>\n<ul>\n<li><strong><a href=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2022\/02\/Convocatoria-Belgica-y-Luxemburgo.pdf\" target=\"_blank\" rel=\"noopener\">Convocatoria B\u00e9lgica y Luxemburgo<\/a><\/strong><\/li>\n<li><strong><a href=\"https:\/\/www.educacionyfp.gob.es\/servicios-al-ciudadano\/catalogo\/general\/20\/200334\/belgica-paises-bajos-luxemburgo\/200334-belgica-luxemburgo-2022-2023.html#dc\" target=\"_blank\" rel=\"noopener\">Informaci\u00f3n y tramites\u00a0<\/a><\/strong><\/li>\n<li><strong>Plazo de presentaci\u00f3n de solicitudes:<\/strong> hasta el 7 de marzo.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;24179&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Interinos en el exterior: Plazas para Maestros y Profesores en varios pa\u00edses&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            <span class=\"kksr-muted\"><\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Portugal, Alemania, Pa\u00edses Bajos, Luxemburgo y B\u00e9lgica abren listas para cubrir plazas durante el curso 2022\/2023. Las Consejer\u00edas de Educaci\u00f3n en Portugal, Alemania, Pa\u00edses Bajos, Luxemburgo y B\u00e9lgica publican convocatoria para la formaci\u00f3n de listas de aspirantes para cubrir puestos docentes en r\u00e9gimen de interinidad en diferentes especialidades para los Cuerpos de Maestros y Profesores [&hellip;]<\/p>\n","protected":false},"author":138,"featured_media":9372,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[199,219,1],"tags":[],"class_list":{"0":"post-24179","1":"post","2":"type-post","3":"status-publish","4":"format-image","5":"has-post-thumbnail","7":"category-bolsas-de-trabajo","8":"category-bolsas-exterior","9":"category-general","10":"post_format-post-format-image"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interinos en el exterior: Plazas para Maestros y Profesores en varios pa\u00edses - Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"Portugal, Alemania, Pa\u00edses Bajos, Luxemburgo y B\u00e9lgica abren listas para cubrir plazas durante el curso 2022\/2023. Las Consejer\u00edas de Educaci\u00f3n en\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interinos en el exterior: Plazas para Maestros y Profesores en varios pa\u00edses - Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"Portugal, Alemania, Pa\u00edses Bajos, Luxemburgo y B\u00e9lgica abren listas para cubrir plazas durante el curso 2022\/2023. Las Consejer\u00edas de Educaci\u00f3n en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-17T17:02:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/03\/multiples-banderas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campuseducacion.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\\\/\"},\"author\":{\"name\":\"Campuseducacion.com\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/b142bb7fe885b7ad61b5bfa15e3d26a4\"},\"headline\":\"Interinos en el exterior: Plazas para Maestros y Profesores en varios pa\u00edses\",\"datePublished\":\"2022-02-17T17:02:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\\\/\"},\"wordCount\":168,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/multiples-banderas.jpg\",\"articleSection\":[\"Bolsas de Trabajo para Interinos Maestros y Profesores\",\"Bolsas fuera de Espa\u00f1a\",\"General\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\\\/\",\"name\":\"Interinos en el exterior: Plazas para Maestros y Profesores en varios pa\u00edses - Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/multiples-banderas.jpg\",\"datePublished\":\"2022-02-17T17:02:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/b142bb7fe885b7ad61b5bfa15e3d26a4\"},\"description\":\"Portugal, Alemania, Pa\u00edses Bajos, Luxemburgo y B\u00e9lgica abren listas para cubrir plazas durante el curso 2022\\\/2023. Las Consejer\u00edas de Educaci\u00f3n en\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/multiples-banderas.jpg\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/multiples-banderas.jpg\",\"width\":1200,\"height\":627,\"caption\":\"100 plazas en el extranjero para funcionarios\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interinos en el exterior: Plazas para Maestros y Profesores en varios pa\u00edses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/b142bb7fe885b7ad61b5bfa15e3d26a4\",\"name\":\"Campuseducacion.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Ced.png\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Ced.png\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Ced.png\",\"caption\":\"Campuseducacion.com\"},\"description\":\"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.\",\"sameAs\":[\"https:\\\/\\\/www.campuseducacion.com\",\"https:\\\/\\\/www.facebook.com\\\/Campuseducacion.es\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Campuseducacion\"],\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/elenaced\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interinos en el exterior: Plazas para Maestros y Profesores en varios pa\u00edses - Campuseducacion.com","description":"Portugal, Alemania, Pa\u00edses Bajos, Luxemburgo y B\u00e9lgica abren listas para cubrir plazas durante el curso 2022\/2023. Las Consejer\u00edas de Educaci\u00f3n en","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/","og_locale":"es_ES","og_type":"article","og_title":"Interinos en el exterior: Plazas para Maestros y Profesores en varios pa\u00edses - Campuseducacion.com","og_description":"Portugal, Alemania, Pa\u00edses Bajos, Luxemburgo y B\u00e9lgica abren listas para cubrir plazas durante el curso 2022\/2023. Las Consejer\u00edas de Educaci\u00f3n en","og_url":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_author":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2022-02-17T17:02:41+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/03\/multiples-banderas.jpg","type":"image\/jpeg"}],"author":"Campuseducacion.com","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Campuseducacion.com","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/"},"author":{"name":"Campuseducacion.com","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/b142bb7fe885b7ad61b5bfa15e3d26a4"},"headline":"Interinos en el exterior: Plazas para Maestros y Profesores en varios pa\u00edses","datePublished":"2022-02-17T17:02:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/"},"wordCount":168,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/03\/multiples-banderas.jpg","articleSection":["Bolsas de Trabajo para Interinos Maestros y Profesores","Bolsas fuera de Espa\u00f1a","General"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/","url":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/","name":"Interinos en el exterior: Plazas para Maestros y Profesores en varios pa\u00edses - Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/03\/multiples-banderas.jpg","datePublished":"2022-02-17T17:02:41+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/b142bb7fe885b7ad61b5bfa15e3d26a4"},"description":"Portugal, Alemania, Pa\u00edses Bajos, Luxemburgo y B\u00e9lgica abren listas para cubrir plazas durante el curso 2022\/2023. Las Consejer\u00edas de Educaci\u00f3n en","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/03\/multiples-banderas.jpg","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2017\/03\/multiples-banderas.jpg","width":1200,"height":627,"caption":"100 plazas en el extranjero para funcionarios"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-en-el-exterior-plazas-para-maestros-y-profesores-en-varios-paises\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Interinos en el exterior: Plazas para Maestros y Profesores en varios pa\u00edses"}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/b142bb7fe885b7ad61b5bfa15e3d26a4","name":"Campuseducacion.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2018\/05\/Ced.png","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2018\/05\/Ced.png","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2018\/05\/Ced.png","caption":"Campuseducacion.com"},"description":"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.","sameAs":["https:\/\/www.campuseducacion.com","https:\/\/www.facebook.com\/Campuseducacion.es","https:\/\/x.com\/https:\/\/twitter.com\/Campuseducacion"],"url":"https:\/\/www.campuseducacion.com\/blog\/autores\/elenaced\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/24179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/138"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=24179"}],"version-history":[{"count":1,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/24179\/revisions"}],"predecessor-version":[{"id":24184,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/24179\/revisions\/24184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/9372"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=24179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=24179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=24179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}