{"id":26124,"date":"2023-02-21T11:56:14","date_gmt":"2023-02-21T10:56:14","guid":{"rendered":"https:\/\/www.campuseducacion.com\/blog\/?p=26124"},"modified":"2023-02-21T11:56:14","modified_gmt":"2023-02-21T10:56:14","slug":"interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/","title":{"rendered":"Interinos Francia: Plazas para Maestros y Profesores para el curso 2023\/2024"},"content":{"rendered":"<p>Plazo abierto para<strong> listas de interinos en Francia para maestros y Profesores.\u00a0<\/strong><\/p>\n<span class='bctt-click-to-tweet'><span class='bctt-ctt-text'><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.campuseducacion.com%2Fblog%2Fbolsas-de-trabajo%2Finterinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024%2F&#038;text=Plazas%20para%20Maestros%20y%20Profesores%20para%20el%20curso%202023%2F2024%20%23InterinosFrancia&#038;via=Campuseducacion&#038;related=Campuseducacion' target='_blank'rel=\"noopener noreferrer\">Plazas para Maestros y Profesores para el curso 2023\/2024 #InterinosFrancia <\/a><\/span><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.campuseducacion.com%2Fblog%2Fbolsas-de-trabajo%2Finterinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024%2F&#038;text=Plazas%20para%20Maestros%20y%20Profesores%20para%20el%20curso%202023%2F2024%20%23InterinosFrancia&#038;via=Campuseducacion&#038;related=Campuseducacion' target='_blank' class='bctt-ctt-btn'rel=\"noopener noreferrer\">Compartir en X<\/a><\/span>\n<p>La Consejer\u00eda de Educaci\u00f3n en Francia publica convocatoria para la <strong>formaci\u00f3n de listas de <\/strong><strong>aspirantes para cubrir puestos docentes en r\u00e9gimen de interinidad en diferentes <\/strong><strong>especialidades<\/strong> para los Cuerpos de Maestros y Profesores de Ense\u00f1anza Secundaria. Especialidades convocadas:<\/p>\n<ul>\n<li><strong>CUERPO DE MAESTROS:<\/strong>\n<ul>\n<li>Educaci\u00f3n F\u00edsica (Colegio Federico Garc\u00eda Lorca de Par\u00eds)<\/li>\n<li>Educaci\u00f3n Infantil (Colegio Federico Garc\u00eda Lorca de Par\u00eds)<\/li>\n<li>Franc\u00e9s (Colegio Federico Garc\u00eda Lorca de Par\u00eds y Agrupaciones de Lengua y Cultura espa\u00f1olas)<\/li>\n<li>Ingl\u00e9s (Colegio Federico Garc\u00eda Lorca de Par\u00eds y Agrupaciones de Lengua y Cultura espa\u00f1olas)<\/li>\n<li>M\u00fasica (Colegio Federico Garc\u00eda Lorca de Par\u00eds)<\/li>\n<li>Primaria (Colegio Federico Garc\u00eda Lorca de Par\u00eds, Agrupaciones de Lengua y Cultura espa\u00f1olas y Secciones Internacionales Espa\u00f1olas)<\/li>\n<\/ul>\n<\/li>\n<li><strong>PROFESORES DE EDUCACI\u00d3N SECUNDARIA:<\/strong>\n<ul>\n<li>Biolog\u00eda y Geolog\u00eda (Liceo Luis Bu\u00f1uel de Par\u00eds)<\/li>\n<li>Dibujo (Liceo Luis Bu\u00f1uel de Par\u00eds)<\/li>\n<li>Econom\u00eda (Liceo Luis Bu\u00f1uel de Par\u00eds)<\/li>\n<li>Educaci\u00f3n F\u00edsica (Liceo Luis Bu\u00f1uel de Par\u00eds)<\/li>\n<li>Filosof\u00eda (Liceo Luis Bu\u00f1uel de Par\u00eds)<\/li>\n<li>F\u00edsica y Qu\u00edmica (Liceo Luis Bu\u00f1uel de Par\u00eds)<\/li>\n<li>Franc\u00e9s (Liceo Luis Bu\u00f1uel de Par\u00eds y Agrupaciones de Lengua y Cultura espa\u00f1olas<\/li>\n<li>Geograf\u00eda e Historia (Liceo Luis Bu\u00f1uel de Par\u00eds y Secciones Internacionales Espa\u00f1olas)<\/li>\n<li>Ingl\u00e9s (Liceo Luis Bu\u00f1uel de Par\u00eds)<\/li>\n<li>Lat\u00edn (Liceo Luis Bu\u00f1uel de Par\u00eds)<\/li>\n<li>Lengua Castellana y Literatura (Liceo Luis Bu\u00f1uel de Par\u00eds, Secciones Internacionales Espa\u00f1olas y Agrupaciones de Lengua y Cultura espa\u00f1olas)<\/li>\n<li>Matem\u00e1ticas (Liceo Luis Bu\u00f1uel de Par\u00eds)<\/li>\n<li>Orientaci\u00f3n Educativa (Liceo Luis Bu\u00f1uel de Par\u00eds)<\/li>\n<li>Tecnolog\u00eda (Liceo Luis Bu\u00f1uel de Par\u00eds)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><strong><a href=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/02\/Comisiones-de-valoracion.pdf\" target=\"_blank\" rel=\"noopener\">Comisiones de valoraci\u00f3n<\/a> <\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/02\/Resolucion-3.pdf\" target=\"_blank\" rel=\"noopener\">Resoluci\u00f3n<\/a><\/strong><\/p>\n<p><strong>Plazo de solicitudes<\/strong>: hasta el 1 de marzo en <strong><a href=\"https:\/\/www.educacionyfp.gob.es\/servicios-al-ciudadano\/catalogo\/general\/20\/200334\/francia\/200334-francia-2022-2023.html#dc1\" target=\"_blank\" rel=\"noopener\">educacionyfp.gob.es<\/a><\/strong><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;26124&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Interinos Francia: Plazas para Maestros y Profesores para el curso 2023\\\/2024&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            <span class=\"kksr-muted\"><\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Plazo abierto para listas de interinos en Francia para maestros y Profesores.\u00a0 La Consejer\u00eda de Educaci\u00f3n en Francia publica convocatoria para la formaci\u00f3n de listas de aspirantes para cubrir puestos docentes en r\u00e9gimen de interinidad en diferentes especialidades para los Cuerpos de Maestros y Profesores de Ense\u00f1anza Secundaria. Especialidades convocadas: CUERPO DE MAESTROS: Educaci\u00f3n F\u00edsica [&hellip;]<\/p>\n","protected":false},"author":138,"featured_media":5535,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[199,219,1],"tags":[],"class_list":{"0":"post-26124","1":"post","2":"type-post","3":"status-publish","4":"format-image","5":"has-post-thumbnail","7":"category-bolsas-de-trabajo","8":"category-bolsas-exterior","9":"category-general","10":"post_format-post-format-image"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interinos Francia: Plazas para Maestros y Profesores para el curso 2023\/2024 - Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"Plazo abierto para listas de interinos en Francia para maestros y Profesores.\u00a0 La Consejer\u00eda de Educaci\u00f3n en Francia publica convocatoria para la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interinos Francia: Plazas para Maestros y Profesores para el curso 2023\/2024 - Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"Plazo abierto para listas de interinos en Francia para maestros y Profesores.\u00a0 La Consejer\u00eda de Educaci\u00f3n en Francia publica convocatoria para la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-21T10:56:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2015\/07\/Francia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campuseducacion.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\\\/\"},\"author\":{\"name\":\"Campuseducacion.com\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/b142bb7fe885b7ad61b5bfa15e3d26a4\"},\"headline\":\"Interinos Francia: Plazas para Maestros y Profesores para el curso 2023\\\/2024\",\"datePublished\":\"2023-02-21T10:56:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\\\/\"},\"wordCount\":356,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Francia.jpg\",\"articleSection\":[\"Bolsas de Trabajo para Interinos Maestros y Profesores\",\"Bolsas fuera de Espa\u00f1a\",\"General\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\\\/\",\"name\":\"Interinos Francia: Plazas para Maestros y Profesores para el curso 2023\\\/2024 - Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Francia.jpg\",\"datePublished\":\"2023-02-21T10:56:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/b142bb7fe885b7ad61b5bfa15e3d26a4\"},\"description\":\"Plazo abierto para listas de interinos en Francia para maestros y Profesores.\u00a0 La Consejer\u00eda de Educaci\u00f3n en Francia publica convocatoria para la\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Francia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/Francia.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"bandera francia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interinos Francia: Plazas para Maestros y Profesores para el curso 2023\\\/2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/b142bb7fe885b7ad61b5bfa15e3d26a4\",\"name\":\"Campuseducacion.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Ced.png\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Ced.png\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Ced.png\",\"caption\":\"Campuseducacion.com\"},\"description\":\"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.\",\"sameAs\":[\"https:\\\/\\\/www.campuseducacion.com\",\"https:\\\/\\\/www.facebook.com\\\/Campuseducacion.es\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Campuseducacion\"],\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/elenaced\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interinos Francia: Plazas para Maestros y Profesores para el curso 2023\/2024 - Campuseducacion.com","description":"Plazo abierto para listas de interinos en Francia para maestros y Profesores.\u00a0 La Consejer\u00eda de Educaci\u00f3n en Francia publica convocatoria para la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/","og_locale":"es_ES","og_type":"article","og_title":"Interinos Francia: Plazas para Maestros y Profesores para el curso 2023\/2024 - Campuseducacion.com","og_description":"Plazo abierto para listas de interinos en Francia para maestros y Profesores.\u00a0 La Consejer\u00eda de Educaci\u00f3n en Francia publica convocatoria para la","og_url":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_author":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2023-02-21T10:56:14+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2015\/07\/Francia.jpg","type":"image\/jpeg"}],"author":"Campuseducacion.com","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Campuseducacion.com","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/"},"author":{"name":"Campuseducacion.com","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/b142bb7fe885b7ad61b5bfa15e3d26a4"},"headline":"Interinos Francia: Plazas para Maestros y Profesores para el curso 2023\/2024","datePublished":"2023-02-21T10:56:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/"},"wordCount":356,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2015\/07\/Francia.jpg","articleSection":["Bolsas de Trabajo para Interinos Maestros y Profesores","Bolsas fuera de Espa\u00f1a","General"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/","url":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/","name":"Interinos Francia: Plazas para Maestros y Profesores para el curso 2023\/2024 - Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2015\/07\/Francia.jpg","datePublished":"2023-02-21T10:56:14+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/b142bb7fe885b7ad61b5bfa15e3d26a4"},"description":"Plazo abierto para listas de interinos en Francia para maestros y Profesores.\u00a0 La Consejer\u00eda de Educaci\u00f3n en Francia publica convocatoria para la","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2015\/07\/Francia.jpg","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2015\/07\/Francia.jpg","width":2000,"height":1333,"caption":"bandera francia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/interinos-francia-plazas-para-maestros-y-profesores-para-el-curso-2023-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Interinos Francia: Plazas para Maestros y Profesores para el curso 2023\/2024"}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/b142bb7fe885b7ad61b5bfa15e3d26a4","name":"Campuseducacion.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2018\/05\/Ced.png","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2018\/05\/Ced.png","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2018\/05\/Ced.png","caption":"Campuseducacion.com"},"description":"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.","sameAs":["https:\/\/www.campuseducacion.com","https:\/\/www.facebook.com\/Campuseducacion.es","https:\/\/x.com\/https:\/\/twitter.com\/Campuseducacion"],"url":"https:\/\/www.campuseducacion.com\/blog\/autores\/elenaced\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/26124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/138"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=26124"}],"version-history":[{"count":1,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/26124\/revisions"}],"predecessor-version":[{"id":26127,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/26124\/revisions\/26127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/5535"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=26124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=26124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=26124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}