{"id":26681,"date":"2023-09-22T11:11:40","date_gmt":"2023-09-22T09:11:40","guid":{"rendered":"https:\/\/www.campuseducacion.com\/blog\/?p=26681"},"modified":"2023-09-22T11:11:40","modified_gmt":"2023-09-22T09:11:40","slug":"comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/","title":{"rendered":"Comunidad de Madrid: Publicada OPE con 1.633 plazas docentes"},"content":{"rendered":"<p><strong>Comunidad de Madrid <\/strong>publica su <strong>OPE 2023<\/strong> con<strong> 1.633 plazas para docentes<\/strong>.<\/p>\n<span class='bctt-click-to-tweet'><span class='bctt-ctt-text'><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.campuseducacion.com%2Fblog%2Foposiciones%2Fcomunidades%2Fmadrid%2Fcomunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes%2F&#038;text=Publicada%20%23OPE%20en%20%23ComunidadDeMadrid%20con%201.633%20plazas%20%23Oposiciones2024&#038;via=Campuseducacion&#038;related=Campuseducacion' target='_blank'rel=\"noopener noreferrer\">Publicada #OPE en #ComunidadDeMadrid con 1.633 plazas #Oposiciones2024 <\/a><\/span><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.campuseducacion.com%2Fblog%2Foposiciones%2Fcomunidades%2Fmadrid%2Fcomunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes%2F&#038;text=Publicada%20%23OPE%20en%20%23ComunidadDeMadrid%20con%201.633%20plazas%20%23Oposiciones2024&#038;via=Campuseducacion&#038;related=Campuseducacion' target='_blank' class='bctt-ctt-btn'rel=\"noopener noreferrer\">Compartir en X<\/a><\/span>\n<ul>\n<li><a href=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/09\/OPE-Madrid-2023.pdf\" target=\"_blank\" rel=\"noopener\">OPE Comunidad de Madrid 2023<\/a><\/li>\n<\/ul>\n<p>La Oferta P\u00fablica de Empleo que ha publicado la Comunidad de Madrid engloba <strong>1.633 plazas para el personal funcionario docente de ense\u00f1anzas no universitarias<\/strong>, repartidas de la siguiente forma:<\/p>\n<ul>\n<li><strong>Profesores de Ense\u00f1anza Secundaria y Otros Cuerpos: 890 plazas<\/strong><\/li>\n<li><strong>Catedr\u00e1ticos de M\u00fasica y Artes Esc\u00e9nicas: 29 plazas<\/strong><\/li>\n<li><strong>Inspectores de Educaci\u00f3n: 10 plazas<\/strong><\/li>\n<li><strong>Maestros y Otros Cuerpos: 704 plazas<\/strong><\/li>\n<\/ul>\n<p>Se espera que en <strong>2024<\/strong> la Comunidad de Madrid convoque, al menos, las <strong>704 plazas<\/strong> contempladas para el <strong>Cuerpo de Maestros<\/strong> en esta OPE, desarrollando as\u00ed las <strong>oposiciones tradicionales<\/strong> de reposici\u00f3n. Sin embargo, todav\u00eda no contamos con m\u00e1s noticias al respecto.<\/p>\n<p style=\"text-align: center;\"><strong>Para conocer el estado de las convocatorias en todas las Comunidades Aut\u00f3nomas y los tipos de procesos que se esperan en las Oposiciones 2024 te recomendamos que permanezcas atento a nuestro <a href=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/oposiciones-2024-mapa-actualizado-de-convocatorias\/\" target=\"_blank\" rel=\"noopener\">Mapa de Previsi\u00f3n de Plazas para las Oposiciones 2024<\/a>.<\/strong><\/p>\n<p><a href=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/oposiciones-2024-mapa-actualizado-de-convocatorias\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-26337 \" src=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/04\/Prevision-Convocatorias-24.jpg\" alt=\"\" width=\"532\" height=\"299\" srcset=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/04\/Prevision-Convocatorias-24.jpg 1200w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/04\/Prevision-Convocatorias-24-300x169.jpg 300w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/04\/Prevision-Convocatorias-24-1024x576.jpg 1024w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/04\/Prevision-Convocatorias-24-150x84.jpg 150w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/04\/Prevision-Convocatorias-24-768x432.jpg 768w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/04\/Prevision-Convocatorias-24-600x338.jpg 600w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/04\/Prevision-Convocatorias-24-696x392.jpg 696w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/04\/Prevision-Convocatorias-24-1068x601.jpg 1068w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/04\/Prevision-Convocatorias-24-747x420.jpg 747w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><strong>\u00bfHas completado ya tu baremo para las pr\u00f3ximas Oposiciones de 2024?<br \/>\n<\/strong><strong>\u00a1No esperes m\u00e1s y consigue la m\u00e1xima nota!\u00a0<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>\u00a1Con los <a href=\"https:\/\/www.campuseducacion.com\/cursos-homologados\/oposiciones-madrid\" target=\"_blank\" rel=\"noopener\">Cursos Homologados de Campuseducacion.com v\u00e1lidos para la Comunidad de Madrid<\/a> puedes obtener hasta 2 puntos extra!<\/strong><\/p>\n<p><a href=\"https:\/\/www.campuseducacion.com\/cursos-homologados-online\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-21665 size-full\" src=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/01\/sumar-generico.png\" alt=\"Cursos sumar puntos\" width=\"688\" height=\"145\" srcset=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/01\/sumar-generico.png 688w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/01\/sumar-generico-300x63.png 300w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/01\/sumar-generico-150x32.png 150w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/01\/sumar-generico-600x126.png 600w\" sizes=\"auto, (max-width: 688px) 100vw, 688px\" \/><\/a><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;26681&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Comunidad de Madrid: Publicada OPE con 1.633 plazas docentes&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            <span class=\"kksr-muted\"><\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Comunidad de Madrid publica su OPE 2023 con 1.633 plazas para docentes. OPE Comunidad de Madrid 2023 La Oferta P\u00fablica de Empleo que ha publicado la Comunidad de Madrid engloba 1.633 plazas para el personal funcionario docente de ense\u00f1anzas no universitarias, repartidas de la siguiente forma: Profesores de Ense\u00f1anza Secundaria y Otros Cuerpos: 890 plazas [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":26683,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,5],"tags":[],"class_list":{"0":"post-26681","1":"post","2":"type-post","3":"status-publish","4":"format-image","5":"has-post-thumbnail","7":"category-general","8":"category-madrid","9":"post_format-post-format-image"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunidad de Madrid: Publicada OPE con 1.633 plazas docentes - Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"Comunidad de Madrid publica su OPE 2023 con 1.633 plazas para docentes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunidad de Madrid: Publicada OPE con 1.633 plazas docentes - Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"Comunidad de Madrid publica su OPE 2023 con 1.633 plazas para docentes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-22T09:11:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/09\/OPOS-MADRID-1633-plazas-docentes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campuseducacion.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\\\/\"},\"author\":{\"name\":\"Campuseducacion.com\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/56e876ff8f12e337395ee2ae40c5fb57\"},\"headline\":\"Comunidad de Madrid: Publicada OPE con 1.633 plazas docentes\",\"datePublished\":\"2023-09-22T09:11:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\\\/\"},\"wordCount\":214,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/OPOS-MADRID-1633-plazas-docentes.jpg\",\"articleSection\":[\"General\",\"Oposiciones Madrid\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\\\/\",\"name\":\"Comunidad de Madrid: Publicada OPE con 1.633 plazas docentes - Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/OPOS-MADRID-1633-plazas-docentes.jpg\",\"datePublished\":\"2023-09-22T09:11:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/56e876ff8f12e337395ee2ae40c5fb57\"},\"description\":\"Comunidad de Madrid publica su OPE 2023 con 1.633 plazas para docentes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/OPOS-MADRID-1633-plazas-docentes.jpg\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/OPOS-MADRID-1633-plazas-docentes.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunidad de Madrid: Publicada OPE con 1.633 plazas docentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/56e876ff8f12e337395ee2ae40c5fb57\",\"name\":\"Campuseducacion.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g\",\"caption\":\"Campuseducacion.com\"},\"description\":\"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.\",\"sameAs\":[\"https:\\\/\\\/www.campuseducacion.com\",\"https:\\\/\\\/www.facebook.com\\\/Campuseducacion.es\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Campuseducacion\"],\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/campuseducacion-com-4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunidad de Madrid: Publicada OPE con 1.633 plazas docentes - Campuseducacion.com","description":"Comunidad de Madrid publica su OPE 2023 con 1.633 plazas para docentes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/","og_locale":"es_ES","og_type":"article","og_title":"Comunidad de Madrid: Publicada OPE con 1.633 plazas docentes - Campuseducacion.com","og_description":"Comunidad de Madrid publica su OPE 2023 con 1.633 plazas para docentes.","og_url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_author":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2023-09-22T09:11:40+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/09\/OPOS-MADRID-1633-plazas-docentes.jpg","type":"image\/jpeg"}],"author":"Campuseducacion.com","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Campuseducacion.com","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/"},"author":{"name":"Campuseducacion.com","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/56e876ff8f12e337395ee2ae40c5fb57"},"headline":"Comunidad de Madrid: Publicada OPE con 1.633 plazas docentes","datePublished":"2023-09-22T09:11:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/"},"wordCount":214,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/09\/OPOS-MADRID-1633-plazas-docentes.jpg","articleSection":["General","Oposiciones Madrid"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/","url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/","name":"Comunidad de Madrid: Publicada OPE con 1.633 plazas docentes - Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/09\/OPOS-MADRID-1633-plazas-docentes.jpg","datePublished":"2023-09-22T09:11:40+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/56e876ff8f12e337395ee2ae40c5fb57"},"description":"Comunidad de Madrid publica su OPE 2023 con 1.633 plazas para docentes.","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/09\/OPOS-MADRID-1633-plazas-docentes.jpg","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2023\/09\/OPOS-MADRID-1633-plazas-docentes.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/comunidad-de-madrid-publicada-ope-con-1-633-plazas-docentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Comunidad de Madrid: Publicada OPE con 1.633 plazas docentes"}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/56e876ff8f12e337395ee2ae40c5fb57","name":"Campuseducacion.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g","caption":"Campuseducacion.com"},"description":"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.","sameAs":["https:\/\/www.campuseducacion.com","https:\/\/www.facebook.com\/Campuseducacion.es","https:\/\/x.com\/https:\/\/twitter.com\/Campuseducacion"],"url":"https:\/\/www.campuseducacion.com\/blog\/autores\/campuseducacion-com-4\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/26681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=26681"}],"version-history":[{"count":1,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/26681\/revisions"}],"predecessor-version":[{"id":26684,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/26681\/revisions\/26684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/26683"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=26681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=26681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=26681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}