{"id":30345,"date":"2025-10-09T12:40:48","date_gmt":"2025-10-09T10:40:48","guid":{"rendered":"https:\/\/www.campuseducacion.com\/blog\/?p=30345"},"modified":"2025-10-09T12:40:48","modified_gmt":"2025-10-09T10:40:48","slug":"extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/","title":{"rendered":"Extremadura propone m\u00e1s de 300 plazas para las Oposiciones 2026"},"content":{"rendered":"<p><strong>Extremadura<\/strong> contempla <strong>m\u00e1s de 300 plazas<\/strong> de maestros para 2026.<\/p>\n<span class='bctt-click-to-tweet'><span class='bctt-ctt-text'><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.campuseducacion.com%2Fblog%2Foposiciones%2Fcomunidades%2Fextremadura%2Fextremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026%2F&#038;text=Pueden%20convocarse%20m%C3%A1s%20de%20300%20plazas%20en%20las%20%23Oposiciones2026%20de%20%23Extremadura&#038;via=Campuseducacion&#038;related=Campuseducacion' target='_blank'rel=\"noopener noreferrer\">Pueden convocarse m\u00e1s de 300 plazas en las #Oposiciones2026 de #Extremadura <\/a><\/span><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fwww.campuseducacion.com%2Fblog%2Foposiciones%2Fcomunidades%2Fextremadura%2Fextremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026%2F&#038;text=Pueden%20convocarse%20m%C3%A1s%20de%20300%20plazas%20en%20las%20%23Oposiciones2026%20de%20%23Extremadura&#038;via=Campuseducacion&#038;related=Campuseducacion' target='_blank' class='bctt-ctt-btn'rel=\"noopener noreferrer\">Compartir en X<\/a><\/span>\n<p class=\"ft-text\">La Consejer\u00eda de Educaci\u00f3n, Ciencia y Formaci\u00f3n Profesional de Extremadura ha anunciado este semana que se propondr\u00e1 una oferta de plazas para la pr\u00f3ximas convocatoria de Oposiciones 2026.<\/p>\n<p class=\"ft-text\">Esta oferta, que tendr\u00e1n que sopesar los distintos sindicatos docentes, abarcar\u00eda <strong>m\u00e1s de 300 plazas<\/strong>, <strong>destinadas tanto al cuerpo de maestros como a sectores singulares de FP y profesores de Escuelas de Idiomas. <\/strong><\/p>\n<p class=\"ft-text\">La pr\u00f3xima semana se llevar\u00eda a cabo la mesa sectorial de personal docente, donde se negociar\u00e1 dicha propuesta.<\/p>\n<p class=\"ft-text\"><strong>Fuente<\/strong>: <a href=\"https:\/\/www.elperiodicoextremadura.com\/extremadura\/2025\/10\/06\/educacion-ofrece-300-plazas-oposiciones-122338597.html\" target=\"_blank\" rel=\"noopener\">elperi\u00f3dicodeextremadura.com<\/a><\/p>\n<p style=\"text-align: center;\">&#8212;<\/p>\n<p style=\"text-align: center;\"><strong>\u00bfNecesitas completar tu baremo de m\u00e9ritos para las pr\u00f3ximas Oposiciones?<br \/>\n<\/strong><strong>\u00a1No esperes m\u00e1s y consigue la m\u00e1xima nota!\u00a0<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>\u00a1Con los <a href=\"https:\/\/www.campuseducacion.com\/cursos-homologados\/oposiciones-extremadura\" target=\"_blank\" rel=\"noopener\">Cursos Homologados de Campuseducacion.com v\u00e1lidos para Extremadura <\/a>puedes obtener hasta 2 PUNTOS extra!<\/strong><\/p>\n<p><a href=\"https:\/\/www.campuseducacion.com\/cursos-homologados-online\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-21665 size-full\" src=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/01\/sumar-generico.png\" alt=\"Cursos sumar puntos\" width=\"688\" height=\"145\" srcset=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/01\/sumar-generico.png 688w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/01\/sumar-generico-300x63.png 300w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/01\/sumar-generico-150x32.png 150w, https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2021\/01\/sumar-generico-600x126.png 600w\" sizes=\"auto, (max-width: 688px) 100vw, 688px\" \/><\/a><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;30345&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Extremadura propone m\u00e1s de 300 plazas para las Oposiciones 2026&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            <span class=\"kksr-muted\"><\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Extremadura contempla m\u00e1s de 300 plazas de maestros para 2026. La Consejer\u00eda de Educaci\u00f3n, Ciencia y Formaci\u00f3n Profesional de Extremadura ha anunciado este semana que se propondr\u00e1 una oferta de plazas para la pr\u00f3ximas convocatoria de Oposiciones 2026. Esta oferta, que tendr\u00e1n que sopesar los distintos sindicatos docentes, abarcar\u00eda m\u00e1s de 300 plazas, destinadas tanto [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":27602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,14,1571,1743],"tags":[],"class_list":{"0":"post-30345","1":"post","2":"type-post","3":"status-publish","4":"format-image","5":"has-post-thumbnail","7":"category-general","8":"category-extremadura","9":"category-oposiciones-maestros-2026","10":"category-oposiciones-secundaria-2026","11":"post_format-post-format-image"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Extremadura propone m\u00e1s de 300 plazas para las Oposiciones 2026- Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"Extremadura contempla m\u00e1s de 300 plazas de maestros para 2026\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Extremadura propone m\u00e1s de 300 plazas para las Oposiciones 2026- Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"Extremadura contempla m\u00e1s de 300 plazas de maestros para 2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-09T10:40:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2024\/02\/Destacada-noticias-Opos-Extremadura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campuseducacion.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/extremadura\\\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/extremadura\\\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\\\/\"},\"author\":{\"name\":\"Campuseducacion.com\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/56e876ff8f12e337395ee2ae40c5fb57\"},\"headline\":\"Extremadura propone m\u00e1s de 300 plazas para las Oposiciones 2026\",\"datePublished\":\"2025-10-09T10:40:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/extremadura\\\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\\\/\"},\"wordCount\":162,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/extremadura\\\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Destacada-noticias-Opos-Extremadura.jpg\",\"articleSection\":[\"General\",\"Oposiciones Extremadura\",\"Oposiciones Maestros 2026\",\"Oposiciones Secundaria 2026\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/extremadura\\\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/extremadura\\\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\\\/\",\"name\":\"Extremadura propone m\u00e1s de 300 plazas para las Oposiciones 2026- Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/extremadura\\\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/extremadura\\\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Destacada-noticias-Opos-Extremadura.jpg\",\"datePublished\":\"2025-10-09T10:40:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/56e876ff8f12e337395ee2ae40c5fb57\"},\"description\":\"Extremadura contempla m\u00e1s de 300 plazas de maestros para 2026\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/extremadura\\\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/extremadura\\\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/extremadura\\\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Destacada-noticias-Opos-Extremadura.jpg\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Destacada-noticias-Opos-Extremadura.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/extremadura\\\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Extremadura propone m\u00e1s de 300 plazas para las Oposiciones 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/56e876ff8f12e337395ee2ae40c5fb57\",\"name\":\"Campuseducacion.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g\",\"caption\":\"Campuseducacion.com\"},\"description\":\"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.\",\"sameAs\":[\"https:\\\/\\\/www.campuseducacion.com\",\"https:\\\/\\\/www.facebook.com\\\/Campuseducacion.es\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Campuseducacion\"],\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/campuseducacion-com-4\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Extremadura propone m\u00e1s de 300 plazas para las Oposiciones 2026- Campuseducacion.com","description":"Extremadura contempla m\u00e1s de 300 plazas de maestros para 2026","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/","og_locale":"es_ES","og_type":"article","og_title":"Extremadura propone m\u00e1s de 300 plazas para las Oposiciones 2026- Campuseducacion.com","og_description":"Extremadura contempla m\u00e1s de 300 plazas de maestros para 2026","og_url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_author":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2025-10-09T10:40:48+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2024\/02\/Destacada-noticias-Opos-Extremadura.jpg","type":"image\/jpeg"}],"author":"Campuseducacion.com","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Campuseducacion.com","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/"},"author":{"name":"Campuseducacion.com","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/56e876ff8f12e337395ee2ae40c5fb57"},"headline":"Extremadura propone m\u00e1s de 300 plazas para las Oposiciones 2026","datePublished":"2025-10-09T10:40:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/"},"wordCount":162,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2024\/02\/Destacada-noticias-Opos-Extremadura.jpg","articleSection":["General","Oposiciones Extremadura","Oposiciones Maestros 2026","Oposiciones Secundaria 2026"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/","url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/","name":"Extremadura propone m\u00e1s de 300 plazas para las Oposiciones 2026- Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2024\/02\/Destacada-noticias-Opos-Extremadura.jpg","datePublished":"2025-10-09T10:40:48+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/56e876ff8f12e337395ee2ae40c5fb57"},"description":"Extremadura contempla m\u00e1s de 300 plazas de maestros para 2026","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2024\/02\/Destacada-noticias-Opos-Extremadura.jpg","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2024\/02\/Destacada-noticias-Opos-Extremadura.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/extremadura\/extremadura-propone-mas-de-300-plazas-para-las-oposiciones-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Extremadura propone m\u00e1s de 300 plazas para las Oposiciones 2026"}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/56e876ff8f12e337395ee2ae40c5fb57","name":"Campuseducacion.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e57fe3e326415535a63efb8946cbf24eaf0b356a4d75639302cd27540923f9ee?s=96&d=wavatar&r=g","caption":"Campuseducacion.com"},"description":"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.","sameAs":["https:\/\/www.campuseducacion.com","https:\/\/www.facebook.com\/Campuseducacion.es","https:\/\/x.com\/https:\/\/twitter.com\/Campuseducacion"],"url":"https:\/\/www.campuseducacion.com\/blog\/autores\/campuseducacion-com-4\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/30345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=30345"}],"version-history":[{"count":1,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/30345\/revisions"}],"predecessor-version":[{"id":30347,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/30345\/revisions\/30347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/27602"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=30345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=30345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=30345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}