{"id":3322,"date":"2013-10-01T11:52:39","date_gmt":"2013-10-01T09:52:39","guid":{"rendered":"http:\/\/www.campuseducacion.com\/oposiciones\/?p=3322"},"modified":"2017-09-15T13:17:08","modified_gmt":"2017-09-15T11:17:08","slug":"bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/","title":{"rendered":"Bolsa de trabajo en el extranjero. Plazas profesionales en Alemania, Austria, Francia, Reino Unido y Suiza."},"content":{"rendered":"<p><strong>Bolsa de trabajo en el extranjero<\/strong>: r<span style=\"font-size: small;\">esoluci\u00f3n de 2 de septiembre de 2013, de la Secretar\u00eda de Estado de Educaci\u00f3n, Formaci\u00f3n Profesional y Universidades, por la que se modifican las de 30 de abril, 30 de mayo y 21 de junio de 2013, por las que se otorgaban plazas de estancias profesionales en <strong>Alemania, Austria, Francia, Reino Unido y Suiza<\/strong>, para<strong> profesorado de lenguas extranjeras o profesorado de otras disciplinas que imparta clase en lengua extranjera<\/strong> y centros educativos que deseen acoger a un docente de uno de estos pa\u00edses para el curso 2012-2013.<!--more--><\/span><\/p>\n<p>Archivo adjunto:<\/p>\n<ul>\n<li><a href=\"http:\/\/www.anpe-albacete.com\/getfile.php?fr=documentos\/notiDOC\/BOE-A-2013-10132.pdf\">BOE.pdf<\/a><\/li>\n<\/ul>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;3322&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;36&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;4.5\\\/5 - (36 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Bolsa de trabajo en el extranjero. Plazas profesionales en Alemania, Austria, Francia, Reino Unido y Suiza.&quot;,&quot;width&quot;:&quot;87.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 87.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            4.5\/5 - (36 votos)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bolsa de trabajo en el extranjero: resoluci\u00f3n de 2 de septiembre de 2013, de la Secretar\u00eda de Estado de Educaci\u00f3n, Formaci\u00f3n Profesional y Universidades, por la que se modifican las de 30 de abril, 30 de mayo y 21 de junio de 2013, por las que se otorgaban plazas de estancias profesionales en Alemania, Austria, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[219],"tags":[],"class_list":{"0":"post-3322","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-bolsas-exterior"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bolsa de trabajo en el extranjero. Plazas profesionales en Alemania, Austria, Francia, Reino Unido y Suiza. - Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"Bolsa de trabajo en el extranjero: resoluci\u00f3n de 2 de septiembre de 2013, de la Secretar\u00eda de Estado de Educaci\u00f3n, Formaci\u00f3n Profesional y Universidades,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolsa de trabajo en el extranjero. Plazas profesionales en Alemania, Austria, Francia, Reino Unido y Suiza. - Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"Bolsa de trabajo en el extranjero: resoluci\u00f3n de 2 de septiembre de 2013, de la Secretar\u00eda de Estado de Educaci\u00f3n, Formaci\u00f3n Profesional y Universidades,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-01T09:52:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-15T11:17:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/09\/oposiciones_30.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campuseducacion.com\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-exterior\\\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-exterior\\\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\\\/\"},\"author\":{\"name\":\"Campuseducacion.com\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"headline\":\"Bolsa de trabajo en el extranjero. Plazas profesionales en Alemania, Austria, Francia, Reino Unido y Suiza.\",\"datePublished\":\"2013-10-01T09:52:39+00:00\",\"dateModified\":\"2017-09-15T11:17:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-exterior\\\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\\\/\"},\"wordCount\":113,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-exterior\\\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/oposiciones_30.jpg\",\"articleSection\":[\"Bolsas fuera de Espa\u00f1a\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-exterior\\\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-exterior\\\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-exterior\\\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\\\/\",\"name\":\"Bolsa de trabajo en el extranjero. Plazas profesionales en Alemania, Austria, Francia, Reino Unido y Suiza. - Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-exterior\\\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-exterior\\\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/oposiciones_30.jpg\",\"datePublished\":\"2013-10-01T09:52:39+00:00\",\"dateModified\":\"2017-09-15T11:17:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"description\":\"Bolsa de trabajo en el extranjero: resoluci\u00f3n de 2 de septiembre de 2013, de la Secretar\u00eda de Estado de Educaci\u00f3n, Formaci\u00f3n Profesional y Universidades,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-exterior\\\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-exterior\\\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-exterior\\\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/oposiciones_30.jpg\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/oposiciones_30.jpg\",\"width\":1024,\"height\":768,\"caption\":\"Oposiciones Maestros y Profesores. Educaci\u00f3n.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/bolsas-de-trabajo\\\/bolsas-exterior\\\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolsa de trabajo en el extranjero. Plazas profesionales en Alemania, Austria, Francia, Reino Unido y Suiza.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\",\"name\":\"Campuseducacion.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"caption\":\"Campuseducacion.com\"},\"description\":\"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.\",\"sameAs\":[\"https:\\\/\\\/www.campuseducacion.com\",\"https:\\\/\\\/www.facebook.com\\\/Campuseducacion.es\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Campuseducacion\"],\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/adminopos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolsa de trabajo en el extranjero. Plazas profesionales en Alemania, Austria, Francia, Reino Unido y Suiza. - Campuseducacion.com","description":"Bolsa de trabajo en el extranjero: resoluci\u00f3n de 2 de septiembre de 2013, de la Secretar\u00eda de Estado de Educaci\u00f3n, Formaci\u00f3n Profesional y Universidades,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/","og_locale":"es_ES","og_type":"article","og_title":"Bolsa de trabajo en el extranjero. Plazas profesionales en Alemania, Austria, Francia, Reino Unido y Suiza. - Campuseducacion.com","og_description":"Bolsa de trabajo en el extranjero: resoluci\u00f3n de 2 de septiembre de 2013, de la Secretar\u00eda de Estado de Educaci\u00f3n, Formaci\u00f3n Profesional y Universidades,","og_url":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_author":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2013-10-01T09:52:39+00:00","article_modified_time":"2017-09-15T11:17:08+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/09\/oposiciones_30.jpg","type":"image\/jpeg"}],"author":"Campuseducacion.com","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Campuseducacion.com"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/"},"author":{"name":"Campuseducacion.com","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"headline":"Bolsa de trabajo en el extranjero. Plazas profesionales en Alemania, Austria, Francia, Reino Unido y Suiza.","datePublished":"2013-10-01T09:52:39+00:00","dateModified":"2017-09-15T11:17:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/"},"wordCount":113,"commentCount":0,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/09\/oposiciones_30.jpg","articleSection":["Bolsas fuera de Espa\u00f1a"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/","url":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/","name":"Bolsa de trabajo en el extranjero. Plazas profesionales en Alemania, Austria, Francia, Reino Unido y Suiza. - Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/09\/oposiciones_30.jpg","datePublished":"2013-10-01T09:52:39+00:00","dateModified":"2017-09-15T11:17:08+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"description":"Bolsa de trabajo en el extranjero: resoluci\u00f3n de 2 de septiembre de 2013, de la Secretar\u00eda de Estado de Educaci\u00f3n, Formaci\u00f3n Profesional y Universidades,","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/09\/oposiciones_30.jpg","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/09\/oposiciones_30.jpg","width":1024,"height":768,"caption":"Oposiciones Maestros y Profesores. Educaci\u00f3n."},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/bolsas-de-trabajo\/bolsas-exterior\/bolsa-de-trabajo-en-el-extranjero-plazas-profesionales-en-alemania-austria-francia-reino-unido-y-suiza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Bolsa de trabajo en el extranjero. Plazas profesionales en Alemania, Austria, Francia, Reino Unido y Suiza."}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f","name":"Campuseducacion.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","caption":"Campuseducacion.com"},"description":"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.","sameAs":["https:\/\/www.campuseducacion.com","https:\/\/www.facebook.com\/Campuseducacion.es","https:\/\/x.com\/https:\/\/twitter.com\/Campuseducacion"],"url":"https:\/\/www.campuseducacion.com\/blog\/autores\/adminopos\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/3322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=3322"}],"version-history":[{"count":1,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/3322\/revisions"}],"predecessor-version":[{"id":3323,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/3322\/revisions\/3323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/3242"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=3322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=3322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=3322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}