{"id":3670,"date":"2013-12-04T17:52:42","date_gmt":"2013-12-04T16:52:42","guid":{"rendered":"http:\/\/www.campuseducacion.com\/oposiciones\/?p=3670"},"modified":"2017-12-13T11:20:16","modified_gmt":"2017-12-13T10:20:16","slug":"profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/","title":{"rendered":"Profesores Interinos Arag\u00f3n. Nueva baremaci\u00f3n de las listas de espera."},"content":{"rendered":"<p><strong>Profesores Interinos<\/strong> en la Comunidad de <strong>Arag\u00f3n<\/strong>: nueva baremaci\u00f3n de las listas de espera del Cuerpo de Profesores de <strong>Educaci\u00f3n Secundaria, Formaci\u00f3n Profesional y R\u00e9gimen Especial.<!--more--><\/strong><\/p>\n<p><span style=\"font-size: small;\"><a href=\"http:\/\/www.boa.aragon.es\/cgi-bin\/EBOA\/BRSCGI?CMD=VEROBJ&amp;MLKOB=764539504545\">RESOLUCI\u00d3N <\/a>de 29 de noviembre de 2013, del Director General de Gesti\u00f3n de Personal, por la que se inicia procedimiento de nueva baremaci\u00f3n de las listas de espera de aspirantes a puestos de trabajo en r\u00e9gimen de interinidad, en el \u00e1mbito de gesti\u00f3n del, Departamento de Educaci\u00f3n, Universidad, Cultura y Deporte.<\/span><\/p>\n<p><strong><span style=\"font-size: small;\">Plazo de presentaci\u00f3n de solicitudes del 4 al 23 de diciembre ambos inclusive.<\/span><\/strong><\/p>\n<div style=\"text-align: left;\"><span style=\"font-size: small;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<a href=\"http:\/\/www.aragon.es\/\">SOLICITUD<\/a><\/span><\/div>\n<p><span style=\"font-size: small;\">\u00a0<\/span><\/p>\n<p><span style=\"font-size: small;\">Documentos:<\/span><\/p>\n<ul>\n<li><span style=\"font-size: small;\"><a href=\"http:\/\/www.educaragon.org\/\" target=\"_blank\" rel=\"noopener\">Especialidades convocatoria 2013-2014<br \/>\n<\/a><\/span><\/li>\n<li><span style=\"font-size: small;\"><a href=\"http:\/\/www.educaragon.org\/\" target=\"_blank\" rel=\"noopener\">Listado alfab\u00e9tico de convocados al proceso de baremaci\u00f3n<br \/>\n<\/a><\/span><\/li>\n<li><span style=\"font-size: small;\"><a href=\"http:\/\/www.educaragon.org\/\" target=\"_blank\" rel=\"noopener\">Ayuda para cumplimentar la solicitud<\/a><\/span><\/li>\n<\/ul>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;3670&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;59&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;5\\\/5 - (59 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Profesores Interinos Arag\u00f3n. Nueva baremaci\u00f3n de las listas de espera.&quot;,&quot;width&quot;:&quot;97.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 97.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            5\/5 - (59 votos)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Profesores Interinos en la Comunidad de Arag\u00f3n: nueva baremaci\u00f3n de las listas de espera del Cuerpo de Profesores de Educaci\u00f3n Secundaria, Formaci\u00f3n Profesional y R\u00e9gimen Especial.<\/p>\n","protected":false},"author":2,"featured_media":783,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[201,1,12],"tags":[28,29,313],"class_list":{"0":"post-3670","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-bolsas-aragon","8":"category-general","9":"category-aragon","10":"tag-formacion-profesional","11":"tag-profesores","12":"tag-regimen-especial"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Profesores Interinos Arag\u00f3n. Nueva baremaci\u00f3n de las listas de espera. - Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"Profesores Interinos en la Comunidad de Arag\u00f3n: nueva baremaci\u00f3n de las listas de espera del Cuerpo de Profesores de Educaci\u00f3n Secundaria, Formaci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Profesores Interinos Arag\u00f3n. Nueva baremaci\u00f3n de las listas de espera. - Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"Profesores Interinos en la Comunidad de Arag\u00f3n: nueva baremaci\u00f3n de las listas de espera del Cuerpo de Profesores de Educaci\u00f3n Secundaria, Formaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-04T16:52:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-13T10:20:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/aragon.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campuseducacion.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/general\\\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/general\\\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\\\/\"},\"author\":{\"name\":\"Campuseducacion.com\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"headline\":\"Profesores Interinos Arag\u00f3n. Nueva baremaci\u00f3n de las listas de espera.\",\"datePublished\":\"2013-12-04T16:52:42+00:00\",\"dateModified\":\"2017-12-13T10:20:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/general\\\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\\\/\"},\"wordCount\":130,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/general\\\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/aragon.gif\",\"keywords\":[\"formaci\u00f3n profesional\",\"profesores\",\"r\u00e9gimen especial\"],\"articleSection\":[\"Bolsas Arag\u00f3n\",\"General\",\"Oposiciones Arag\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/general\\\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/general\\\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/general\\\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\\\/\",\"name\":\"Profesores Interinos Arag\u00f3n. Nueva baremaci\u00f3n de las listas de espera. - Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/general\\\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/general\\\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/aragon.gif\",\"datePublished\":\"2013-12-04T16:52:42+00:00\",\"dateModified\":\"2017-12-13T10:20:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"description\":\"Profesores Interinos en la Comunidad de Arag\u00f3n: nueva baremaci\u00f3n de las listas de espera del Cuerpo de Profesores de Educaci\u00f3n Secundaria, Formaci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/general\\\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/general\\\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/general\\\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/aragon.gif\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/aragon.gif\",\"width\":620,\"height\":330,\"caption\":\"Noticia sobre educaci\u00f3n y oposiciones para profesores y maestros en Arag\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/general\\\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Profesores Interinos Arag\u00f3n. Nueva baremaci\u00f3n de las listas de espera.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\",\"name\":\"Campuseducacion.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"caption\":\"Campuseducacion.com\"},\"description\":\"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.\",\"sameAs\":[\"https:\\\/\\\/www.campuseducacion.com\",\"https:\\\/\\\/www.facebook.com\\\/Campuseducacion.es\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Campuseducacion\"],\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/adminopos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Profesores Interinos Arag\u00f3n. Nueva baremaci\u00f3n de las listas de espera. - Campuseducacion.com","description":"Profesores Interinos en la Comunidad de Arag\u00f3n: nueva baremaci\u00f3n de las listas de espera del Cuerpo de Profesores de Educaci\u00f3n Secundaria, Formaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/","og_locale":"es_ES","og_type":"article","og_title":"Profesores Interinos Arag\u00f3n. Nueva baremaci\u00f3n de las listas de espera. - Campuseducacion.com","og_description":"Profesores Interinos en la Comunidad de Arag\u00f3n: nueva baremaci\u00f3n de las listas de espera del Cuerpo de Profesores de Educaci\u00f3n Secundaria, Formaci\u00f3n","og_url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_author":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2013-12-04T16:52:42+00:00","article_modified_time":"2017-12-13T10:20:16+00:00","og_image":[{"width":620,"height":330,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/aragon.gif","type":"image\/gif"}],"author":"Campuseducacion.com","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Campuseducacion.com","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/"},"author":{"name":"Campuseducacion.com","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"headline":"Profesores Interinos Arag\u00f3n. Nueva baremaci\u00f3n de las listas de espera.","datePublished":"2013-12-04T16:52:42+00:00","dateModified":"2017-12-13T10:20:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/"},"wordCount":130,"commentCount":0,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/aragon.gif","keywords":["formaci\u00f3n profesional","profesores","r\u00e9gimen especial"],"articleSection":["Bolsas Arag\u00f3n","General","Oposiciones Arag\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/","url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/","name":"Profesores Interinos Arag\u00f3n. Nueva baremaci\u00f3n de las listas de espera. - Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/aragon.gif","datePublished":"2013-12-04T16:52:42+00:00","dateModified":"2017-12-13T10:20:16+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"description":"Profesores Interinos en la Comunidad de Arag\u00f3n: nueva baremaci\u00f3n de las listas de espera del Cuerpo de Profesores de Educaci\u00f3n Secundaria, Formaci\u00f3n","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/aragon.gif","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/aragon.gif","width":620,"height":330,"caption":"Noticia sobre educaci\u00f3n y oposiciones para profesores y maestros en Arag\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/general\/profesores-interinos-aragon-nueva-baremacion-de-las-listas-de-espera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Profesores Interinos Arag\u00f3n. Nueva baremaci\u00f3n de las listas de espera."}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f","name":"Campuseducacion.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","caption":"Campuseducacion.com"},"description":"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.","sameAs":["https:\/\/www.campuseducacion.com","https:\/\/www.facebook.com\/Campuseducacion.es","https:\/\/x.com\/https:\/\/twitter.com\/Campuseducacion"],"url":"https:\/\/www.campuseducacion.com\/blog\/autores\/adminopos\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/3670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=3670"}],"version-history":[{"count":3,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/3670\/revisions"}],"predecessor-version":[{"id":12977,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/3670\/revisions\/12977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/783"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=3670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=3670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=3670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}