{"id":669,"date":"2012-05-13T19:07:20","date_gmt":"2012-05-13T17:07:20","guid":{"rendered":"http:\/\/www.campuseducacion.com\/oposiciones\/?p=669"},"modified":"2013-08-21T10:37:08","modified_gmt":"2013-08-21T08:37:08","slug":"temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/","title":{"rendered":"Temario de Oposiciones del Cuerpo de Profesores de EOI: Euskera"},"content":{"rendered":"<h2><span style=\"font-size: medium;\">Temario de Oposiciones del Cuerpo de Profesores de Escuelas Oficiales de Idiomas: EUSKERA.<\/span><!--more--><\/h2>\n<div dir=\"ltr\" data-canvas-width=\"289.9884\" data-font-name=\"g_font_p0_3\"><a title=\"Temario oposiciones EOI: euskera\" href=\"http:\/\/www.anpe.es\/wp-content\/2012\/temas\/Euskera.pdf\">ORDEN ECD\/477\/2003, de 5 de marzo, por la que se modifican parcialmente la Orden de 9 de septiembre de 1993, la Orden de 20 de abril de 1994, la Orden de 1 de febrero de 1996 y la Orden ECD\/310\/2002, de 15 de febrero, por las que se aprueban los temarios que han de regir en los procedimientos de ingreso a los Cuerpos de Maestros, Profesores de Ense\u00f1anza Secundaria, Profesores T\u00e9cnicos de Formaci\u00f3n Profesional, Profesores de Escuelas Oficiales de Idiomas, Profesores de M\u00fasica y Artes Esc\u00e9nicas, Profesores de Artes Pl\u00e1sticas y Dise\u00f1o y Maestros de Taller de Artes Pl\u00e1sticas y Dise\u00f1o, regulados por el Real Decreto 850\/1993, de 4 de junio.<\/a><\/div>\n<div dir=\"ltr\" data-canvas-width=\"289.9884\" data-font-name=\"g_font_p0_3\"><\/div>\n<div dir=\"ltr\" data-canvas-width=\"289.9884\" data-font-name=\"g_font_p0_3\">(BOE 56 de 06\/03\/2003)<\/div>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;669&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;19&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;3.7&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;3.7\\\/5 - (19 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Temario de Oposiciones del Cuerpo de Profesores de EOI: Euskera&quot;,&quot;width&quot;:&quot;71.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 71.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            3.7\/5 - (19 votos)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Temario de Oposiciones del Cuerpo de Profesores de Escuelas Oficiales de Idiomas: EUSKERA.<\/p>\n","protected":false},"author":2,"featured_media":322,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[60],"tags":[179,29],"class_list":{"0":"post-669","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-temarios-otros-cuerpos","8":"tag-escuela-oficial-de-idiomas","9":"tag-profesores"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Temario de Oposiciones del Cuerpo de Profesores de EOI: Euskera - Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"Temario de Oposiciones del Cuerpo de Profesores de Escuelas Oficiales de Idiomas: EUSKERA. ORDEN ECD\/477\/2003, de 5 de marzo, por la que se modifican\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Temario de Oposiciones del Cuerpo de Profesores de EOI: Euskera - Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"Temario de Oposiciones del Cuerpo de Profesores de Escuelas Oficiales de Idiomas: EUSKERA. ORDEN ECD\/477\/2003, de 5 de marzo, por la que se modifican\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-13T17:07:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-08-21T08:37:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/Temarios.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campuseducacion.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/temarios\\\/temarios-otros-cuerpos\\\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/temarios\\\/temarios-otros-cuerpos\\\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\\\/\"},\"author\":{\"name\":\"Campuseducacion.com\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"headline\":\"Temario de Oposiciones del Cuerpo de Profesores de EOI: Euskera\",\"datePublished\":\"2012-05-13T17:07:20+00:00\",\"dateModified\":\"2013-08-21T08:37:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/temarios\\\/temarios-otros-cuerpos\\\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\\\/\"},\"wordCount\":135,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/temarios\\\/temarios-otros-cuerpos\\\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/Temarios.jpg\",\"keywords\":[\"escuela oficial de idiomas\",\"profesores\"],\"articleSection\":[\"Temarios Otros Cuerpos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/temarios\\\/temarios-otros-cuerpos\\\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/temarios\\\/temarios-otros-cuerpos\\\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/temarios\\\/temarios-otros-cuerpos\\\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\\\/\",\"name\":\"Temario de Oposiciones del Cuerpo de Profesores de EOI: Euskera - Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/temarios\\\/temarios-otros-cuerpos\\\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/temarios\\\/temarios-otros-cuerpos\\\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/Temarios.jpg\",\"datePublished\":\"2012-05-13T17:07:20+00:00\",\"dateModified\":\"2013-08-21T08:37:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"description\":\"Temario de Oposiciones del Cuerpo de Profesores de Escuelas Oficiales de Idiomas: EUSKERA. ORDEN ECD\\\/477\\\/2003, de 5 de marzo, por la que se modifican\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/temarios\\\/temarios-otros-cuerpos\\\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/temarios\\\/temarios-otros-cuerpos\\\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/temarios\\\/temarios-otros-cuerpos\\\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/Temarios.jpg\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/Temarios.jpg\",\"width\":620,\"height\":330,\"caption\":\"temarios oposiciones de maestros y profesores\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/temarios\\\/temarios-otros-cuerpos\\\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Temario de Oposiciones del Cuerpo de Profesores de EOI: Euskera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\",\"name\":\"Campuseducacion.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"caption\":\"Campuseducacion.com\"},\"description\":\"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.\",\"sameAs\":[\"https:\\\/\\\/www.campuseducacion.com\",\"https:\\\/\\\/www.facebook.com\\\/Campuseducacion.es\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Campuseducacion\"],\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/adminopos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Temario de Oposiciones del Cuerpo de Profesores de EOI: Euskera - Campuseducacion.com","description":"Temario de Oposiciones del Cuerpo de Profesores de Escuelas Oficiales de Idiomas: EUSKERA. ORDEN ECD\/477\/2003, de 5 de marzo, por la que se modifican","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/","og_locale":"es_ES","og_type":"article","og_title":"Temario de Oposiciones del Cuerpo de Profesores de EOI: Euskera - Campuseducacion.com","og_description":"Temario de Oposiciones del Cuerpo de Profesores de Escuelas Oficiales de Idiomas: EUSKERA. ORDEN ECD\/477\/2003, de 5 de marzo, por la que se modifican","og_url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_author":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2012-05-13T17:07:20+00:00","article_modified_time":"2013-08-21T08:37:08+00:00","og_image":[{"width":620,"height":330,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/Temarios.jpg","type":"image\/jpeg"}],"author":"Campuseducacion.com","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Campuseducacion.com","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/"},"author":{"name":"Campuseducacion.com","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"headline":"Temario de Oposiciones del Cuerpo de Profesores de EOI: Euskera","datePublished":"2012-05-13T17:07:20+00:00","dateModified":"2013-08-21T08:37:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/"},"wordCount":135,"commentCount":0,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/Temarios.jpg","keywords":["escuela oficial de idiomas","profesores"],"articleSection":["Temarios Otros Cuerpos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/","url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/","name":"Temario de Oposiciones del Cuerpo de Profesores de EOI: Euskera - Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/Temarios.jpg","datePublished":"2012-05-13T17:07:20+00:00","dateModified":"2013-08-21T08:37:08+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"description":"Temario de Oposiciones del Cuerpo de Profesores de Escuelas Oficiales de Idiomas: EUSKERA. ORDEN ECD\/477\/2003, de 5 de marzo, por la que se modifican","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/Temarios.jpg","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/Temarios.jpg","width":620,"height":330,"caption":"temarios oposiciones de maestros y profesores"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/temarios\/temarios-otros-cuerpos\/temario-de-oposiciones-del-cuerpo-de-profesores-de-eoi-euskera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Temario de Oposiciones del Cuerpo de Profesores de EOI: Euskera"}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f","name":"Campuseducacion.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","caption":"Campuseducacion.com"},"description":"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.","sameAs":["https:\/\/www.campuseducacion.com","https:\/\/www.facebook.com\/Campuseducacion.es","https:\/\/x.com\/https:\/\/twitter.com\/Campuseducacion"],"url":"https:\/\/www.campuseducacion.com\/blog\/autores\/adminopos\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=669"}],"version-history":[{"count":2,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/669\/revisions"}],"predecessor-version":[{"id":2952,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/669\/revisions\/2952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/322"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}