{"id":7284,"date":"2016-06-09T10:28:54","date_gmt":"2016-06-09T08:28:54","guid":{"rendered":"http:\/\/www.campuseducacion.com\/blog\/?p=7284"},"modified":"2017-09-15T09:20:04","modified_gmt":"2017-09-15T07:20:04","slug":"oposiciones-2016-andalucia-criterios-actuacion-tribunales","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/","title":{"rendered":"Oposiciones 2016 Andaluc\u00eda: criterios de actuaci\u00f3n de los tribunales"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Criterios de actuaci\u00f3n de los tribunales<\/strong> que juzgar\u00e1n el proceso selectivo a los cuerpos de Profesores de Ense\u00f1anzas Medias en la Comunidad Aut\u00f3noma de Andaluc\u00eda.<!--more--><\/p>\n<div id=\"p_p_id_ABACO_WEB_WAR_abacoportlet_INSTANCE_5GI6BhBq0QqH_\" class=\"portlet-boundary portlet-boundary_ABACO_WEB_WAR_abacoportlet_ portlet-static portlet-static-end \">\n<section id=\"portlet_ABACO_WEB_WAR_abacoportlet_INSTANCE_5GI6BhBq0QqH\" class=\"portlet\">\n<header class=\"portlet-topper\">\n<p class=\"portlet-title\" style=\"text-align: justify;\">Los tribunales en la sesi\u00f3n de constituci\u00f3n tomar\u00e1n las decisiones oportunas para el correcto desarrollo del procedimiento selectivo, todo ello con sujeci\u00f3n a lo previsto en esta convocatoria y a los criterios de actuaci\u00f3n que marquen las respectivas comisiones de selecci\u00f3n.<\/p>\n<\/header>\n<div class=\"portlet-content\">\n<div class=\" portlet-content-container\">\n<div class=\"portlet-body\">\n<div class=\"contenido_portlet \">\n<div class=\"portlet_web\">\n<div class=\"detalle web detalle-web-img-float\">\n<div class=\"contenido_detalle\">\n<section class=\"cuerpo detalle_html\">\n<div class=\"inner_cuerpo\">\n<p class=\"caps\" style=\"text-align: justify;\">Corresponde a los tribunales:<\/p>\n<p style=\"text-align: justify;\"><strong>a)<\/strong> El desarrollo del procedimiento selectivo de acuerdo con lo dispuesto en la presente Orden, impartir las instrucciones para el desarrollo del mismo y aclarar las dudas que se puedan plantear.<br \/>\n<strong>b)<\/strong> La calificaci\u00f3n de las distintas partes de las pruebas de la fase de oposici\u00f3n.<br \/>\n<strong>c)<\/strong> La conformaci\u00f3n del expediente administrativo mediante la cumplimentaci\u00f3n de los modelos que se faciliten por la Direcci\u00f3n General del Profesorado y Gesti\u00f3n de Recursos Humanos.<br \/>\n<strong>d)<\/strong> Mantener actualizados los datos relativos al procedimiento selectivo, a efectos de su divulgaci\u00f3n en el portal web de la Consejer\u00eda de\u00a0 Educaci\u00f3n, mediante el uso de las aplicaciones inform\u00e1ticas que se pongan a su disposici\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><strong>Ficheros:<\/strong><\/p>\n<div class=\"portlet-content\">\n<div class=\" portlet-content-container\">\n<div class=\"portlet-body\">\n<div class=\"contenido_portlet \">\n<div class=\"portlet_documentos\">\n<div class=\"document-list\">\n<div class=\"documentos\">\n<ul class=\"listado\">\n<li class=\"item\">\n<p class=\"title icopdf\"><strong><a title=\"Pulse para visualizar el documento\" href=\"http:\/\/www.juntadeandalucia.es\/educacion\/portals\/abaco-portlet\/content\/adcbd308-b275-4269-8902-b9c9d37231d7?a=true\" target=\"_blank\" rel=\"nofollow noopener\">Indicadores de evaluaci\u00f3n<\/a><\/strong><\/p>\n<\/li>\n<li class=\"item\">\n<p class=\"title icopdf\"><strong><a title=\"Pulse para visualizar el documento\" href=\"http:\/\/www.juntadeandalucia.es\/educacion\/portals\/abaco-portlet\/content\/12011256-152c-44b7-aeab-9f0b25d77d37?a=true\" target=\"_blank\" rel=\"nofollow noopener\">Invalidaciones y penalizaciones<\/a><\/strong><\/p>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;7284&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;52&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.7&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;4.7\\\/5 - (52 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Oposiciones 2016 Andaluc\u00eda: criterios de actuaci\u00f3n de los tribunales&quot;,&quot;width&quot;:&quot;91.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 91.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            4.7\/5 - (52 votos)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Criterios de actuaci\u00f3n de los tribunales que juzgar\u00e1n el proceso selectivo a los cuerpos de Profesores de Ense\u00f1anzas Medias en la Comunidad Aut\u00f3noma de Andaluc\u00eda.<\/p>\n","protected":false},"author":2,"featured_media":6220,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3,716],"tags":[1061,190],"class_list":{"0":"post-7284","1":"post","2":"type-post","3":"status-publish","4":"format-image","5":"has-post-thumbnail","7":"category-andalucia","8":"category-oposiciones-secundaria-2016","9":"tag-criterios-de-correccion","10":"tag-tribunales","11":"post_format-post-format-image"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oposiciones 2016 Andaluc\u00eda: criterios de actuaci\u00f3n de los tribunales - Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"Criterios de actuaci\u00f3n de los tribunales que juzgar\u00e1n el proceso selectivo a los cuerpos de Profesores de Ense\u00f1anzas Medias en la Comunidad Aut\u00f3noma de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oposiciones 2016 Andaluc\u00eda: criterios de actuaci\u00f3n de los tribunales - Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"Criterios de actuaci\u00f3n de los tribunales que juzgar\u00e1n el proceso selectivo a los cuerpos de Profesores de Ense\u00f1anzas Medias en la Comunidad Aut\u00f3noma de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-09T08:28:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-15T07:20:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/andalucia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campuseducacion.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/andalucia\\\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/andalucia\\\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\\\/\"},\"author\":{\"name\":\"Campuseducacion.com\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"headline\":\"Oposiciones 2016 Andaluc\u00eda: criterios de actuaci\u00f3n de los tribunales\",\"datePublished\":\"2016-06-09T08:28:54+00:00\",\"dateModified\":\"2017-09-15T07:20:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/andalucia\\\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\\\/\"},\"wordCount\":219,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/andalucia\\\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/andalucia.jpg\",\"keywords\":[\"criterios de correcci\u00f3n\",\"tribunales\"],\"articleSection\":[\"Oposiciones Andaluc\u00eda\",\"Oposiciones Secundaria 2016\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/andalucia\\\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/andalucia\\\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/andalucia\\\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\\\/\",\"name\":\"Oposiciones 2016 Andaluc\u00eda: criterios de actuaci\u00f3n de los tribunales - Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/andalucia\\\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/andalucia\\\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/andalucia.jpg\",\"datePublished\":\"2016-06-09T08:28:54+00:00\",\"dateModified\":\"2017-09-15T07:20:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"description\":\"Criterios de actuaci\u00f3n de los tribunales que juzgar\u00e1n el proceso selectivo a los cuerpos de Profesores de Ense\u00f1anzas Medias en la Comunidad Aut\u00f3noma de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/andalucia\\\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/andalucia\\\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/andalucia\\\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/andalucia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/andalucia.jpg\",\"width\":1200,\"height\":627,\"caption\":\"bandera Andaluc\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/andalucia\\\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oposiciones 2016 Andaluc\u00eda: criterios de actuaci\u00f3n de los tribunales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\",\"name\":\"Campuseducacion.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"caption\":\"Campuseducacion.com\"},\"description\":\"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.\",\"sameAs\":[\"https:\\\/\\\/www.campuseducacion.com\",\"https:\\\/\\\/www.facebook.com\\\/Campuseducacion.es\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Campuseducacion\"],\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/adminopos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oposiciones 2016 Andaluc\u00eda: criterios de actuaci\u00f3n de los tribunales - Campuseducacion.com","description":"Criterios de actuaci\u00f3n de los tribunales que juzgar\u00e1n el proceso selectivo a los cuerpos de Profesores de Ense\u00f1anzas Medias en la Comunidad Aut\u00f3noma de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/","og_locale":"es_ES","og_type":"article","og_title":"Oposiciones 2016 Andaluc\u00eda: criterios de actuaci\u00f3n de los tribunales - Campuseducacion.com","og_description":"Criterios de actuaci\u00f3n de los tribunales que juzgar\u00e1n el proceso selectivo a los cuerpos de Profesores de Ense\u00f1anzas Medias en la Comunidad Aut\u00f3noma de","og_url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_author":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2016-06-09T08:28:54+00:00","article_modified_time":"2017-09-15T07:20:04+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/andalucia.jpg","type":"image\/jpeg"}],"author":"Campuseducacion.com","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Campuseducacion.com","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/"},"author":{"name":"Campuseducacion.com","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"headline":"Oposiciones 2016 Andaluc\u00eda: criterios de actuaci\u00f3n de los tribunales","datePublished":"2016-06-09T08:28:54+00:00","dateModified":"2017-09-15T07:20:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/"},"wordCount":219,"commentCount":0,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/andalucia.jpg","keywords":["criterios de correcci\u00f3n","tribunales"],"articleSection":["Oposiciones Andaluc\u00eda","Oposiciones Secundaria 2016"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/","url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/","name":"Oposiciones 2016 Andaluc\u00eda: criterios de actuaci\u00f3n de los tribunales - Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/andalucia.jpg","datePublished":"2016-06-09T08:28:54+00:00","dateModified":"2017-09-15T07:20:04+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"description":"Criterios de actuaci\u00f3n de los tribunales que juzgar\u00e1n el proceso selectivo a los cuerpos de Profesores de Ense\u00f1anzas Medias en la Comunidad Aut\u00f3noma de","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/andalucia.jpg","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/andalucia.jpg","width":1200,"height":627,"caption":"bandera Andaluc\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/andalucia\/oposiciones-2016-andalucia-criterios-actuacion-tribunales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Oposiciones 2016 Andaluc\u00eda: criterios de actuaci\u00f3n de los tribunales"}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f","name":"Campuseducacion.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","caption":"Campuseducacion.com"},"description":"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.","sameAs":["https:\/\/www.campuseducacion.com","https:\/\/www.facebook.com\/Campuseducacion.es","https:\/\/x.com\/https:\/\/twitter.com\/Campuseducacion"],"url":"https:\/\/www.campuseducacion.com\/blog\/autores\/adminopos\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/7284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=7284"}],"version-history":[{"count":2,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/7284\/revisions"}],"predecessor-version":[{"id":11507,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/7284\/revisions\/11507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/6220"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=7284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=7284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=7284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}