{"id":7451,"date":"2016-07-15T08:58:51","date_gmt":"2016-07-15T06:58:51","guid":{"rendered":"http:\/\/www.campuseducacion.com\/blog\/?p=7451"},"modified":"2018-12-20T20:14:07","modified_gmt":"2018-12-20T19:14:07","slug":"oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/","title":{"rendered":"Oposiciones 2016 Castilla y Le\u00f3n: calificaciones 2\u00aa prueba"},"content":{"rendered":"<p><strong>Listados<\/strong> de los tribunales <strong>con las calificaciones correspondientes a la segunda prueba<\/strong> del proceso selectivo del cuerpo de Maestros 2016.<!--more--><\/p>\n<p><strong>Los listados deben consultarse a trav\u00e9s del portal de Educaci\u00f3n de la Junta de Castilla y Le\u00f3n.<\/strong><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;7451&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;62&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;4.5\\\/5 - (62 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Oposiciones 2016 Castilla y Le\u00f3n: calificaciones 2\u00aa prueba&quot;,&quot;width&quot;:&quot;87.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 87.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            4.5\/5 - (62 votos)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Listados de los tribunales con las calificaciones correspondientes a la segunda prueba del proceso selectivo del cuerpo de Maestros 2016.<\/p>\n","protected":false},"author":2,"featured_media":6229,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"imagen","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[47,8,715],"tags":[812],"class_list":{"0":"post-7451","1":"post","2":"type-post","3":"status-publish","4":"format-imagen","5":"has-post-thumbnail","7":"category-oposiciones","8":"category-castilla-y-leon","9":"category-oposiciones-maestros-2016","10":"tag-aspirantes-seleccionados","11":"post_format-imagen"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oposiciones 2016 Castilla y Le\u00f3n: calificaciones 2\u00aa prueba - Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"Listados de los tribunales con las calificaciones correspondientes a la segunda prueba del proceso selectivo del cuerpo de Maestros 2016. Los listados\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oposiciones 2016 Castilla y Le\u00f3n: calificaciones 2\u00aa prueba - Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"Listados de los tribunales con las calificaciones correspondientes a la segunda prueba del proceso selectivo del cuerpo de Maestros 2016. Los listados\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-15T06:58:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-20T19:14:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/cyleon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campuseducacion.com\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-y-leon\\\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-y-leon\\\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\\\/\"},\"author\":{\"name\":\"Campuseducacion.com\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"headline\":\"Oposiciones 2016 Castilla y Le\u00f3n: calificaciones 2\u00aa prueba\",\"datePublished\":\"2016-07-15T06:58:51+00:00\",\"dateModified\":\"2018-12-20T19:14:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-y-leon\\\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\\\/\"},\"wordCount\":46,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-y-leon\\\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/cyleon.jpg\",\"keywords\":[\"aspirantes seleccionados\"],\"articleSection\":[\"Noticias OPOSICIONES de Maestros y Profesores\",\"Oposiciones Castilla y Le\u00f3n\",\"Oposiciones Maestros 2016\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-y-leon\\\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-y-leon\\\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-y-leon\\\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\\\/\",\"name\":\"Oposiciones 2016 Castilla y Le\u00f3n: calificaciones 2\u00aa prueba - Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-y-leon\\\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-y-leon\\\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/cyleon.jpg\",\"datePublished\":\"2016-07-15T06:58:51+00:00\",\"dateModified\":\"2018-12-20T19:14:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"description\":\"Listados de los tribunales con las calificaciones correspondientes a la segunda prueba del proceso selectivo del cuerpo de Maestros 2016. Los listados\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-y-leon\\\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-y-leon\\\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-y-leon\\\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/cyleon.jpg\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/cyleon.jpg\",\"width\":1200,\"height\":627,\"caption\":\"bandera castilla y le\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/castilla-y-leon\\\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oposiciones 2016 Castilla y Le\u00f3n: calificaciones 2\u00aa prueba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\",\"name\":\"Campuseducacion.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"caption\":\"Campuseducacion.com\"},\"description\":\"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.\",\"sameAs\":[\"https:\\\/\\\/www.campuseducacion.com\",\"https:\\\/\\\/www.facebook.com\\\/Campuseducacion.es\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Campuseducacion\"],\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/adminopos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oposiciones 2016 Castilla y Le\u00f3n: calificaciones 2\u00aa prueba - Campuseducacion.com","description":"Listados de los tribunales con las calificaciones correspondientes a la segunda prueba del proceso selectivo del cuerpo de Maestros 2016. Los listados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/","og_locale":"es_ES","og_type":"article","og_title":"Oposiciones 2016 Castilla y Le\u00f3n: calificaciones 2\u00aa prueba - Campuseducacion.com","og_description":"Listados de los tribunales con las calificaciones correspondientes a la segunda prueba del proceso selectivo del cuerpo de Maestros 2016. Los listados","og_url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_author":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2016-07-15T06:58:51+00:00","article_modified_time":"2018-12-20T19:14:07+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/cyleon.jpg","type":"image\/jpeg"}],"author":"Campuseducacion.com","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Campuseducacion.com"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/"},"author":{"name":"Campuseducacion.com","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"headline":"Oposiciones 2016 Castilla y Le\u00f3n: calificaciones 2\u00aa prueba","datePublished":"2016-07-15T06:58:51+00:00","dateModified":"2018-12-20T19:14:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/"},"wordCount":46,"commentCount":0,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/cyleon.jpg","keywords":["aspirantes seleccionados"],"articleSection":["Noticias OPOSICIONES de Maestros y Profesores","Oposiciones Castilla y Le\u00f3n","Oposiciones Maestros 2016"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/","url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/","name":"Oposiciones 2016 Castilla y Le\u00f3n: calificaciones 2\u00aa prueba - Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/cyleon.jpg","datePublished":"2016-07-15T06:58:51+00:00","dateModified":"2018-12-20T19:14:07+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"description":"Listados de los tribunales con las calificaciones correspondientes a la segunda prueba del proceso selectivo del cuerpo de Maestros 2016. Los listados","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/cyleon.jpg","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/cyleon.jpg","width":1200,"height":627,"caption":"bandera castilla y le\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/castilla-y-leon\/oposiciones-2016-castilla-y-leon-calificaciones-2a-prueba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Oposiciones 2016 Castilla y Le\u00f3n: calificaciones 2\u00aa prueba"}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f","name":"Campuseducacion.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","caption":"Campuseducacion.com"},"description":"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.","sameAs":["https:\/\/www.campuseducacion.com","https:\/\/www.facebook.com\/Campuseducacion.es","https:\/\/x.com\/https:\/\/twitter.com\/Campuseducacion"],"url":"https:\/\/www.campuseducacion.com\/blog\/autores\/adminopos\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/7451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=7451"}],"version-history":[{"count":4,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/7451\/revisions"}],"predecessor-version":[{"id":11653,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/7451\/revisions\/11653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/6229"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=7451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=7451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=7451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}