{"id":7737,"date":"2016-09-28T17:05:50","date_gmt":"2016-09-28T15:05:50","guid":{"rendered":"http:\/\/www.campuseducacion.com\/blog\/?p=7737"},"modified":"2017-04-24T11:34:51","modified_gmt":"2017-04-24T09:34:51","slug":"interinos-madrid-bolsa-trabajo-cuerpo-profesores","status":"publish","type":"post","link":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/","title":{"rendered":"Interinos Madrid: bolsa de trabajo para el cuerpo de Profesores"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Convocatoria extraordinaria para la selecci\u00f3n de aspirantes a ocupar puestos en r\u00e9gimen de interinidad<\/strong> en varias especialidades de los cuerpos de Profesores de Ense\u00f1anza Secundaria, FP, EOI y Maestros de Taller de Artes Pl\u00e1sticas y Dise\u00f1o en la Comunidad de Madrid.<!--more--><\/p>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/www.bocm.es\/boletin\/CM_Orden_BOCM\/2016\/09\/27\/BOCM-20160927-9.PDF\" target=\"_blank\" rel=\"noopener noreferrer\">CONVOCATORIA SECUNDARIA<\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/www.bocm.es\/boletin\/CM_Orden_BOCM\/2016\/09\/27\/BOCM-20160927-10.PDF\" target=\"_blank\" rel=\"noopener noreferrer\">CONVOCATORIA OTROS CUERPOS<\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Plazo de presentaci\u00f3n de\u00a0solicitudes: del 28 de septiembre al\u00a0\u00a07 de octubre de 2016, ambos inclusive.<\/strong><\/p>\n<table border=\"1\" cellspacing=\"1\" cellpadding=\"2\" align=\"center\">\n<tbody>\n<tr>\n<td width=\"80%\">Acceso a la ficha de Servicios y Tr\u00e1mites (Secundaria)<\/td>\n<td class=\"parrafoCentro\"><a href=\"http:\/\/www.madrid.org\/cs\/Satellite?c=CM_ConvocaPrestac_FA&amp;cid=1354613264234&amp;definicion=Ofertas+Empleo+Publico&amp;idConsejeria=1109266187254&amp;idListConsj=1109265444710&amp;idOrganismo=1109167995708&amp;language=es&amp;pagename=ComunidadMadrid%2FEstructura&amp;sm=1109266100986&amp;tipoServicio=CM_ConvocaPrestac_FA\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Enlace<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table border=\"1\" cellspacing=\"1\" cellpadding=\"2\" align=\"center\">\n<tbody>\n<tr>\n<td width=\"80%\">Acceso a la ficha de servicios y Tr\u00e1mites (Otros Cuerpos)<\/td>\n<td class=\"parrafoCentro\"><a href=\"http:\/\/www.madrid.org\/cs\/Satellite?c=CM_ConvocaPrestac_FA&amp;cid=1354613273558&amp;definicion=Ofertas+Empleo+Publico&amp;idConsejeria=1109266187254&amp;idListConsj=1109265444710&amp;idOrganismo=1109167995708&amp;language=es&amp;pagename=ComunidadMadrid%2FEstructura&amp;sm=1109266100986&amp;tipoServicio=CM_ConvocaPrestac_FA\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Enlace<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>0590 \u2013 CUERPO DE PROFESORES DE ENSE\u00d1ANZA SECUNDARIA<\/p>\n<ul>\n<li>010 \u2013 FRANC\u00c9S 061 \u2013 ECONOM\u00cdA<\/li>\n<li>103 \u2013 ASESOR\u00cdA Y PROCESOS DE IMAGEN PERSONAL<\/li>\n<li>124 \u2013 SISTEMAS ELECTR\u00d3NICOS<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>0590 \u2013 CUERPO DE PROFESORES DE ENSE\u00d1ANZA SECUNDARIA ESPECIALIDADES BILING\u00dcES<\/p>\n<ul>\n<li>821 \u2013 GEOGRAF\u00cdA E HISTORIA-ALEM\u00c1N<\/li>\n<li>824 \u2013 BIOLOG\u00cdA Y GEOLOG\u00cdA-ALEM\u00c1N<\/li>\n<li>825 \u2013 F\u00cdSICA Y QU\u00cdMICA-FRANC\u00c9S<\/li>\n<li>827 \u2013 F\u00cdSICA Y QU\u00cdMICA-ALEM\u00c1N<\/li>\n<li>835 \u2013 EDUCACI\u00d3N F\u00cdSICA-INGL\u00c9S<\/li>\n<li>836 \u2013 EDUCACI\u00d3N F\u00cdSICA-ALEM\u00c1N<\/li>\n<li>839 \u2013 TECNOLOG\u00cdA-ALEM\u00c1N 840 \u2013 FILOSOF\u00cdA-FRANC\u00c9S<\/li>\n<li>843 \u2013 FILOSOF\u00cdA -ALEM\u00c1N<\/li>\n<\/ul>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;7737&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;70&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;4.5\\\/5 - (70 votos)&quot;,&quot;size&quot;:&quot;15&quot;,&quot;title&quot;:&quot;Interinos Madrid: bolsa de trabajo para el cuerpo de Profesores&quot;,&quot;width&quot;:&quot;87.5&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 87.5px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 15px; height: 15px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12px;\">\n            4.5\/5 - (70 votos)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Convocatoria extraordinaria para la selecci\u00f3n de aspirantes a ocupar puestos en r\u00e9gimen de interinidad en varias especialidades de los cuerpos de Profesores de Ense\u00f1anza Secundaria, FP, EOI y Maestros de Taller de Artes Pl\u00e1sticas y Dise\u00f1o en la Comunidad de Madrid.<\/p>\n","protected":false},"author":2,"featured_media":6233,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[213,611,5],"tags":[29],"class_list":{"0":"post-7737","1":"post","2":"type-post","3":"status-publish","4":"format-image","5":"has-post-thumbnail","7":"category-bolsas-madrid","8":"category-bolsas-trabajo-secundaria","9":"category-madrid","10":"tag-profesores","11":"post_format-post-format-image"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interinos Madrid: bolsa de trabajo para el cuerpo de Profesores - Campuseducacion.com<\/title>\n<meta name=\"description\" content=\"Convocatoria extraordinaria para la selecci\u00f3n de aspirantes a ocupar puestos en r\u00e9gimen de interinidad en varias especialidades de los cuerpos de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interinos Madrid: bolsa de trabajo para el cuerpo de Profesores - Campuseducacion.com\" \/>\n<meta property=\"og:description\" content=\"Convocatoria extraordinaria para la selecci\u00f3n de aspirantes a ocupar puestos en r\u00e9gimen de interinidad en varias especialidades de los cuerpos de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Campuseducacion.es\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-28T15:05:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-24T09:34:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/madrid.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campuseducacion.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Campuseducacion\" \/>\n<meta name=\"twitter:site\" content=\"@Campuseducacion\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campuseducacion.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\\\/\"},\"author\":{\"name\":\"Campuseducacion.com\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"headline\":\"Interinos Madrid: bolsa de trabajo para el cuerpo de Profesores\",\"datePublished\":\"2016-09-28T15:05:50+00:00\",\"dateModified\":\"2017-04-24T09:34:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\\\/\"},\"wordCount\":176,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/madrid.jpg\",\"keywords\":[\"profesores\"],\"articleSection\":[\"Bolsas Madrid\",\"Bolsas Trabajo Secundaria\",\"Oposiciones Madrid\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\\\/\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\\\/\",\"name\":\"Interinos Madrid: bolsa de trabajo para el cuerpo de Profesores - Campuseducacion.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/madrid.jpg\",\"datePublished\":\"2016-09-28T15:05:50+00:00\",\"dateModified\":\"2017-04-24T09:34:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\"},\"description\":\"Convocatoria extraordinaria para la selecci\u00f3n de aspirantes a ocupar puestos en r\u00e9gimen de interinidad en varias especialidades de los cuerpos de\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/madrid.jpg\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/madrid.jpg\",\"width\":1200,\"height\":627,\"caption\":\"Comunidad de Madrid\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/oposiciones\\\/comunidades\\\/madrid\\\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interinos Madrid: bolsa de trabajo para el cuerpo de Profesores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/\",\"name\":\"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com\",\"description\":\"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/#\\\/schema\\\/person\\\/62fa9d1bd01a38844a0fea68cbbc9f3f\",\"name\":\"Campuseducacion.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"contentUrl\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/LogoCampusEducacionCuadrado_125px.png\",\"caption\":\"Campuseducacion.com\"},\"description\":\"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.\",\"sameAs\":[\"https:\\\/\\\/www.campuseducacion.com\",\"https:\\\/\\\/www.facebook.com\\\/Campuseducacion.es\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Campuseducacion\"],\"url\":\"https:\\\/\\\/www.campuseducacion.com\\\/blog\\\/autores\\\/adminopos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interinos Madrid: bolsa de trabajo para el cuerpo de Profesores - Campuseducacion.com","description":"Convocatoria extraordinaria para la selecci\u00f3n de aspirantes a ocupar puestos en r\u00e9gimen de interinidad en varias especialidades de los cuerpos de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/","og_locale":"es_ES","og_type":"article","og_title":"Interinos Madrid: bolsa de trabajo para el cuerpo de Profesores - Campuseducacion.com","og_description":"Convocatoria extraordinaria para la selecci\u00f3n de aspirantes a ocupar puestos en r\u00e9gimen de interinidad en varias especialidades de los cuerpos de","og_url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/","og_site_name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","article_publisher":"https:\/\/www.facebook.com\/Campuseducacion.es","article_author":"https:\/\/www.facebook.com\/Campuseducacion.es","article_published_time":"2016-09-28T15:05:50+00:00","article_modified_time":"2017-04-24T09:34:51+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/madrid.jpg","type":"image\/jpeg"}],"author":"Campuseducacion.com","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Campuseducacion","twitter_site":"@Campuseducacion","twitter_misc":{"Escrito por":"Campuseducacion.com","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/#article","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/"},"author":{"name":"Campuseducacion.com","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"headline":"Interinos Madrid: bolsa de trabajo para el cuerpo de Profesores","datePublished":"2016-09-28T15:05:50+00:00","dateModified":"2017-04-24T09:34:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/"},"wordCount":176,"commentCount":0,"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/madrid.jpg","keywords":["profesores"],"articleSection":["Bolsas Madrid","Bolsas Trabajo Secundaria","Oposiciones Madrid"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/","url":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/","name":"Interinos Madrid: bolsa de trabajo para el cuerpo de Profesores - Campuseducacion.com","isPartOf":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/#primaryimage"},"image":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/madrid.jpg","datePublished":"2016-09-28T15:05:50+00:00","dateModified":"2017-04-24T09:34:51+00:00","author":{"@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f"},"description":"Convocatoria extraordinaria para la selecci\u00f3n de aspirantes a ocupar puestos en r\u00e9gimen de interinidad en varias especialidades de los cuerpos de","breadcrumb":{"@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/#primaryimage","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/madrid.jpg","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2016\/02\/madrid.jpg","width":1200,"height":627,"caption":"Comunidad de Madrid"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campuseducacion.com\/blog\/oposiciones\/comunidades\/madrid\/interinos-madrid-bolsa-trabajo-cuerpo-profesores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.campuseducacion.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Interinos Madrid: bolsa de trabajo para el cuerpo de Profesores"}]},{"@type":"WebSite","@id":"https:\/\/www.campuseducacion.com\/blog\/#website","url":"https:\/\/www.campuseducacion.com\/blog\/","name":"BLOG Noticias Oposiciones y bolsas Trabajo Interinos. Campuseducacion.com","description":"Actualidad en Oposiciones Maestros de Infantil Primaria y Profesores Secundaria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campuseducacion.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.campuseducacion.com\/blog\/#\/schema\/person\/62fa9d1bd01a38844a0fea68cbbc9f3f","name":"Campuseducacion.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","url":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","contentUrl":"https:\/\/www.campuseducacion.com\/blog\/wp-content\/uploads\/2013\/05\/LogoCampusEducacionCuadrado_125px.png","caption":"Campuseducacion.com"},"description":"Campuseducacion.com te ofrece una amplia oferta en cursos homologados a distancia on-line para Oposiciones: cursos v\u00e1lidos para m\u00e9ritos en las Oposiciones de Maestros en Educaci\u00f3n Infantil y Primaria, y Profesores de Educaci\u00f3n Secundaria. Completa tu formaci\u00f3n Tambi\u00e9n para Sexenios y Concurso General de Traslados. Ahora puedes realizar formaci\u00f3n de postgrado para el profesorado con nuestros M\u00e1steres Oficiales Universitarios (1 punto para oposiciones y 3 puntos en Concurso General de Traslados). Consigue importantes descuentos con Campuseducacion.com en tu formaci\u00f3n homologada: 30% para afiliados a ANPE en cursos a distancia.","sameAs":["https:\/\/www.campuseducacion.com","https:\/\/www.facebook.com\/Campuseducacion.es","https:\/\/x.com\/https:\/\/twitter.com\/Campuseducacion"],"url":"https:\/\/www.campuseducacion.com\/blog\/autores\/adminopos\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/7737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/comments?post=7737"}],"version-history":[{"count":2,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/7737\/revisions"}],"predecessor-version":[{"id":9909,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/posts\/7737\/revisions\/9909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media\/6233"}],"wp:attachment":[{"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/media?parent=7737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/categories?post=7737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.campuseducacion.com\/blog\/wp-json\/wp\/v2\/tags?post=7737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}